{"id":560940,"date":"2026-07-11T00:17:42","date_gmt":"2026-07-11T00:17:42","guid":{"rendered":"https:\/\/driver-work.com\/job\/chauffeur-spl-h-f\/"},"modified":"2026-07-11T00:17:42","modified_gmt":"2026-07-11T00:17:42","slug":"job-560940","status":"publish","type":"job_listing","link":"https:\/\/driver-work.com\/uk\/job\/job-560940\/","title":{"rendered":"Chauffeur SPL (H\/F)"},"content":{"rendered":"<div id=\"shema_offre3\">\n<div>\n<p>\n                            <span>L&#8217;agence Domino Missions Narbonne recherche pour l&#8217;un de ses clients un <strong>Chauffeur SPL<\/strong> Messagerie.<\/p>\n<p>Missions :<\/p>\n<p>Conduite d&#8217;un poids lourd en SPL pour la messagerie<br \/>Livraison et collecte de colis sur diff\u00e9rents points de livraison<br \/>Chargement et d\u00e9chargement des marchandises<br \/>Respect des consignes de s\u00e9curit\u00e9, notamment li\u00e9es au transport de marchandises dangereuses (ADR)<br \/>Entretien de base du v\u00e9hicule<\/p>\n<p>Contrat : Interim<\/p>\n<p>Salaire : 12.31 \u00e0 14<\/p>\n<p>Profil recherch\u00e9 :<\/p>\n<p>Motiv\u00e9e<br \/>Responsable<br \/>Disposant de la FIMO \u00e0 jour<br \/>Titulaire de la certification ADR<br \/>Ayant une bonne connaissance des r\u00e8gles de s\u00e9curit\u00e9 li\u00e9es au transport routier<br \/>Capable de g\u00e9rer les temps de conduite et de repos<br \/><\/span>\n                        <\/p>\n<\/p><\/div>\n<\/p><\/div>\n","protected":false},"author":25753,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","job_listing_type":[],"job_listing_category":[],"job_listing_location":[],"job_listing_tag":[],"class_list":["post-560940","job_listing","type-job_listing","status-publish","hentry"],"aioseo_notices":[],"metas":{"_job_country_picker":"ChIJMVd4MymgVA0R99lHx5Y__Ws","_job_required_languages":"","_job_driving_license":"","_job_we_offer":"","_job_type":[],"_job_salary_type":"","_job_salary":"","_job_experience":"","_job_video_url":"","_job_photos":"","_job_application_deadline_date":"","_job_employer_name":"DOMINO RH","_job_employer_url":"https:\/\/driver-work.com\/uk\/employer\/ext-domino-rh\/"},"_links":{"self":[{"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/job_listing\/560940","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/job_listing"}],"about":[{"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/users\/25753"}],"replies":[{"embeddable":true,"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/comments?post=560940"}],"version-history":[{"count":1,"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/job_listing\/560940\/revisions"}],"predecessor-version":[{"id":560941,"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/job_listing\/560940\/revisions\/560941"}],"wp:attachment":[{"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/media?parent=560940"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/job_listing_type?post=560940"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/job_listing_category?post=560940"},{"taxonomy":"job_listing_location","embeddable":true,"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/job_listing_location?post=560940"},{"taxonomy":"job_listing_tag","embeddable":true,"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/job_listing_tag?post=560940"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}