{"id":560924,"date":"2026-07-11T00:16:30","date_gmt":"2026-07-11T00:16:30","guid":{"rendered":"https:\/\/driver-work.com\/job\/chauffeur-pl-avec-manut-f-h\/"},"modified":"2026-07-11T00:16:30","modified_gmt":"2026-07-11T00:16:30","slug":"job-560924","status":"publish","type":"job_listing","link":"https:\/\/driver-work.com\/uk\/job\/job-560924\/","title":{"rendered":"Chauffeur PL avec manut (F\/H)"},"content":{"rendered":"<div id=\"shema_offre3\">\n<div>\n<p>\n                            <span>Nous recherchons un Conducteur Poids Lourds (H\/F) charg\u00e9 de livrer des boissons (ex: f\u00fbt) dans les caves de clients et de r\u00e9cup\u00e9rer les consignes. Le poste implique de la manutention et la manipulation de charges lourdes (jusqu&#8217;\u00e0 42 kg). Vous effectuerez des livraisons pour une dizaine de clients en moyenne dans le d\u00e9partement 35 et ses environs.<\/p>\n<p>A pourvoir d\u00e8s que possible<\/p>\n<p>Contrat : D\u00e9but en int\u00e9rim avec possibilit\u00e9 de CDI par la suite, du lundi au vendredi de 6h \u00e0 16h pour un total de 35 heures par semaine.<\/p>\n<p>Taux horaire : 13,85 EUR <br \/>Les avantages : Tickets restaurant de 8,50EUR, pas de travail le weekend.<\/p>\n<p>Ce poste vous int\u00e9ress\u00e9 ?<\/p>\n<p>Veuillez contacter notre agence Actual Expert Conduite Sur Routes *<\/p>\n<p>Contrat : INTERIM<\/p>\n<p>Dur\u00e9e du contrat : 1 mois<\/p>\n<p>Nous cherchons un Conducteur poids lourds PL (H\/F) Titulaire du permis C + FIMO \u00e0 jour. Rigoureux, dynamique, r\u00e9actif et \u00e0 l&#8217;aise avec le contact client et le travail en autonomie.<br \/><\/span>\n                        <\/p>\n<\/p><\/div>\n<\/p><\/div>\n","protected":false},"author":25969,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","job_listing_type":[],"job_listing_category":[],"job_listing_location":[],"job_listing_tag":[],"class_list":["post-560924","job_listing","type-job_listing","status-publish","hentry"],"aioseo_notices":[],"metas":{"_job_country_picker":"ChIJMVd4MymgVA0R99lHx5Y__Ws","_job_required_languages":"","_job_driving_license":"","_job_we_offer":"","_job_type":[],"_job_salary_type":"","_job_salary":"","_job_experience":"","_job_video_url":"","_job_photos":"","_job_application_deadline_date":"","_job_employer_name":"Actual","_job_employer_url":"https:\/\/driver-work.com\/uk\/employer\/ext-actual\/"},"_links":{"self":[{"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/job_listing\/560924","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/job_listing"}],"about":[{"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/users\/25969"}],"replies":[{"embeddable":true,"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/comments?post=560924"}],"version-history":[{"count":1,"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/job_listing\/560924\/revisions"}],"predecessor-version":[{"id":560925,"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/job_listing\/560924\/revisions\/560925"}],"wp:attachment":[{"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/media?parent=560924"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/job_listing_type?post=560924"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/job_listing_category?post=560924"},{"taxonomy":"job_listing_location","embeddable":true,"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/job_listing_location?post=560924"},{"taxonomy":"job_listing_tag","embeddable":true,"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/job_listing_tag?post=560924"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}