{"id":559545,"date":"2026-07-10T00:08:09","date_gmt":"2026-07-10T00:08:09","guid":{"rendered":"https:\/\/driver-work.com\/job\/chauffeur-pl-toupie-h-f-d\/"},"modified":"2026-07-10T00:08:09","modified_gmt":"2026-07-10T00:08:09","slug":"job-559545","status":"publish","type":"job_listing","link":"https:\/\/driver-work.com\/uk\/job\/job-559545\/","title":{"rendered":"Chauffeur PL toupie (H\/F\/D)"},"content":{"rendered":"<p>Notre agence SAMSIC EMPLOI MONTFORT SUR MEU recrute pour son client, sp\u00e9cialis\u00e9 dans les travaux publics, Un Chauffeur PL toupie sur le secteur de Breteil (35).<br \/>\n \u00c0 ce titre, votre mission principale sera la suivante :<br \/>\n &#8211; Participer aux op\u00e9rations de chargement\/d\u00e9chargement du b\u00e9ton dans le respect des r\u00e8gles de s\u00e9curit\u00e9.<br \/>\n &#8211; Nettoyer la toupie apr\u00e8s chaque livraison pour \u00e9viter que le b\u00e9ton ne durcisse.<br \/>\n &#8211; V\u00e9rifier l&#8217;\u00e9tat du camion et respecter les r\u00e8gles de s\u00e9curit\u00e9.<\/p>\n<p>Informations sur le poste<br \/>\n &#8211; Travail du lundi au vendredi en horaire de journ\u00e9e.<br \/>\n &#8211; Poste \u00e0 pourvoir de suite en int\u00e9rim pour 2-3 semaines<br \/>\n L&#8217;entreprise n&#8217;est pas desservie par les transports en commun.<\/p>\n<p>\nSAMSIC, soci\u00e9t\u00e9 socialement responsable, s&#8217;engage au quotidien pour l&#8217;emploi des personnes en situation de handicap.<br \/><\/p>\n","protected":false},"author":25747,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","job_listing_type":[67],"job_listing_category":[],"job_listing_location":[],"job_listing_tag":[],"class_list":["post-559545","job_listing","type-job_listing","status-publish","hentry","job_listing_type-full-time"],"aioseo_notices":[],"metas":{"_job_country_picker":"ChIJMVd4MymgVA0R99lHx5Y__Ws","_job_required_languages":"","_job_driving_license":["B","C"],"_job_we_offer":"","_job_type":{"67":"Full time work"},"_job_salary_type":"","_job_salary":"","_job_experience":"","_job_video_url":"","_job_photos":"","_job_application_deadline_date":"","_job_employer_name":"SAMSIC EMPLOI","_job_employer_url":"https:\/\/driver-work.com\/uk\/employer\/ext-samsic-emploi\/"},"_links":{"self":[{"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/job_listing\/559545","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/job_listing"}],"about":[{"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/users\/25747"}],"replies":[{"embeddable":true,"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/comments?post=559545"}],"version-history":[{"count":1,"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/job_listing\/559545\/revisions"}],"predecessor-version":[{"id":559546,"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/job_listing\/559545\/revisions\/559546"}],"wp:attachment":[{"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/media?parent=559545"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/job_listing_type?post=559545"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/job_listing_category?post=559545"},{"taxonomy":"job_listing_location","embeddable":true,"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/job_listing_location?post=559545"},{"taxonomy":"job_listing_tag","embeddable":true,"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/job_listing_tag?post=559545"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}