{"id":559453,"date":"2026-07-10T00:05:48","date_gmt":"2026-07-10T00:05:48","guid":{"rendered":"https:\/\/driver-work.com\/job\/conducteur-spl-bache-h-f\/"},"modified":"2026-07-10T00:05:48","modified_gmt":"2026-07-10T00:05:48","slug":"job-559453","status":"publish","type":"job_listing","link":"https:\/\/driver-work.com\/uk\/job\/job-559453\/","title":{"rendered":"Conducteur spl b\u00e2ch\u00e9 (H\/F)"},"content":{"rendered":"<p>Nous recherchons un conducteur SPL b\u00e2ch\u00e9 au d\u00e9part de Bourgbarr\u00e9 (35) pour une mission de remplacement du 15 juin au 3 juillet.<br \/>\n<br \/>\n-Activit\u00e9 : livraison et chargement de palettes.<br \/>\n<br \/>\n-Rythme : du lundi au vendredi d\u00e9part \u00e0 6h00 du matin avec une amplitude de 10h par jour.<br \/>\n<br \/>\n-Contrat : 12.80EUR\/h + 16.36EUR repas. Heures suppl\u00e9mentaires major\u00e9s \u00e0 25% et 50%.<br \/>\n<br \/>\nInt\u00e9ress\u00e9 et disponible ?<br \/>\n<br \/>\nContactez ACTUAL EXPERTS CSR au 02 28 09 01 76 \/ 06 16 96 99 28<br \/>\n<br \/>\nMagali, Maximilienne, Ryan<\/p>\n","protected":false},"author":29600,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","job_listing_type":[67],"job_listing_category":[],"job_listing_location":[],"job_listing_tag":[],"class_list":["post-559453","job_listing","type-job_listing","status-publish","hentry","job_listing_type-full-time"],"aioseo_notices":[],"metas":{"_job_country_picker":"ChIJMVd4MymgVA0R99lHx5Y__Ws","_job_required_languages":"","_job_driving_license":"","_job_we_offer":"","_job_type":{"67":"Full time work"},"_job_salary_type":"","_job_salary":"","_job_experience":"","_job_video_url":"","_job_photos":"","_job_application_deadline_date":"","_job_employer_name":"Actual","_job_employer_url":"https:\/\/driver-work.com\/uk\/employer\/ext-actual-2\/"},"_links":{"self":[{"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/job_listing\/559453","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/job_listing"}],"about":[{"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/users\/29600"}],"replies":[{"embeddable":true,"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/comments?post=559453"}],"version-history":[{"count":1,"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/job_listing\/559453\/revisions"}],"predecessor-version":[{"id":559454,"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/job_listing\/559453\/revisions\/559454"}],"wp:attachment":[{"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/media?parent=559453"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/job_listing_type?post=559453"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/job_listing_category?post=559453"},{"taxonomy":"job_listing_location","embeddable":true,"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/job_listing_location?post=559453"},{"taxonomy":"job_listing_tag","embeddable":true,"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/job_listing_tag?post=559453"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}