{"id":534461,"date":"2026-06-25T00:15:51","date_gmt":"2026-06-25T00:15:51","guid":{"rendered":"https:\/\/driver-work.com\/job\/lkw-fahrerin-container-abroller\/"},"modified":"2026-06-25T00:15:51","modified_gmt":"2026-06-25T00:15:51","slug":"job-534461","status":"publish","type":"job_listing","link":"https:\/\/driver-work.com\/uk\/job\/job-534461\/","title":{"rendered":"LKW-Fahrer*in Container-Abroller"},"content":{"rendered":"<p>DAS SIND WIR!<\/p>\n<p>Wir sind Teil der I.K. Hofmann GmbH, die weltweit mehr als 17.000 Menschen in Arbeit bringt. In \u00d6sterreich z\u00e4hlen wir mit rund 5.000 Mitarbeiter*innen an mehr als 20 Standorten zu den besten Personaldienstleistern. <\/p>\n<p>Durch Offenheit und Klarheit schaffen wir Vertrauen zu unseren Mitarbeiter*innen und f\u00f6rdern das Miteinander im Team. 1 LKW-Fahrer*in Container-Abroller WAS ERWARTEN WIR?<\/p>\n<p>* Transportfahrten\/Container<\/p>\n<p>* Be- und Entladearbeiten<\/p>\n<p>* Verantwortung bez\u00fcglich Pflege und Wartung des zugeteilten Fahrzeuges<\/p>\n<p>* Dokumentation und F\u00fchren des Bautagebuches (Tablet)<\/p>\n<\/p>\n<p>WEN SUCHEN WIR?<\/p>\n<p>* Einschl\u00e4gige Praxis von Vorteil<\/p>\n<p>* G\u00fcltiger F\u00fchrerschein der Klassen C, CE, C95<\/p>\n<p>* Technisches Verst\u00e4ndnis und Genauigkeit sowie handwerkliches Geschick<\/p>\n<p>* Zuverl\u00e4ssigkeit, Flexibilit\u00e4t, Leistungsbereitschaft und Teamgeist<\/p>\n<p>* Elementare Deutschkenntnisse<\/p>\n<\/p>\n<p>DAS ERWARTET DICH BEI UNS!<\/p>\n<p>* Deine Benefits bei Hofmann Personal<\/p>\n<p>    &#8211; Anspruch auf Vorschuss<\/p>\n<p>    &#8211; betriebliche Mitarbeiter*innenvorsorge<\/p>\n<p>    &#8211; Kantine<\/p>\n<p>    &#8211; kollegiales Arbeitsklima<\/p>\n<p>    &#8211; langfristige Anstellung<\/p>\n<p>    &#8211; Parkplatz<\/p>\n<p>    &#8211; Tagesarbeitszeiten<\/p>\n<p>* Der Verdienst betr\u00e4gt EUR 15,62 brutto pro Stunde.<\/p>\n<\/p>\n<p>WIR SIND GERNE F\u00dcR DICH DA<\/p>\n<p>* Z\u00f6gere nicht und bewirb Dich noch heute.<\/p>\n<p>Gerne beantworten wir Deine Fragen telefonisch oder per E-Mail.<\/p>\n<p>Kontakt-Name: Anita Altinger<\/p>\n<p>Kontakt-Telefon: +43 7242 2105104212<\/p>\n<p>Bewerbung E-Mail: karriere.wels@hofmann-personal.at<\/p>\n<p>Kontakt-Adresse: Europastra\u00dfe 67, 4600 Wels<\/p>\n<\/p>\n<p>ARBEITSORT<\/p>\n<p>* 4551 Ried im Traunkreis<\/p>\n<\/p>\n<p>EXPRESSBEWERBUNG<\/p>\n<p>https:\/\/hofmann-personal.at\/jobs\/detail\/get?p=hofmann_ats&amp;pcid=19&amp;puid=23075&amp;job_only=1 Das Mindestentgelt f\u00fcr die Stelle als LKW-Fahrer*in Container-Abroller betr\u00e4gt 15,62 EUR brutto pro Stunde.<\/p>\n","protected":false},"author":25975,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","job_listing_type":[67],"job_listing_category":[],"job_listing_location":[],"job_listing_tag":[],"class_list":["post-534461","job_listing","type-job_listing","status-publish","hentry","job_listing_type-full-time"],"aioseo_notices":[],"metas":{"_job_country_picker":"ChIJfyqdJZsHbUcRr8Hk3XvUEhA","_job_required_languages":"","_job_driving_license":"","_job_we_offer":"","_job_type":{"67":"Full time work"},"_job_salary_type":"","_job_salary":"","_job_experience":"","_job_video_url":"","_job_photos":"","_job_application_deadline_date":"","_job_employer_name":"Siehe Beschreibung","_job_employer_url":"https:\/\/driver-work.com\/uk\/employer\/ext-siehe-beschreibung\/"},"_links":{"self":[{"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/job_listing\/534461","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/job_listing"}],"about":[{"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/users\/25975"}],"replies":[{"embeddable":true,"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/comments?post=534461"}],"version-history":[{"count":1,"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/job_listing\/534461\/revisions"}],"predecessor-version":[{"id":534462,"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/job_listing\/534461\/revisions\/534462"}],"wp:attachment":[{"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/media?parent=534461"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/job_listing_type?post=534461"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/job_listing_category?post=534461"},{"taxonomy":"job_listing_location","embeddable":true,"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/job_listing_location?post=534461"},{"taxonomy":"job_listing_tag","embeddable":true,"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/job_listing_tag?post=534461"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}