{"id":492028,"date":"2026-06-01T00:05:57","date_gmt":"2026-06-01T00:05:57","guid":{"rendered":"https:\/\/driver-work.com\/job\/lkw-fahrer-m-w-d\/"},"modified":"2026-06-01T00:05:57","modified_gmt":"2026-06-01T00:05:57","slug":"job-492028","status":"publish","type":"job_listing","link":"https:\/\/driver-work.com\/uk\/job\/job-492028\/","title":{"rendered":"LKW-Fahrer (m\/w\/d)"},"content":{"rendered":"<p>LKW-Fahrer (m\/w\/d)<br \/>\nWir suchen ab sofort motivierte Unterst\u00fctzung als LKW-Fahrer (m\/w\/d)Wenn Sie flexibel sind, gerne Verantwortung \u00fcbernehmen und in einem abwechslungsreichen Umfeld arbeiten m\u00f6chten, freuen wir uns auf Ihre Bewerbung.<\/p>\n<p>Diese Vorteile erwarten Sie bei Tempton<\/p>\n<p>&#8211; unbefristetes Arbeitsverh\u00e4ltnis<br \/>\n&#8211; Bezahlung mindestens nach g\u00fcltigem Tarifvertrag<br \/>\n&#8211; tarifliche Zuschl\u00e4ge f\u00fcr \u00dcberstunden, Nachtschicht, Sonn- und Feiertagsarbeit<br \/>\n&#8211; bis zu 30 Tage Urlaub (je nach Betriebszugeh\u00f6rigkeit)<br \/>\n&#8211; anerkannte Sozialleistungen, inkl. Urlaubs- und Weihnachtsgeld sowie Zusch\u00fcsse zur betrieblichen Altersvorsorge<br \/>\n&#8211; pers\u00f6nliche Betreuung und Beratung durch einen festen Ansprechpartner in Ihrer Niederlassung<br \/>\n&#8211; Eins\u00e4tze in namhaften Kundenunternehmen, bei denen Sie die Chance haben, sich pers\u00f6nlich weiterzuentwickeln<br \/>\n&#8211; Mitarbeitervorteilsprogramm (wie z. B. Verg\u00fcnstigungen in Onlineshops)<br \/>\n&#8211; kostenfreie arbeitsmedizinische Vorsorgeuntersuchung<br \/>\n&#8211; kostenfreie Stellung von Arbeitsschutzkleidung<\/p>\n<p>Ihre t\u00e4glichen Aufgaben:<\/p>\n<p>&#8211; Termingenaue Abholung und exakte Erfassung<br \/>\n&#8211; Kontrolle der maximalen Zuladung<br \/>\n&#8211; Transport und Abladen<br \/>\n&#8211; Durchf\u00fchrung der Wagenpflege<\/p>\n<p>Das bringen Sie mit:<\/p>\n<p>&#8211; Fahrerlaubnis C\/CE mit Eintragung 95, g\u00fcltige Fahrerkarte<br \/>\n&#8211; Erste Berufserfahrung im Transportwesen inkl. erster Fahrpraxis w\u00fcnschenswert<br \/>\n&#8211; Selbst\u00e4ndigkeit und P\u00fcnktlichkeit sowie hohes Ma\u00df an Verantwortungsbewusstsein<br \/>\n&#8211; Freundliches Auftreten und ein gepflegtes Erscheinungsbild<br \/>\n&#8211; Gute Deutschkenntnisse<\/p>\n<p>Erkennen Sie sich wieder?<br \/>\n Diese Wege f\u00fchren zu Tempton:<br \/>\nvia E-Mail: bewerbung-ravensburg@tempton.deoder \u00fcber unser Online-Bewerberformular<br \/>\nTelefon: F\u00fcr weiterf\u00fchrende Informationen steht &#8211; Seyhabidin Bugday, Niederlassungsleiter &#8211; unter der Telefonnummer +49 751 3593996-12 gerne zur Verf\u00fcgung. Es wird sich auf den Anruf und die Bewerbung, gerne mit Angabe der Gehaltsvorstellung, gefreut.<br \/>\nGerne besteht auch die M\u00f6glichkeit, pers\u00f6nlich vorbeizukommen: Bachstra\u00dfe 3, 88214 Ravensburg \u2013 ein Besuch ist jederzeit willkommen.  <\/p>\n<p>\u00dcber Tempton<br \/>\nMit \u00fcber 11.000 Kolleginnen und Kollegen an bundesweit 200 Standorten geh\u00f6rt Tempton zu den gr\u00f6\u00dften Personaldienstleistern Deutschlands. Unser gemeinsames Ziel: motivierte Jobsuchende und Unternehmen, die personelle Unterst\u00fctzung suchen, zusammenzubringen.<\/p>\n","protected":false},"author":20669,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","job_listing_type":[67],"job_listing_category":[],"job_listing_location":[],"job_listing_tag":[],"class_list":["post-492028","job_listing","type-job_listing","status-publish","hentry","job_listing_type-full-time"],"aioseo_notices":[],"metas":{"_job_country_picker":"ChIJa76xwh5ymkcRW-WRjmtd6HU","_job_required_languages":"","_job_driving_license":"","_job_we_offer":"","_job_type":{"67":"Full time work"},"_job_salary_type":"","_job_salary":"","_job_experience":"","_job_video_url":"","_job_photos":"","_job_application_deadline_date":"","_job_employer_name":"Tempton Personaldienst- leistungen GmbH","_job_employer_url":"https:\/\/driver-work.com\/uk\/employer\/ext-tempton-personaldienst-leistungen-gmbh\/"},"_links":{"self":[{"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/job_listing\/492028","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/job_listing"}],"about":[{"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/users\/20669"}],"replies":[{"embeddable":true,"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/comments?post=492028"}],"version-history":[{"count":1,"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/job_listing\/492028\/revisions"}],"predecessor-version":[{"id":492029,"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/job_listing\/492028\/revisions\/492029"}],"wp:attachment":[{"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/media?parent=492028"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/job_listing_type?post=492028"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/job_listing_category?post=492028"},{"taxonomy":"job_listing_location","embeddable":true,"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/job_listing_location?post=492028"},{"taxonomy":"job_listing_tag","embeddable":true,"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/job_listing_tag?post=492028"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}