{"id":489228,"date":"2026-05-29T00:13:00","date_gmt":"2026-05-29T00:13:00","guid":{"rendered":"https:\/\/driver-work.com\/job\/lkw-fahrer-m-w-d\/"},"modified":"2026-05-29T00:13:00","modified_gmt":"2026-05-29T00:13:00","slug":"job-489228","status":"publish","type":"job_listing","link":"https:\/\/driver-work.com\/uk\/job\/job-489228\/","title":{"rendered":"LKW-Fahrer (m\/w\/d)"},"content":{"rendered":"<p>\u00dcber uns<br \/>\nDie A\/S Logcare GmbH wurde im Jahr 2009 in der charmanten Stadt Gersthofen gegr\u00fcndet, die heute auch unseren Hauptsitz beherbergt. Seit unseren Anf\u00e4ngen haben wir uns kontinuierlich weiterentwickelt. Im Jahr 2014 er\u00f6ffneten wir unsere zweite Niederlassung in Kirchheim unter Teck, in der Region nahe Stuttgart. Seit 2021 d\u00fcrfen wir zudem eine weitere Gesch\u00e4ftsstelle in Neu-Ulm unser Eigen nennen.<\/p>\n<p>Als mittelst\u00e4ndischer Personaldienstleister sind wir stolz darauf, rund 150 engagierte Mitarbeiter in unserem Team zu haben. Wir glauben fest daran, dass der pers\u00f6nliche Kontakt zu unseren Mitarbeitern von entscheidender Bedeutung ist. Deshalb legen wir gro\u00dfen Wert auf eine offene und ehrliche Kommunikation. Bei A\/S Logcare f\u00f6rdern wir ein Arbeitsumfeld, in dem sich jeder Einzelne wertgesch\u00e4tzt und geh\u00f6rt f\u00fchlt. Unsere Grundprinzipien \u2013 Offenheit und Ehrlichkeit \u2013 spiegeln sich nicht nur in unserem Umgang miteinander wider, sondern auch in der Art und Weise, wie wir unsere Dienstleistungen erbringen.<\/p>\n<p>LKW-Fahrer (m\/w\/d)<\/p>\n<p>Standort: Gersthofen<br \/>\nAnstellungsart(en): Vollzeit<\/p>\n<p>Wir suchen<br \/>\nf\u00fcr unseren Kunden im Raum Gersthofen LKW Fahrer (m\/w\/d)<\/p>\n<p>Ihre Aufgaben<br \/>\n&#8211; \u00dcberpr\u00fcfen und Laden der Ware<br \/>\n&#8211; Lieferung der Ware zum Kunden<br \/>\n&#8211; Packen und Entpacken von Haushaltsg\u00fctern<br \/>\n&#8211; Auf- und Abbau und Transport von M\u00f6beln<\/p>\n<p>Ihr Profil<br \/>\n&#8211; Erfahrung als LKW-Fahrer im Lieferverkehr oder Umzugsverkehr<br \/>\n&#8211; G\u00fcltiger F\u00fchrerschein Klasse C \/ C1 \/ CE mit Kennziffer 95<br \/>\n&#8211; Bereitschaft zum \u201cAnpacken\u201d<\/p>\n<p>Wir bieten<br \/>\n&#8211; Einen unbefristeten Arbeitsvertrag<br \/>\n&#8211; \u00dcberwiegend langfristige Eins\u00e4tze und realistische \u00dcbernahmem\u00f6glichkeiten<br \/>\n&#8211; Urlaubs- und Weihnachtsgeld<br \/>\n&#8211; Einfache Kommunikation und digitaler Abruf der Lohnunterlagen \u00fcber die JobApp<\/p>\n<p>Ihr Ansprechpartner bei uns<br \/>\nRen\u00e9 Wieser<\/p>\n<p>0821\/999 674 20<br \/>\nOtto-Hahn-Stra\u00dfe 2<br \/>\n86368 Gersthofen<\/p>\n<p>bewerbung-gersthofen@aslogcare.de<\/p>\n","protected":false},"author":14545,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","job_listing_type":[67],"job_listing_category":[],"job_listing_location":[],"job_listing_tag":[],"class_list":["post-489228","job_listing","type-job_listing","status-publish","hentry","job_listing_type-full-time"],"aioseo_notices":[],"metas":{"_job_country_picker":"ChIJa76xwh5ymkcRW-WRjmtd6HU","_job_required_languages":"","_job_driving_license":"","_job_we_offer":"","_job_type":{"67":"Full time work"},"_job_salary_type":"","_job_salary":"","_job_experience":"","_job_video_url":"","_job_photos":"","_job_application_deadline_date":"","_job_employer_name":"A\/S Logcare GmbH","_job_employer_url":"https:\/\/driver-work.com\/uk\/employer\/ext-a-s-logcare-gmbh\/"},"_links":{"self":[{"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/job_listing\/489228","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/job_listing"}],"about":[{"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/users\/14545"}],"replies":[{"embeddable":true,"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/comments?post=489228"}],"version-history":[{"count":1,"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/job_listing\/489228\/revisions"}],"predecessor-version":[{"id":489229,"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/job_listing\/489228\/revisions\/489229"}],"wp:attachment":[{"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/media?parent=489228"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/job_listing_type?post=489228"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/job_listing_category?post=489228"},{"taxonomy":"job_listing_location","embeddable":true,"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/job_listing_location?post=489228"},{"taxonomy":"job_listing_tag","embeddable":true,"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/job_listing_tag?post=489228"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}