{"id":457497,"date":"2026-05-11T00:06:12","date_gmt":"2026-05-11T00:06:12","guid":{"rendered":"https:\/\/driver-work.com\/job\/conducteur-spl-h-f\/"},"modified":"2026-05-11T00:06:12","modified_gmt":"2026-05-11T00:06:12","slug":"job-457497","status":"publish","type":"job_listing","link":"https:\/\/driver-work.com\/uk\/job\/job-457497\/","title":{"rendered":"Conducteur SPL (H\/F)"},"content":{"rendered":"<div id=\"shema_offre3\">\n<div>\n<p>\n                            <span>Manpower, recherche pour une entreprise active dans la location de machines et \u00e9quipements, un <strong>Conducteur<\/strong> SPL &#8211; H\/F \u00e0 29270 CARHAIX-PLOUGUER.<\/p>\n<p>Poste en mission d&#8217;int\u00e9rim \u00e0 pourvoir d\u00e8s que possible pour plusieurs semaines. Le poste se situe \u00e0 29270 CARHAIX-PLOUGUER. Dans ce poste, vous serez amen\u00e9 \u00e0 :<br \/>&#8211; Effectuer les livraisons des engins chez les clients.<br \/>&#8211; V\u00e9rifier la conformit\u00e9 des chargements.<br \/>&#8211; Respecter les proc\u00e9dures de s\u00e9curit\u00e9.<br \/>&#8211; Communiquer avec les clients.<br \/>&#8211; Assurer le suivi des op\u00e9rations.<br \/>&#8211; Maintenir l&#8217;\u00e9tat des v\u00e9hicules.<br \/>&#8211; Optimiser les itin\u00e9raires quotidiennement.<br \/>La r\u00e9mun\u00e9ration et avantages:<br \/>&#8211; Taux horaires entre 12,02\u20ac et 13\u20ac<br \/>&#8211; Mutuelle d&#8217;entreprise et pr\u00e9voyance sant\u00e9<br \/>&#8211; CET \u00e0 8 &amp;#37;<br \/>&#8211; CSE, CSEC<br \/>&#8211; FASTT (garde d&#8217;enfant, aide au logement, location de v\u00e9hicule?)<br \/>Vous \u00eates titulaire du permis SPL + FCO + carte chrono<br \/>Vous justifiez d&#8217;exp\u00e9riences significatives dans le transport et la logistique. Vous ma\u00eetrisez l&#8217;optimisation des itin\u00e9raires, la gestion documentaire et assurez un excellent relationnel client, tout en respectant les normes professionnelles.<\/p>\n<p>Int\u00e9ress\u00e9(e) ? Postulez en ligne ou contactez directement notre agence Manpower Carhaix.<\/p>\n<p>Si votre candidature a retenu notre attention pour ce poste, voici les \u00e9tapes du processus de recrutement :<br \/>&#8211; Un \u00e9change t\u00e9l\u00e9phonique pr\u00e9alable<br \/>&#8211; Un entretien avec l&#8217;un de nos Agents de Talents<br \/>&#8211; Un entretien avec le client<\/p>\n<p>Dans le cadre de sa politique diversit\u00e9, Manpower \u00e9tudie, \u00e0 comp\u00e9tences \u00e9gales, toutes candidatures dont celles de personnes en situation de handicap<\/p>\n<p>Contrat : Mission en int\u00e9rim<\/p>\n<p>Exp\u00e9rience : &lt; 1 an<\/p>\n<p>Salaire : 12,02 \u00e0 13 \u20ac par heure<\/p>\n<p>Date de d\u00e9but : 14\/04\/2026<\/p>\n<p>Dur\u00e9e : 3 semaine(s) renouvelable<\/span>\n                        <\/p>\n<\/p><\/div>\n<\/p><\/div>\n","protected":false},"author":25760,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","job_listing_type":[],"job_listing_category":[],"job_listing_location":[],"job_listing_tag":[],"class_list":["post-457497","job_listing","type-job_listing","status-publish","hentry"],"aioseo_notices":[],"metas":{"_job_country_picker":"ChIJMVd4MymgVA0R99lHx5Y__Ws","_job_required_languages":"","_job_driving_license":"","_job_we_offer":"","_job_type":[],"_job_salary_type":"","_job_salary":"","_job_experience":"","_job_video_url":"","_job_photos":"","_job_application_deadline_date":"","_job_employer_name":"Manpower","_job_employer_url":"https:\/\/driver-work.com\/uk\/employer\/ext-manpower-3\/"},"_links":{"self":[{"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/job_listing\/457497","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/job_listing"}],"about":[{"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/users\/25760"}],"replies":[{"embeddable":true,"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/comments?post=457497"}],"version-history":[{"count":0,"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/job_listing\/457497\/revisions"}],"wp:attachment":[{"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/media?parent=457497"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/job_listing_type?post=457497"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/job_listing_category?post=457497"},{"taxonomy":"job_listing_location","embeddable":true,"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/job_listing_location?post=457497"},{"taxonomy":"job_listing_tag","embeddable":true,"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/job_listing_tag?post=457497"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}