{"id":439068,"date":"2026-04-30T00:12:39","date_gmt":"2026-04-30T00:12:39","guid":{"rendered":"https:\/\/driver-work.com\/job\/truck-driver-gn\/"},"modified":"2026-04-30T00:12:39","modified_gmt":"2026-04-30T00:12:39","slug":"job-439068","status":"publish","type":"job_listing","link":"https:\/\/driver-work.com\/uk\/job\/job-439068\/","title":{"rendered":"Truck Driver (gn)"},"content":{"rendered":"<p>Bitte einschlie\u00dflich Trennlinie l\u00f6schen: Infotext zum Job Post: Jobs werden immer auf deutschem &amp; englischem Job Board platziert! Zusatzangaben zum generellen Job-Titel immer hinter dem Gendern Innerhalb der JD wird die \u201cDu\u201d-Ansprache, au\u00dfer am Satzanfang, immer klein geschrieben (du\/dein\/dich) Stellenintro kann bei einem anderem, individuellerem Text abweichen, sonst den u.g. Text nehmen und anpassen Maximal zwei l\u00e4ngere- oder drei kurze S\u00e4tze. Nicht mehr als 6 BulletPoints, immer einzeilig Ke\u2026<\/p>\n","protected":false},"author":27042,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","job_listing_type":[],"job_listing_category":[],"job_listing_location":[],"job_listing_tag":[],"class_list":["post-439068","job_listing","type-job_listing","status-publish","hentry"],"aioseo_notices":[],"metas":{"_job_country_picker":"ChIJa76xwh5ymkcRW-WRjmtd6HU","_job_required_languages":["en","de"],"_job_driving_license":"","_job_we_offer":"","_job_type":[],"_job_salary_type":"","_job_salary":"","_job_experience":"","_job_video_url":"","_job_photos":"","_job_application_deadline_date":"","_job_employer_name":"The Quality Group","_job_employer_url":"https:\/\/driver-work.com\/uk\/employer\/ext-the-quality-group\/"},"_links":{"self":[{"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/job_listing\/439068","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/job_listing"}],"about":[{"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/users\/27042"}],"replies":[{"embeddable":true,"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/comments?post=439068"}],"version-history":[{"count":0,"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/job_listing\/439068\/revisions"}],"wp:attachment":[{"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/media?parent=439068"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/job_listing_type?post=439068"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/job_listing_category?post=439068"},{"taxonomy":"job_listing_location","embeddable":true,"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/job_listing_location?post=439068"},{"taxonomy":"job_listing_tag","embeddable":true,"href":"https:\/\/driver-work.com\/uk\/wp-json\/wp\/v2\/job_listing_tag?post=439068"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}