{"id":562139,"date":"2026-07-13T00:05:03","date_gmt":"2026-07-13T00:05:03","guid":{"rendered":"https:\/\/driver-work.com\/job\/chauffeur-pl-grue-f-h-h-f\/"},"modified":"2026-07-13T00:05:03","modified_gmt":"2026-07-13T00:05:03","slug":"job-562139","status":"publish","type":"job_listing","link":"https:\/\/driver-work.com\/sv\/job\/job-562139\/","title":{"rendered":"Chauffeur PL GRUE (F\/H) (H\/F)"},"content":{"rendered":"<p>Pourquoi a-t-on besoin de vous?<br \/>Notre agence de MIGNE AUXANCES recherche son\/sa futur(e) Chauffeur PL dans le cadre d&#8217;un CDI.<\/p>\n<p>Votre quotidien sera le suivant :<\/p>\n<p> Vous livrez les commandes clients<\/p>\n<p>En respectant votre plan de tourn\u00e9es, vous assurez la livraison des commandes de nos clients directement sur leur chantier. Vous d\u00e9chargez votre livraison \u00e0 l&#8217;aide de mat\u00e9riels adapt\u00e9s (camions grues, retourneurs de plaques.) tout en veillant \u00e0 respecter scrupuleusement les r\u00e8gles de s\u00e9curit\u00e9 en vigueur.<\/p>\n<p> Vous \u00eates maitre de votre camion<\/p>\n<p>Avant de partir en livraison, vous veillez \u00e0 la bonne charge de votre camion et \u00e0 l&#8217;arrimage des produits. Vous vous assurez que les produits transport\u00e9s sont bien conformes aux bons de livraison et que votre camion est en parfait \u00e9tat.<\/p>\n<p> Vous \u00eates ambassadeur(rice) de notre enseigne aupr\u00e8s de nos clients<\/p>\n<p>Gr\u00e2ce \u00e0 votre excellent relationnel, vous \u00eates le\/la garant(e) de l&#8217;image de notre entreprise aupr\u00e8s de nos clients. Vous informez les clients de toute information utile sur la livraison et leur garantissez des livraisons de qualit\u00e9 dans le respect des d\u00e9lais impartis. Vous faites la promotion des actions commerciales et des actualit\u00e9s de l&#8217;agence.<\/p>\n<p>Ce poste est-il fait pour vous ?<br \/>Titulaire du permis C, du CACES GRUE AUXILIAIRE et d&#8217;une FIMO\/FCO \u00e0 jour :<\/p>\n<p>Vous travaillez en toute s\u00e9curit\u00e9 : vous savez charger et sangler votre marchandise. Vous ma\u00eetrisez et appliquez parfaitement les r\u00e8gles de s\u00e9curit\u00e9 en livraison.<br \/>Vous aimez travailler en autonomie et savez faire face aux al\u00e9as : vous savez rebondir en cas d&#8217;impr\u00e9vus sur votre tourn\u00e9e afin de garantir la satisfaction de nos clients.<br \/>Vous \u00eates dot\u00e9(e) d&#8217;un bon relationnel : vous savez entretenir une bonne relation avec nos clients.<\/p>\n","protected":false},"author":26276,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","job_listing_type":[481],"job_listing_category":[],"job_listing_location":[],"job_listing_tag":[],"class_list":["post-562139","job_listing","type-job_listing","status-publish","hentry","job_listing_type-full-time-da"],"aioseo_notices":[],"metas":{"_job_country_picker":"ChIJMVd4MymgVA0R99lHx5Y__Ws","_job_required_languages":"","_job_driving_license":"","_job_we_offer":"","_job_type":{"481":"Fuldtidsarbejde"},"_job_salary_type":"","_job_salary":"","_job_experience":"","_job_video_url":"","_job_photos":"","_job_application_deadline_date":"","_job_employer_name":"BMSO","_job_employer_url":"https:\/\/driver-work.com\/sv\/employer\/ext-bmso\/"},"_links":{"self":[{"href":"https:\/\/driver-work.com\/sv\/wp-json\/wp\/v2\/job_listing\/562139","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/driver-work.com\/sv\/wp-json\/wp\/v2\/job_listing"}],"about":[{"href":"https:\/\/driver-work.com\/sv\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/driver-work.com\/sv\/wp-json\/wp\/v2\/users\/26276"}],"replies":[{"embeddable":true,"href":"https:\/\/driver-work.com\/sv\/wp-json\/wp\/v2\/comments?post=562139"}],"version-history":[{"count":1,"href":"https:\/\/driver-work.com\/sv\/wp-json\/wp\/v2\/job_listing\/562139\/revisions"}],"predecessor-version":[{"id":562140,"href":"https:\/\/driver-work.com\/sv\/wp-json\/wp\/v2\/job_listing\/562139\/revisions\/562140"}],"wp:attachment":[{"href":"https:\/\/driver-work.com\/sv\/wp-json\/wp\/v2\/media?parent=562139"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/driver-work.com\/sv\/wp-json\/wp\/v2\/job_listing_type?post=562139"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/driver-work.com\/sv\/wp-json\/wp\/v2\/job_listing_category?post=562139"},{"taxonomy":"job_listing_location","embeddable":true,"href":"https:\/\/driver-work.com\/sv\/wp-json\/wp\/v2\/job_listing_location?post=562139"},{"taxonomy":"job_listing_tag","embeddable":true,"href":"https:\/\/driver-work.com\/sv\/wp-json\/wp\/v2\/job_listing_tag?post=562139"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}