{"id":561166,"date":"2026-07-12T00:08:45","date_gmt":"2026-07-12T00:08:45","guid":{"rendered":"https:\/\/driver-work.com\/job\/lkw-fahrer-m-w-d\/"},"modified":"2026-07-12T00:08:45","modified_gmt":"2026-07-12T00:08:45","slug":"job-561166","status":"publish","type":"job_listing","link":"https:\/\/driver-work.com\/sv\/job\/job-561166\/","title":{"rendered":"LKW-Fahrer (m\/w\/d)"},"content":{"rendered":"<p>Unique bietet Ihnen mehr als nur einen sicheren Arbeitsplatz. Bei unserem Kunden in Straubing erwartet Sie eine interessante Perspektive! Wir geben Ihnen einen unbefristeten Arbeitsvertrag mit tariflich geregelter Bezahlung, vielen Zusatzleistungen sowie beruflichen Entwicklungsm\u00f6glichkeiten. Wir suchen Sie in Vollzeit als LKW-Fahrer (m\/w\/d).<\/p>\n<p>Unser Angebot f\u00fcr dich als LKW-Fahrer (m\/w\/d) am Standort Straubing<\/p>\n<p>&#8211; P\u00fcnkltiche und korrekte Lohnzahlung<br \/>\n&#8211; Abschlagzahlungen m\u00f6glich<br \/>\n&#8211; Urlaubs- und Weihnachtsgeld<br \/>\n&#8211; Extrazahlung: 250 \u20ac Willkommensbonus<\/p>\n<p>Deine Aufgaben als LKW-Fahrer (m\/w\/d)<\/p>\n<p>&#8211; Be- und Entladen des LKW\u00b4s<br \/>\n&#8211; Ladungssicherung und Pflege des Fahrzeugs<br \/>\n&#8211; Fahrzeugpflege<br \/>\n&#8211; Durchf\u00fchrung von regelm\u00e4\u00dfigen Lieferungen<br \/>\n&#8211; Sicherstellung der p\u00fcnktlichen und sicheren Auslieferung der Waren<\/p>\n<p>Dein Profil als LKW-Fahrer (m\/w\/d) am Standort Straubing<\/p>\n<p>&#8211; F\u00fchrerschein Klasse C\/CE plus Fahrerkarte<br \/>\n&#8211; Teamf\u00e4hig und Zuverl\u00e4ssig<br \/>\n&#8211; Gute Deutschkenntnisse in Wort und Schrift<\/p>\n<p>Wir sind f\u00fcr dich da.<\/p>\n<p>Unique bietet dir einen sicheren Arbeitsplatz mit tariflich geregeltem Einkommen und vielen Extras. Denn du sollst Dich im Job wohlf\u00fchlen. Deine Zukunft ist unsere Aufgabe. Mit Unique hast du einen festen Hafen &#8211; heute und in Zukunft. Werde auch du Teil unseres Teams. Bis gleich!<\/p>\n<p>Das klingt nach einem guten Gesamtpaket f\u00fcr Dich? Dann freuen wir uns \u00fcber deine Online-Bewerbung als LKW-Fahrer (m\/w\/d) in Straubing.<\/p>\n<p>Ihr Ansprechpartner:<\/p>\n<p>Unique Personalservice GmbH<br \/>\nSelina Abstreiter<br \/>\nInnere Passauer Stra\u00dfe 30<br \/>\n94315 Straubing<br \/>\n+49 9421 96370<\/p>\n<p>bewerbung.straubing@unique-personal.de<br \/>\nhttps:\/\/unique-personal.de<\/p>\n","protected":false},"author":29930,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","job_listing_type":[487],"job_listing_category":[],"job_listing_location":[],"job_listing_tag":[],"class_list":["post-561166","job_listing","type-job_listing","status-publish","hentry","job_listing_type-full-time-nl"],"aioseo_notices":[],"metas":{"_job_country_picker":"ChIJa76xwh5ymkcRW-WRjmtd6HU","_job_required_languages":"","_job_driving_license":"","_job_we_offer":"","_job_type":{"487":"Voltijdwerk"},"_job_salary_type":"","_job_salary":"","_job_experience":"","_job_video_url":"","_job_photos":"","_job_application_deadline_date":"","_job_employer_name":"Unique Personalservice GmbH NL Straubing\u00a0 \u00a0","_job_employer_url":"https:\/\/driver-work.com\/sv\/employer\/ext-unique-personalservice-gmbh-nl-straubing\/"},"_links":{"self":[{"href":"https:\/\/driver-work.com\/sv\/wp-json\/wp\/v2\/job_listing\/561166","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/driver-work.com\/sv\/wp-json\/wp\/v2\/job_listing"}],"about":[{"href":"https:\/\/driver-work.com\/sv\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/driver-work.com\/sv\/wp-json\/wp\/v2\/users\/29930"}],"replies":[{"embeddable":true,"href":"https:\/\/driver-work.com\/sv\/wp-json\/wp\/v2\/comments?post=561166"}],"version-history":[{"count":1,"href":"https:\/\/driver-work.com\/sv\/wp-json\/wp\/v2\/job_listing\/561166\/revisions"}],"predecessor-version":[{"id":561167,"href":"https:\/\/driver-work.com\/sv\/wp-json\/wp\/v2\/job_listing\/561166\/revisions\/561167"}],"wp:attachment":[{"href":"https:\/\/driver-work.com\/sv\/wp-json\/wp\/v2\/media?parent=561166"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/driver-work.com\/sv\/wp-json\/wp\/v2\/job_listing_type?post=561166"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/driver-work.com\/sv\/wp-json\/wp\/v2\/job_listing_category?post=561166"},{"taxonomy":"job_listing_location","embeddable":true,"href":"https:\/\/driver-work.com\/sv\/wp-json\/wp\/v2\/job_listing_location?post=561166"},{"taxonomy":"job_listing_tag","embeddable":true,"href":"https:\/\/driver-work.com\/sv\/wp-json\/wp\/v2\/job_listing_tag?post=561166"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}