{"id":438405,"date":"2026-04-29T15:55:32","date_gmt":"2026-04-29T15:55:32","guid":{"rendered":"https:\/\/driver-work.com\/job\/vrachtwagenchauffeur-ce-kipper-v-x-m-gezocht\/"},"modified":"2026-04-29T15:55:32","modified_gmt":"2026-04-29T15:55:32","slug":"job-438405","status":"publish","type":"job_listing","link":"https:\/\/driver-work.com\/sv\/job\/job-438405\/","title":{"rendered":"Vrachtwagenchauffeur CE Kipper (v\/x\/m) gezocht"},"content":{"rendered":"<p>Als vrachtwagenchauffeur CE met kipper ben je verantwoordelijk voor het transport van glascontainers bij bedrijven in de regio Limburg. Je laadt en lost glascontainers en zorgt ervoor dat alle documenten correct worden ingevuld en afgehandeld door de bedrijven. Daarnaast zorg je ervoor dat lege containers op de juiste plek worden afgeleverd en volle containers naar het recyclagepark van onze klant worden gebracht.<\/p>\n<p>Een gemiddelde werkdag start vroeg in de ochtend, rond 5 \u00e0 6 uur. Je begint met een kop koffie met je collega&#8217;s voordat je de weg op gaat. Doorheen de dag werk je zelfstandig, maar blijf je in nauw contact met klanten. Je werkt gemiddeld 10 \u00e0 12 uur per dag en keert tegen 17 uur terug naar de site.<\/p>\n<p>Ben jij klaar om als vrachtwagenchauffeur CE het verschil te maken? Solliciteer dan nu en word onderdeel van ons hechte team. We kijken ernaar uit om jou te verwelkomen!<\/p>\n<ul>\n<li>Geldig rijbewijs CE met ervaring in het rijden met een kipper<\/li>\n<li>Bereidheid om vroeg te beginnen (5 \u00e0 6 uur)<\/li>\n<li>Zelfstandig kunnen werken en toch teamgericht zijn<\/li>\n<li>Klantgericht en communicatief sterk<\/li>\n<li>Flexibel in werktijden en klantwensen<\/li>\n<\/ul>\n","protected":false},"author":25766,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","job_listing_type":[67],"job_listing_category":[],"job_listing_location":[],"job_listing_tag":[],"class_list":["post-438405","job_listing","type-job_listing","status-publish","hentry","job_listing_type-full-time"],"aioseo_notices":[],"metas":{"_job_country_picker":"ChIJl5fz7WR9wUcR8g_mObTy60c","_job_required_languages":"","_job_driving_license":["CE"],"_job_we_offer":"","_job_type":{"67":"Full time work"},"_job_salary_type":"","_job_salary":"","_job_experience":"","_job_video_url":"","_job_photos":"","_job_application_deadline_date":"","_job_employer_name":"JOB TALENT NV","_job_employer_url":"https:\/\/driver-work.com\/sv\/employer\/ext-job-talent-nv\/"},"_links":{"self":[{"href":"https:\/\/driver-work.com\/sv\/wp-json\/wp\/v2\/job_listing\/438405","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/driver-work.com\/sv\/wp-json\/wp\/v2\/job_listing"}],"about":[{"href":"https:\/\/driver-work.com\/sv\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/driver-work.com\/sv\/wp-json\/wp\/v2\/users\/25766"}],"replies":[{"embeddable":true,"href":"https:\/\/driver-work.com\/sv\/wp-json\/wp\/v2\/comments?post=438405"}],"version-history":[{"count":0,"href":"https:\/\/driver-work.com\/sv\/wp-json\/wp\/v2\/job_listing\/438405\/revisions"}],"wp:attachment":[{"href":"https:\/\/driver-work.com\/sv\/wp-json\/wp\/v2\/media?parent=438405"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/driver-work.com\/sv\/wp-json\/wp\/v2\/job_listing_type?post=438405"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/driver-work.com\/sv\/wp-json\/wp\/v2\/job_listing_category?post=438405"},{"taxonomy":"job_listing_location","embeddable":true,"href":"https:\/\/driver-work.com\/sv\/wp-json\/wp\/v2\/job_listing_location?post=438405"},{"taxonomy":"job_listing_tag","embeddable":true,"href":"https:\/\/driver-work.com\/sv\/wp-json\/wp\/v2\/job_listing_tag?post=438405"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}