{"id":560100,"date":"2026-07-11T00:10:51","date_gmt":"2026-07-11T00:10:51","guid":{"rendered":"https:\/\/driver-work.com\/job\/lkw-fahrer-m-w-d\/"},"modified":"2026-07-11T00:10:51","modified_gmt":"2026-07-11T00:10:51","slug":"job-560100","status":"publish","type":"job_listing","link":"https:\/\/driver-work.com\/ru\/job\/job-560100\/","title":{"rendered":"LKW-Fahrer (m\/w\/d)"},"content":{"rendered":"<p>Standort: L\u00f6hne<br \/>\nArbeitszeit: 35 &#8212; 40 Stunden pro Woche<\/p>\n<p>LKW-Fahrer (m\/w\/d)<br \/>\nArbeitszeiten: Vollzeit<\/p>\n<p>Wir haben Ihr Interesse geweckt?<\/p>\n<p>Dann melden Sie sich telefonisch oder per E-Mail. Senden Sie uns gerne Ihre Kurzbewerbung oder bewerben sich \u00fcber unsere Internetseite am Standort Bad Oeynhausen in nur wenigen Minuten.<\/p>\n<p>tandem Personal und Dienstleistungen GmbH<br \/>\nMindener Str. 29<br \/>\n32547 Bad Oeynhausen<br \/>\nTel. 0573117740<br \/>\nwww.tandem-bo.de<br \/>\nbewerbung@tandem-bo.de<\/p>\n<p>Wir bieten Ihnen<br \/>\n&#8212; ab 19 Euro Stundenlohn<br \/>\n&#8212; Urlaubs- und Weihnachtsgeld<br \/>\n&#8212; wachsenden Urlaubsanspruch<br \/>\n&#8212; langfristige Besch\u00e4ftigung<\/p>\n<p>Ihre T\u00e4tigkeiten unter anderem:<br \/>\n&#8212; Fahren eines 40-Tonnen-LKW ohne Gefahrgut<br \/>\n&#8212; Auslieferung und Abholung von Waren im Nahverkehr<br \/>\n&#8212; gelegentlicher Fernverkehr mit \u00dcbernachtung<br \/>\n&#8212; Be- und Entladen des Fahrzeugs<\/p>\n<p>Sie bringen mit:<br \/>\n&#8212; F\u00fchrerschein Klasse C \/ CE<br \/>\n&#8212; idealerweise die BKrFQG (5-Module)<br \/>\n&#8212; Erfahrung w\u00fcnschenswert<br \/>\n&#8212; Zuverl\u00e4ssigkeit<br \/>\n&#8212; Verantwortungsbewusstsein<\/p>\n<p>Die tandem Personal und Dienstleistungen GmbH Bad Oeynhausen bietet dank der mehr als 32-j\u00e4hrigen Firmenhistorie der Unternehmensgruppe die Chance auf einzigartige, faire und lukrative Arbeitspl\u00e4tze.<br \/>\nGemeinsam bilden wir eines der f\u00fchrenden Dienstleistungsunternehmen Deutschlands.<br \/>\nWir freuen uns auf Ihre Bewerbung!<\/p>\n","protected":false},"author":19124,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","job_listing_type":[67],"job_listing_category":[],"job_listing_location":[],"job_listing_tag":[],"class_list":["post-560100","job_listing","type-job_listing","status-publish","hentry","job_listing_type-full-time"],"aioseo_notices":[],"metas":{"_job_country_picker":"ChIJa76xwh5ymkcRW-WRjmtd6HU","_job_required_languages":"","_job_driving_license":"","_job_we_offer":"","_job_type":{"67":"Full time work"},"_job_salary_type":"","_job_salary":"","_job_experience":"","_job_video_url":"","_job_photos":"","_job_application_deadline_date":"","_job_employer_name":"Tandem Personal und Dienstleistungen GmbH","_job_employer_url":"https:\/\/driver-work.com\/ru\/employer\/ext-tandem-personal-und-dienstleistungen-gmbh\/"},"_links":{"self":[{"href":"https:\/\/driver-work.com\/ru\/wp-json\/wp\/v2\/job_listing\/560100","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/driver-work.com\/ru\/wp-json\/wp\/v2\/job_listing"}],"about":[{"href":"https:\/\/driver-work.com\/ru\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/driver-work.com\/ru\/wp-json\/wp\/v2\/users\/19124"}],"replies":[{"embeddable":true,"href":"https:\/\/driver-work.com\/ru\/wp-json\/wp\/v2\/comments?post=560100"}],"version-history":[{"count":1,"href":"https:\/\/driver-work.com\/ru\/wp-json\/wp\/v2\/job_listing\/560100\/revisions"}],"predecessor-version":[{"id":560101,"href":"https:\/\/driver-work.com\/ru\/wp-json\/wp\/v2\/job_listing\/560100\/revisions\/560101"}],"wp:attachment":[{"href":"https:\/\/driver-work.com\/ru\/wp-json\/wp\/v2\/media?parent=560100"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/driver-work.com\/ru\/wp-json\/wp\/v2\/job_listing_type?post=560100"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/driver-work.com\/ru\/wp-json\/wp\/v2\/job_listing_category?post=560100"},{"taxonomy":"job_listing_location","embeddable":true,"href":"https:\/\/driver-work.com\/ru\/wp-json\/wp\/v2\/job_listing_location?post=560100"},{"taxonomy":"job_listing_tag","embeddable":true,"href":"https:\/\/driver-work.com\/ru\/wp-json\/wp\/v2\/job_listing_tag?post=560100"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}