{"id":530054,"date":"2026-06-20T00:15:54","date_gmt":"2026-06-20T00:15:54","guid":{"rendered":"https:\/\/driver-work.com\/job\/lkw-fahrer-m-w-d\/"},"modified":"2026-06-20T00:15:54","modified_gmt":"2026-06-20T00:15:54","slug":"job-530054","status":"publish","type":"job_listing","link":"https:\/\/driver-work.com\/ru\/job\/job-530054\/","title":{"rendered":"LKW-Fahrer (m\/w\/d)"},"content":{"rendered":"<p>LKW-Fahrer (m\/w\/d)<\/p>\n<p>Standort: Heiligenhaus<br \/>\nAnstellungsart(en): Vollzeit<\/p>\n<p>Seit \u00fcber 30 Jahren schreiben wir\u202fHeldenstories!<\/p>\n<p>M\u00f6chtest du ein Teil davon werden?<br \/>\nTrau dich und bewirb dich als LKW-Fahrer (m\/w\/d).<\/p>\n<p>Deine Mission<br \/>\n&#8212; Durchf\u00fchrung von Tagesfahrten im Umkreis<br \/>\n&#8212; Termingerechte Auslieferung und Abholung von Waren<br \/>\n&#8212; Be- und Entladung des Fahrzeugs unter Beachtung der Ladungssicherung<br \/>\n&#8212; Pflege und verantwortungsvoller Umgang mit dem Fahrzeug<br \/>\n&#8212; Einhaltung der gesetzlichen Lenk- und Ruhezeiten<\/p>\n<p>Deine Superkr\u00e4fte<br \/>\n&#8212; G\u00fcltiger F\u00fchrerschein der Klasse CE<br \/>\n&#8212; Fahrerkarte zwingend erforderlich<br \/>\n&#8212; Nachweis der gesetzlich vorgeschriebenen Berufskraftfahrer-Module (95)<br \/>\n&#8212; Erfahrung im LKW-Verkehr von Vorteil<br \/>\n&#8212; Zuverl\u00e4ssigkeit, P\u00fcnktlichkeit und selbstst\u00e4ndige Arbeitsweise<br \/>\n&#8212; Freundliches und kundenorientiertes Auftreten<br \/>\n&#8212; Gabelstaplerschein von Vorteil<\/p>\n<p>Unser Versprechen an dich<br \/>\n&#8212; Verg\u00fctung nach Vereinbarung zzgl. Zulagen &amp; Zuschl\u00e4gen<br \/>\n&#8212; M\u00f6gliche \u00dcbernahme durch unseren Kunden<br \/>\n&#8212; Verg\u00fcnstigungen bei diversen Anbietern (FitX, Mobilfunkanbietern &amp; Reisen)<br \/>\n&#8212; Bis zu 30 Urlaubstage<br \/>\n&#8212; Urlaubs- &amp; Weihnachtsgeld<br \/>\n&#8212; Abschlagszahlungen nach Wunsch<br \/>\n&#8212; Digitale Abwicklung per App<\/p>\n<p>Hier ist die Anleitung zu deiner eigenen #Heldenstory<\/p>\n<p>#1: Zaubere mit deinen Superkr\u00e4ften deine bisherigen Erfahrungen auf ein Dokument und nenne dieses Meisterwerk \u201cBewerbung\u201d.<br \/>\n#2: Nutze deine telepathischen Kr\u00e4fte und sende deine Bewerbung an uns.<br \/>\n#3:\u202fStarte gemeinsam mit uns deine TERO-Heldenstory, wir freuen uns!<\/p>\n<p>Kontaktdaten f\u00fcr Stellenanzeige<br \/>\nTERO GmbH<br \/>\nz.Hd. Frau Nesrin Aydin<br \/>\nHomberger Stra\u00dfe 25<br \/>\n40882 Ratingen<\/p>\n<p>Tel.: +49 (0)2102\/5400-54<br \/>\nWhatsApp: +49 (0)173\/5397401<br \/>\nE-Mail: ratingen@tero-personal.de<\/p>\n","protected":false},"author":14148,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","job_listing_type":[478],"job_listing_category":[],"job_listing_location":[],"job_listing_tag":[],"class_list":["post-530054","job_listing","type-job_listing","status-publish","hentry","job_listing_type-full-time-pl"],"aioseo_notices":[],"metas":{"_job_country_picker":"ChIJa76xwh5ymkcRW-WRjmtd6HU","_job_required_languages":"","_job_driving_license":"","_job_we_offer":"","_job_type":{"478":"Praca na pe\u0142en etat"},"_job_salary_type":"","_job_salary":"","_job_experience":"","_job_video_url":"","_job_photos":"","_job_application_deadline_date":"","_job_employer_name":"TERO GmbH","_job_employer_url":"https:\/\/driver-work.com\/ru\/employer\/ext-tero-gmbh\/"},"_links":{"self":[{"href":"https:\/\/driver-work.com\/ru\/wp-json\/wp\/v2\/job_listing\/530054","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/driver-work.com\/ru\/wp-json\/wp\/v2\/job_listing"}],"about":[{"href":"https:\/\/driver-work.com\/ru\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/driver-work.com\/ru\/wp-json\/wp\/v2\/users\/14148"}],"replies":[{"embeddable":true,"href":"https:\/\/driver-work.com\/ru\/wp-json\/wp\/v2\/comments?post=530054"}],"version-history":[{"count":1,"href":"https:\/\/driver-work.com\/ru\/wp-json\/wp\/v2\/job_listing\/530054\/revisions"}],"predecessor-version":[{"id":530055,"href":"https:\/\/driver-work.com\/ru\/wp-json\/wp\/v2\/job_listing\/530054\/revisions\/530055"}],"wp:attachment":[{"href":"https:\/\/driver-work.com\/ru\/wp-json\/wp\/v2\/media?parent=530054"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/driver-work.com\/ru\/wp-json\/wp\/v2\/job_listing_type?post=530054"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/driver-work.com\/ru\/wp-json\/wp\/v2\/job_listing_category?post=530054"},{"taxonomy":"job_listing_location","embeddable":true,"href":"https:\/\/driver-work.com\/ru\/wp-json\/wp\/v2\/job_listing_location?post=530054"},{"taxonomy":"job_listing_tag","embeddable":true,"href":"https:\/\/driver-work.com\/ru\/wp-json\/wp\/v2\/job_listing_tag?post=530054"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}