{"id":491055,"date":"2026-05-30T00:17:30","date_gmt":"2026-05-30T00:17:30","guid":{"rendered":"https:\/\/driver-work.com\/job\/conducteur-routier-h-f\/"},"modified":"2026-05-30T00:17:30","modified_gmt":"2026-05-30T00:17:30","slug":"job-491055","status":"publish","type":"job_listing","link":"https:\/\/driver-work.com\/ru\/job\/job-491055\/","title":{"rendered":"CONDUCTEUR ROUTIER H\/F"},"content":{"rendered":"<div id=\"shema_offre3\">\n<div>\n<p>\n                            <span>Notre filiale <b>TEHM <\/b>bas\u00e9e \u00e0 Longeau-Percey (52)\u00a0recherche des Conducteurs Routiers H\/F sur <b>Troyes<\/b>\u00a0(10) en zone r\u00e9gional pour une activit\u00e9 de messagerie palettis\u00e9.\u00a0<\/p>\n<div><\/div>\n<div>Quelques d\u00e9tails :<\/div>\n<div>&#8212; CDD \/ Contrat 169 heures \/ Coef 138<\/div>\n<div>&#8212; Prise de poste \u00e0 Troyes<\/div>\n<div>&#8212; Porteur 19 tonnes attitr\u00e9\u00a0<\/div>\n<div>&#8212; Lundi au vendredi pas de d\u00e9couche\u00a0<\/div>\n<div>&#8212; ADR<\/div>\n<div>-Utilisation PDA<\/div>\n<p><\/span>\n                        <\/p>\n<\/p><\/div>\n<\/p><\/div>\n","protected":false},"author":25972,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","job_listing_type":[],"job_listing_category":[],"job_listing_location":[],"job_listing_tag":[],"class_list":["post-491055","job_listing","type-job_listing","status-publish","hentry"],"aioseo_notices":[],"metas":{"_job_country_picker":"ChIJMVd4MymgVA0R99lHx5Y__Ws","_job_required_languages":"","_job_driving_license":"","_job_we_offer":"","_job_type":[],"_job_salary_type":"","_job_salary":"","_job_experience":"","_job_video_url":"","_job_photos":"","_job_application_deadline_date":"","_job_employer_name":"Groupe EONNET","_job_employer_url":"https:\/\/driver-work.com\/ru\/employer\/ext-groupe-eonnet\/"},"_links":{"self":[{"href":"https:\/\/driver-work.com\/ru\/wp-json\/wp\/v2\/job_listing\/491055","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/driver-work.com\/ru\/wp-json\/wp\/v2\/job_listing"}],"about":[{"href":"https:\/\/driver-work.com\/ru\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/driver-work.com\/ru\/wp-json\/wp\/v2\/users\/25972"}],"replies":[{"embeddable":true,"href":"https:\/\/driver-work.com\/ru\/wp-json\/wp\/v2\/comments?post=491055"}],"version-history":[{"count":1,"href":"https:\/\/driver-work.com\/ru\/wp-json\/wp\/v2\/job_listing\/491055\/revisions"}],"predecessor-version":[{"id":491056,"href":"https:\/\/driver-work.com\/ru\/wp-json\/wp\/v2\/job_listing\/491055\/revisions\/491056"}],"wp:attachment":[{"href":"https:\/\/driver-work.com\/ru\/wp-json\/wp\/v2\/media?parent=491055"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/driver-work.com\/ru\/wp-json\/wp\/v2\/job_listing_type?post=491055"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/driver-work.com\/ru\/wp-json\/wp\/v2\/job_listing_category?post=491055"},{"taxonomy":"job_listing_location","embeddable":true,"href":"https:\/\/driver-work.com\/ru\/wp-json\/wp\/v2\/job_listing_location?post=491055"},{"taxonomy":"job_listing_tag","embeddable":true,"href":"https:\/\/driver-work.com\/ru\/wp-json\/wp\/v2\/job_listing_tag?post=491055"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}