{"id":491007,"date":"2026-05-30T00:12:09","date_gmt":"2026-05-30T00:12:09","guid":{"rendered":"https:\/\/driver-work.com\/job\/conducteur-pl-spl-livreur-gaz-en-bouteilles-let\/"},"modified":"2026-05-30T00:12:09","modified_gmt":"2026-05-30T00:12:09","slug":"job-491007","status":"publish","type":"job_listing","link":"https:\/\/driver-work.com\/ru\/job\/job-491007\/","title":{"rendered":"Conducteur PL\/SPL livreur gaz en bouteilles LET"},"content":{"rendered":"<div id=\"shema_offre3\">\n<div>\n<p>\n                            <span><\/p>\n<div>\n<p>LOIRE ENTREPOT TRANSPORT est une PME sp\u00e9cialis\u00e9e dans le transport et la distribution de marchandises dangereuses (GPL). L&#8217;ensemble de ses 70 collaborateurs r\u00e9partis sur 7 sites sont engag\u00e9s au service de nos Clients dans un esprit de coh\u00e9sion et d&#8217;entraide.<\/p>\n<\/p>\n<\/div>\n<p><span><\/span><\/p>\n<p>Votre mission consiste \u00e0 approvisionner les stations services en bouteilles de gaz.<\/p>\n<p>Vos tourn\u00e9es sont compos\u00e9es d&#8217;environ 10 \u00e0 12 Clients par jour en moyenne.<\/p>\n<p>Prise de poste \u00e0 6h et fin de service entre 15 et 17h selon les tourn\u00e9es.<\/p>\n<p>Votre activit\u00e9 est organis\u00e9e sur 4 ou 5 jours du lundi au vendredi.<\/p>\n<p>Poste bas\u00e9 sur 169h mensuelles.<\/p>\n<p>R\u00e9mun\u00e9ration : Entre 2300\u20ac et 2500 \u20ac bruts \/ mois + Frais + Primes (Qualit\u00e9, 13\u00e8me mois, participation) + Mutuelle + CSE<\/p>\n<p>Int\u00e9gration d\u00e8s que possible avec un plan de formation de 2 \u00e0 3 semaines en double<\/p>\n<p>Ci-dessous une pr\u00e9sentation de notre m\u00e9tier :<br \/>https:\/\/www.youtube.com\/watch?v=YD1Gd3j44Qs<\/p>\n<\/p>\n<div>\n<p><span>Titulaire du permis C\/CE, de la FIMO (et FCO), de l\u2019ADR de base, vous justifiez de 1 ann\u00e9e d\u2019exp\u00e9rience de conduite.\u00a0<\/p>\n<p>Vous appr\u00e9ciez le contact Client, vous \u00eates respectueux des r\u00e8gles de s\u00e9curit\u00e9, vous \u00eates rigoureux et recherchez une certaine stabilit\u00e9, alors rejoignez nous&#8230;<\/span><\/p>\n<\/div>\n<p><\/span>\n                        <\/p>\n<\/p><\/div>\n<\/p><\/div>\n","protected":false},"author":25971,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","job_listing_type":[],"job_listing_category":[],"job_listing_location":[],"job_listing_tag":[],"class_list":["post-491007","job_listing","type-job_listing","status-publish","hentry"],"aioseo_notices":[],"metas":{"_job_country_picker":"ChIJMVd4MymgVA0R99lHx5Y__Ws","_job_required_languages":"","_job_driving_license":"","_job_we_offer":"","_job_type":[],"_job_salary_type":"","_job_salary":"","_job_experience":"","_job_video_url":"","_job_photos":"","_job_application_deadline_date":"","_job_employer_name":"GCA Transport et Distribution","_job_employer_url":"https:\/\/driver-work.com\/ru\/employer\/ext-gca-transport-et-distribution\/"},"_links":{"self":[{"href":"https:\/\/driver-work.com\/ru\/wp-json\/wp\/v2\/job_listing\/491007","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/driver-work.com\/ru\/wp-json\/wp\/v2\/job_listing"}],"about":[{"href":"https:\/\/driver-work.com\/ru\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/driver-work.com\/ru\/wp-json\/wp\/v2\/users\/25971"}],"replies":[{"embeddable":true,"href":"https:\/\/driver-work.com\/ru\/wp-json\/wp\/v2\/comments?post=491007"}],"version-history":[{"count":1,"href":"https:\/\/driver-work.com\/ru\/wp-json\/wp\/v2\/job_listing\/491007\/revisions"}],"predecessor-version":[{"id":491008,"href":"https:\/\/driver-work.com\/ru\/wp-json\/wp\/v2\/job_listing\/491007\/revisions\/491008"}],"wp:attachment":[{"href":"https:\/\/driver-work.com\/ru\/wp-json\/wp\/v2\/media?parent=491007"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/driver-work.com\/ru\/wp-json\/wp\/v2\/job_listing_type?post=491007"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/driver-work.com\/ru\/wp-json\/wp\/v2\/job_listing_category?post=491007"},{"taxonomy":"job_listing_location","embeddable":true,"href":"https:\/\/driver-work.com\/ru\/wp-json\/wp\/v2\/job_listing_location?post=491007"},{"taxonomy":"job_listing_tag","embeddable":true,"href":"https:\/\/driver-work.com\/ru\/wp-json\/wp\/v2\/job_listing_tag?post=491007"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}