{"id":489210,"date":"2026-05-29T00:11:39","date_gmt":"2026-05-29T00:11:39","guid":{"rendered":"https:\/\/driver-work.com\/job\/lkw-fahrer-m-w-d\/"},"modified":"2026-05-29T00:11:39","modified_gmt":"2026-05-29T00:11:39","slug":"job-489210","status":"publish","type":"job_listing","link":"https:\/\/driver-work.com\/ru\/job\/job-489210\/","title":{"rendered":"LKW-Fahrer (m\/w\/d)"},"content":{"rendered":"<p>Wir sind Trio Personalmanagement\u2014 Dein regionaler Personaldienstleister<\/p>\n<p>Die gesamte Gesch\u00e4ftsf\u00fchrung, Mitarbeiterinnen und Mitarbeiter bringen langj\u00e4hrige Erfahrung in den Bereichen Arbeitnehmer\u00fcberlassung, Personalvermittlung, Vertrieb, Customer Service, Recruiting und Employee Care mit und leben Ihre Arbeit mit einer sehr ausgepr\u00e4gten Dienstleistungsmentalit\u00e4t.<\/p>\n<p>LKW-Fahrer (m\/w\/d)<\/p>\n<p>Standort: Bretten<br \/>\nAnstellungsart(en): Vollzeit<br \/>\nArbeitszeit: 35 &#8212; 40 Stunden pro Woche<\/p>\n<p>Deine Aufgaben:<br \/>\n&#8212; Termingerechte Auslieferung der Waren unserer Kunden<br \/>\n&#8212; Verantwortlich f\u00fcr die ordnungsgem\u00e4\u00dfe Ladungssicherung<br \/>\n&#8212; Sorgsamer Umgang mit dem LKW<br \/>\n&#8212; Verantwortlich f\u00fcr die Sauberkeit des LKW<br \/>\n&#8212; Einhaltung aller gesetzlichen Vorschriften sowie Arbeitsanweisungen<br \/>\n&#8212; Einhaltung von Weisungen der Disposition<\/p>\n<p>Dein Profil:<br \/>\n&#8212; Sehr gute Erfahrung und sicherer Umgang mit BDF-H\u00e4ngerzug \/ Sattelzug<br \/>\n&#8212; Berufskraftfahrerqualifikation, eingetragen im F\u00fchrerschein mit Code95 w\u00e4re vorteilhaft<br \/>\n&#8212; Deutschkenntnisse in Wort und Schrift<br \/>\n&#8212; Zuverl\u00e4ssig, stets p\u00fcnktlich, flexibel, verantwortungsbewusst und belastbar<br \/>\n&#8212; Wohnort in Standortn\u00e4he<\/p>\n<p>Unser Angebot:<br \/>\n&#8212; Ein attraktives Verg\u00fctungspaket und Sonderzahlungen<br \/>\n&#8212; Eine langfristig gesicherte Perspektive mit Option auf \u00dcbernahme<br \/>\n&#8212; Abwechslungsreiche und interessante T\u00e4tigkeit<br \/>\n&#8212; Eins\u00e4tze in Deiner N\u00e4he<br \/>\n&#8212; Tarifliche Zuschl\u00e4ge (100 % Feiertagszulage, 50% Sonntagszulage, 25% Nachtzulage, 25% \u00dcberstundenzuschl\u00e4ge)<br \/>\n&#8212; Pers\u00f6nliche, qualifizierte und mehrsprachige (z.B. polnisch, mazedonisch, serbokroatisch, t\u00fcrkisch, italienisch, etc.) Betreuung<br \/>\n&#8212; Weiterbildungsm\u00f6glichkeiten<br \/>\n&#8212; Attraktive Sozialleistungen<br \/>\n&#8212; Fair Treatment<\/p>\n<p>Wir alle sind regional-pers\u00f6nlich-TRIO<\/p>\n<p>Haben wir Dein Interesse geweckt?<br \/>\nDann freuen wir uns auf Deine Bewerbung oder Deinen Besuch im Trio-Office in Bretten. Bitte sende uns Deine vollst\u00e4ndigen Bewerbungsunterlagen mit m\u00f6glichem Eintrittstermin und Deiner Gehaltsvorstellung, bevorzugt per E-Mail, zu.<\/p>\n<p>Wir bieten Voll-und Teilzeit Stellen unter anderem in folgenden Bereichen:<\/p>\n<p>Metall, Maschinenbau, Dienstleistung, Gesundheit, Soziales, P\u00e4dagogik, Elektro, Produktion, Fertigung, Verkehr, Logistik, Lager, Wirtschaft, Verwaltung<\/p>\n<p>Besuche uns auch auf www.trio-personal.de, Facebook und Instagram<\/p>\n<p>Kontakt:<\/p>\n<p>Trio Personalmanagement<\/p>\n<p>Engelsberg 12, 75015 Bretten<br \/>\n+49 7252 974 21 60<br \/>\nbretten@trio-personal.de<br \/>\nArt(en) des Personalbedarfs: Neubesetzung<br \/>\nTarifvertrag: GVP<\/p>\n","protected":false},"author":14105,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","job_listing_type":[],"job_listing_category":[],"job_listing_location":[],"job_listing_tag":[],"class_list":["post-489210","job_listing","type-job_listing","status-publish","hentry"],"aioseo_notices":[],"metas":{"_job_country_picker":"ChIJa76xwh5ymkcRW-WRjmtd6HU","_job_required_languages":"","_job_driving_license":"","_job_we_offer":"","_job_type":[],"_job_salary_type":"","_job_salary":"","_job_experience":"","_job_video_url":"","_job_photos":"","_job_application_deadline_date":"","_job_employer_name":"Trio Personalmanagement GmbH","_job_employer_url":"https:\/\/driver-work.com\/ru\/employer\/ext-trio-personalmanagement-gmbh\/"},"_links":{"self":[{"href":"https:\/\/driver-work.com\/ru\/wp-json\/wp\/v2\/job_listing\/489210","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/driver-work.com\/ru\/wp-json\/wp\/v2\/job_listing"}],"about":[{"href":"https:\/\/driver-work.com\/ru\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/driver-work.com\/ru\/wp-json\/wp\/v2\/users\/14105"}],"replies":[{"embeddable":true,"href":"https:\/\/driver-work.com\/ru\/wp-json\/wp\/v2\/comments?post=489210"}],"version-history":[{"count":1,"href":"https:\/\/driver-work.com\/ru\/wp-json\/wp\/v2\/job_listing\/489210\/revisions"}],"predecessor-version":[{"id":489211,"href":"https:\/\/driver-work.com\/ru\/wp-json\/wp\/v2\/job_listing\/489210\/revisions\/489211"}],"wp:attachment":[{"href":"https:\/\/driver-work.com\/ru\/wp-json\/wp\/v2\/media?parent=489210"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/driver-work.com\/ru\/wp-json\/wp\/v2\/job_listing_type?post=489210"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/driver-work.com\/ru\/wp-json\/wp\/v2\/job_listing_category?post=489210"},{"taxonomy":"job_listing_location","embeddable":true,"href":"https:\/\/driver-work.com\/ru\/wp-json\/wp\/v2\/job_listing_location?post=489210"},{"taxonomy":"job_listing_tag","embeddable":true,"href":"https:\/\/driver-work.com\/ru\/wp-json\/wp\/v2\/job_listing_tag?post=489210"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}