{"id":488181,"date":"2026-05-28T00:21:18","date_gmt":"2026-05-28T00:21:18","guid":{"rendered":"https:\/\/driver-work.com\/job\/lkw-fahrer_in\/"},"modified":"2026-05-28T00:21:18","modified_gmt":"2026-05-28T00:21:18","slug":"job-488181","status":"publish","type":"job_listing","link":"https:\/\/driver-work.com\/ru\/job\/job-488181\/","title":{"rendered":"LKW-Fahrer_in"},"content":{"rendered":"<p>work4life Personalservice konzentriert sich prim\u00e4r auf Dauerstellen bzw. langfristige Besch\u00e4ftigungsverh\u00e4ltnisse.<\/p>\n<p>Als Familienunternehmen im Bereich der Arbeitskr\u00e4fte\u00fcberlassung ist es unser oberstes Ziel die Anliegen unserer Mitarbeiter und Kunden bestm\u00f6glich zu vereinen um unserer Unternehmensphilosophie stets gerecht zu werden!<\/p>\n<\/p>\n<p>work4life sucht f\u00fcr einen renommierten Betrieb in der Holzbranche eine\/n LKW-Fahrer\/in f\u00fcr befristete Besch\u00e4ftigung. 1 LKW-Fahrer_in Einsatzort ist Allhaming.<\/p>\n<\/p>\n<p>T\u00e4tigkeitsfeld:<\/p>\n<p> * Warentransport mittels LKW zwischen den Firmeninternen Standorten in Ober\u00f6sterreich (t\u00e4gliche Heimkehr)<\/p>\n<p> * Laden oder Entladen der Ware lediglich begleiten (wird grunds\u00e4tzlich von Lagermitarbeitern durchgef\u00fchrt)<\/p>\n<\/p>\n<p>Anforderungen:<\/p>\n<p> * Im Idealfall bringen Sie Erfahrung als LKW-Fahrer mit<\/p>\n<p> * Eigenes KFZ zum Erreichen des Arbeitsplatzes in Allhaming<\/p>\n<p> * F\u00fchrerschein C, E, C95<\/p>\n<p> * Deutschkenntnisse<\/p>\n<\/p>\n<p>Geboten wird:<\/p>\n<p> * Gutes Betriebsklima<\/p>\n<p> * Befristetes Dienstverh\u00e4ltnis (vorraussichtlich 1-3 Monate)<\/p>\n<p> * M\u00f6glichkeit bei Eignung und Interesse zur erneuten Besch\u00e4ftigung (auch unbefristet sobald eine entsprechende Position zu besetzen ist)<\/p>\n<p> * Entlohnung: brutto \u20ac 18,00 je Stunde<\/p>\n<p> * M\u00f6glichkeit Berufspraxis zu sammeln<\/p>\n<p> * Nach Absprache M\u00f6glichkeit f\u00fcr w\u00f6chentliche Akontozahlungen<\/p>\n<p> * Arbeitskleidung<\/p>\n<p> * Gastarbeitern bieten wir nach Absprache gerne eine kostenfreie Unterkunft zur N\u00e4chtigung <\/p>\n<\/p>\n<\/p>\n<p>Im Sinne des Gleichbehandlungsgesetzes wenden wir uns gleicherma\u00dfen an weibliche sowie m\u00e4nnliche Bewerber.<\/p>\n<p>Ihre aussagekr\u00e4ftige Bewerbung inkl. Lebenslauf und Foto, senden Sie bitte an office@work4life.at oder bewerben sich gleich hier:<\/p>\n<\/p>\n<p>https:\/\/www.work4life.at\/job\/lkw-fahrer-mw Das Mindestentgelt f\u00fcr die Stelle als LKW-Fahrer_in betr\u00e4gt 18,00 EUR brutto pro Stunde. Bereitschaft zur \u00dcberzahlung.<\/p>\n","protected":false},"author":25975,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","job_listing_type":[67],"job_listing_category":[],"job_listing_location":[],"job_listing_tag":[],"class_list":["post-488181","job_listing","type-job_listing","status-publish","hentry","job_listing_type-full-time"],"aioseo_notices":[],"metas":{"_job_country_picker":"ChIJfyqdJZsHbUcRr8Hk3XvUEhA","_job_required_languages":"","_job_driving_license":"","_job_we_offer":"","_job_type":{"67":"Full time work"},"_job_salary_type":"","_job_salary":"","_job_experience":"","_job_video_url":"","_job_photos":"","_job_application_deadline_date":"","_job_employer_name":"Siehe Beschreibung","_job_employer_url":"https:\/\/driver-work.com\/ru\/employer\/ext-siehe-beschreibung\/"},"_links":{"self":[{"href":"https:\/\/driver-work.com\/ru\/wp-json\/wp\/v2\/job_listing\/488181","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/driver-work.com\/ru\/wp-json\/wp\/v2\/job_listing"}],"about":[{"href":"https:\/\/driver-work.com\/ru\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/driver-work.com\/ru\/wp-json\/wp\/v2\/users\/25975"}],"replies":[{"embeddable":true,"href":"https:\/\/driver-work.com\/ru\/wp-json\/wp\/v2\/comments?post=488181"}],"version-history":[{"count":1,"href":"https:\/\/driver-work.com\/ru\/wp-json\/wp\/v2\/job_listing\/488181\/revisions"}],"predecessor-version":[{"id":488182,"href":"https:\/\/driver-work.com\/ru\/wp-json\/wp\/v2\/job_listing\/488181\/revisions\/488182"}],"wp:attachment":[{"href":"https:\/\/driver-work.com\/ru\/wp-json\/wp\/v2\/media?parent=488181"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/driver-work.com\/ru\/wp-json\/wp\/v2\/job_listing_type?post=488181"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/driver-work.com\/ru\/wp-json\/wp\/v2\/job_listing_category?post=488181"},{"taxonomy":"job_listing_location","embeddable":true,"href":"https:\/\/driver-work.com\/ru\/wp-json\/wp\/v2\/job_listing_location?post=488181"},{"taxonomy":"job_listing_tag","embeddable":true,"href":"https:\/\/driver-work.com\/ru\/wp-json\/wp\/v2\/job_listing_tag?post=488181"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}