{"id":564371,"date":"2026-07-15T00:30:25","date_gmt":"2026-07-15T00:30:25","guid":{"rendered":"https:\/\/driver-work.com\/job\/chauffeur-pl-spl-tp-h-f\/"},"modified":"2026-07-15T00:30:25","modified_gmt":"2026-07-15T00:30:25","slug":"job-564371","status":"publish","type":"job_listing","link":"https:\/\/driver-work.com\/pl\/job\/job-564371\/","title":{"rendered":"Chauffeur PL\/SPL TP (H\/F)"},"content":{"rendered":"<p>L&#8217;entreprise intervient dans les domaines de l&#8217;ing\u00e9nierie appliqu\u00e9e aux travaux publics, aux ouvrages de g\u00e9nie civil, aux stations d&#8217;\u00e9puration ainsi qu&#8217;aux b\u00e2timents techniques. Dans le cadre du d\u00e9veloppement de ses activit\u00e9s sur un chantier situ\u00e9 \u00e0 Chamb\u00e9ry, elle recherche un.e Chauffeur PL \/ SPL afin d&#8217;assurer les rotations et l&#8217;approvisionnement du chantier en mat\u00e9riaux.Le poste s&#8217;inscrit dans un environnement chantier exigeant, n\u00e9cessitant une bonne ma\u00eetrise de la conduite en milieu TP ainsi qu&#8217;une capacit\u00e9 \u00e0 travailler en coordination avec les \u00e9quipes terrain. Missions principales : &#8211; Conduite camion benne 8&#215;4- Approvisionnement du chantier<\/p>\n","protected":false},"author":26101,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","job_listing_type":[],"job_listing_category":[],"job_listing_location":[],"job_listing_tag":[],"class_list":["post-564371","job_listing","type-job_listing","status-publish","hentry"],"aioseo_notices":[],"metas":{"_job_country_picker":"ChIJMVd4MymgVA0R99lHx5Y__Ws","_job_required_languages":"","_job_driving_license":"","_job_we_offer":"","_job_type":[],"_job_salary_type":"","_job_salary":"","_job_experience":"","_job_video_url":"","_job_photos":"","_job_application_deadline_date":"","_job_employer_name":"Non renseign\u00e9","_job_employer_url":"https:\/\/driver-work.com\/pl\/employer\/ext-non-renseigne-2\/"},"_links":{"self":[{"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/job_listing\/564371","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/job_listing"}],"about":[{"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/users\/26101"}],"replies":[{"embeddable":true,"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/comments?post=564371"}],"version-history":[{"count":1,"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/job_listing\/564371\/revisions"}],"predecessor-version":[{"id":564372,"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/job_listing\/564371\/revisions\/564372"}],"wp:attachment":[{"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/media?parent=564371"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/job_listing_type?post=564371"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/job_listing_category?post=564371"},{"taxonomy":"job_listing_location","embeddable":true,"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/job_listing_location?post=564371"},{"taxonomy":"job_listing_tag","embeddable":true,"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/job_listing_tag?post=564371"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}