{"id":562001,"date":"2026-07-13T00:06:30","date_gmt":"2026-07-13T00:06:30","guid":{"rendered":"https:\/\/driver-work.com\/job\/berufskraftfahrer-lkw-fahrer-m-w-d\/"},"modified":"2026-07-13T00:06:30","modified_gmt":"2026-07-13T00:06:30","slug":"job-562001","status":"publish","type":"job_listing","link":"https:\/\/driver-work.com\/pl\/job\/job-562001\/","title":{"rendered":"**Berufskraftfahrer \/ LKW-Fahrer (m\/w\/d)**"},"content":{"rendered":"<p>Die PETER KEREN Bauunternehmung GmbH ist f\u00fcr den Bau komplexer Bauvorhaben in den Bereichen Tiefbau, Ingenieurbau und Stra\u00dfenbau t\u00e4tig. Mithilfe unserer hoch qualifizierten Mitarbeiter\/-innen und unserem gro\u00dfen Maschinen- und Ger\u00e4tefuhrpark werden vielf\u00e4ltige Bauprojekte schnell und mit hoher Qualit\u00e4t umgesetzt.<\/p>\n<p>Wir suchen ab sofort<\/p>\n<p>**Berufskraftfahrer \/ LKW-Fahrer (m\/w\/d)** <\/p>\n<p>**f\u00fcr Kipperfahrzeuge (3-Achser, 4-Achser, Tandemzug)**<\/p>\n<p>Das bringen Sie mit:<\/p>\n<p>&#8211; F\u00fchrerschein Klasse C\/CE<br \/>\n&#8211; Selbstst\u00e4ndiges, teamorientiertes Arbeiten<br \/>\n&#8211; Freundlichkeit und Zuverl\u00e4ssigkeit<br \/>\n&#8211; Kenntnisse im Transport von Baumaschinen mit Tieflader sowie das Bedienen der Baumaschienen w\u00e4re von Vorteil<br \/>\n&#8211; Bedienen eines Kran-LKW\u00b4s ebenfalls<\/p>\n<p>Das bieten wir Ihnen:<\/p>\n<p>&#8211; eine Festanstellung<br \/>\n&#8211; einen unbefristeten Arbeitsvertrag<br \/>\n&#8211; attraktive Verg\u00fctung<br \/>\n&#8211; regionales Einsatzgebiet<br \/>\n&#8211; Weihnachtsgeld<br \/>\n&#8211; Urlaubsgeld<br \/>\n&#8211; Bonuszahlung<br \/>\n&#8211; Mitarbeitervorteile (JobRad \/ Corporate Benefits)<\/p>\n<p>Wir freuen uns auf Ihre Bewerbung per Email an:<\/p>\n<p>bewerbung@keren-bau.de<\/p>\n","protected":false},"author":29360,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","job_listing_type":[171],"job_listing_category":[],"job_listing_location":[],"job_listing_tag":[],"class_list":["post-562001","job_listing","type-job_listing","status-publish","hentry","job_listing_type-full-time-uk"],"aioseo_notices":[],"metas":{"_job_country_picker":"ChIJa76xwh5ymkcRW-WRjmtd6HU","_job_required_languages":"","_job_driving_license":"","_job_we_offer":"","_job_type":{"171":"\u041f\u043e\u0432\u043d\u0430 \u0437\u0430\u0439\u043d\u044f\u0442\u0456\u0441\u0442\u044c"},"_job_salary_type":"","_job_salary":"","_job_experience":"","_job_video_url":"","_job_photos":"","_job_application_deadline_date":"","_job_employer_name":"Peter Keren Bauunternehmung GmbH","_job_employer_url":"https:\/\/driver-work.com\/pl\/employer\/ext-peter-keren-bauunternehmung-gmbh\/"},"_links":{"self":[{"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/job_listing\/562001","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/job_listing"}],"about":[{"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/users\/29360"}],"replies":[{"embeddable":true,"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/comments?post=562001"}],"version-history":[{"count":1,"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/job_listing\/562001\/revisions"}],"predecessor-version":[{"id":562002,"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/job_listing\/562001\/revisions\/562002"}],"wp:attachment":[{"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/media?parent=562001"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/job_listing_type?post=562001"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/job_listing_category?post=562001"},{"taxonomy":"job_listing_location","embeddable":true,"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/job_listing_location?post=562001"},{"taxonomy":"job_listing_tag","embeddable":true,"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/job_listing_tag?post=562001"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}