{"id":561132,"date":"2026-07-12T00:11:06","date_gmt":"2026-07-12T00:11:06","guid":{"rendered":"https:\/\/driver-work.com\/job\/lkw-fahrer-m-w-d\/"},"modified":"2026-07-12T00:11:06","modified_gmt":"2026-07-12T00:11:06","slug":"job-561132","status":"publish","type":"job_listing","link":"https:\/\/driver-work.com\/pl\/job\/job-561132\/","title":{"rendered":"LKW-Fahrer (m\/w\/d)"},"content":{"rendered":"<p>Als eines der gr\u00f6\u00dften Personaldienstleistungsunternehmen im Norden arbeiten wir seit 2003 solidarisch und erfolgreich mit anerkannten Unternehmen aus der Weser-Ems-Region zusammen und unterst\u00fctzen diese durch unser Know-how bei der Personalauswahl.<\/p>\n<p>Zudem bieten wir jedem die M\u00f6glichkeit unsere jahrelange Erfahrung im Bewerbermanagement zu nutzen. Wir agieren somit als Bindeglied zwischen unseren namhaften Partnerunternehmen und den Bewerbern, die sich neu orientieren m\u00f6chten.<\/p>\n<p>Du bist LKW-Fahrer (m\/w\/d) und suchst ein neues Aufgabengebiet? Du m\u00f6chtest Dein Fachwissen einsetzen, Dich weiterentwickeln und dennoch flexibel bleiben? Dann unterst\u00fctze zum n\u00e4chstm\u00f6glichen Zeitpunkt unsere Kundenunternehmen und werde Mitglied unseres Teams.<\/p>\n<p>**LKW-Fahrer (m\/w\/d)**<\/p>\n<p>**Dein Aufgabengebiet umfasst u. a.:**<\/p>\n<p>\u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Durchf\u00fchrung von Transportauftr\u00e4gen im nationalen und internationalen G\u00fcterverkehr<br \/>\n\u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Be- und Entladung des LKWs sowie Sicherung der Ladung<br \/>\n\u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Pflege und Wartung des Fahrzeugs<br \/>\n\u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Einhaltung der gesetzlichen Vorschriften und Lenkzeiten<br \/>\n\u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Freundlicher und professioneller Umgang mit Kunden und Lieferanten<\/p>\n<p>****<\/p>\n<p>**Dein Profil:**<\/p>\n<p>\u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 G\u00fcltiger F\u00fchrerschein der Klasse CE<br \/>\n\u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Berufserfahrung als LKW-Fahrer w\u00fcnschenswert<br \/>\n\u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Kenntnisse in der Ladungssicherung und Umgang mit Frachtpapieren<br \/>\n\u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Zuverl\u00e4ssigkeit, P\u00fcnktlichkeit und selbstst\u00e4ndige Arbeitsweise<br \/>\n\u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Bereitschaft zu flexiblen Arbeitszeiten und gelegentlichen \u00dcbernachtungen<\/p>\n<p>****<\/p>\n<p>**Unsere Leistungen:**<br \/>\nEs erwarten Dich ein unbefristeter Arbeitsvertrag zu attraktiven Konditionen, Urlaubs- und Weihnachtsgeld und ein gutes Betriebsklima. Dar\u00fcber hinaus kannst Du Dich auf eine innovative und zuverl\u00e4ssige Betreuung unseres Teams verlassen.<\/p>\n<p>Du findest dich im obigen Profil wieder und hast Interesse Deine Karriere bei unseren Partnerunternehmen zu starten bzw. auszubauen? Dann nutze jetzt diese Chance und bewirb dich noch heute online, per E-Mail oder per Post. Solltest Du noch Fragen zu diesem Angebot haben, beantworten wir\u00a0diese gerne unter 0491-979691-0.<\/p>\n<p>Wir freuen uns auf Dich!<\/p>\n<p>Hinweis: Auf unserer Homepage befinden sich viele weitere interessante und attraktive Stellen im gewerblichen als auch im kaufm\u00e4nnischen Bereich. Ob als Facharbeiter oder Helfer, in den Bereichen Produktion, Metallbau und Logistik wie z.B. als Schlosser, Schwei\u00dfer, Mechaniker, Maschinen und Anlagenf\u00fchrer, Maschinenf\u00fchrer, Maschinenbediener, Lagermitarbeiter, Lagerhelfer, Produktionsmitarbeiter, Produktionshelfer, Staplerfahrer, Monteur\/Montierer, Disponent oder auch als Quereinsteiger =&gt; Hier ist f\u00fcr jeden etwas dabei.<\/p>\n","protected":false},"author":14354,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","job_listing_type":[475],"job_listing_category":[],"job_listing_location":[],"job_listing_tag":[],"class_list":["post-561132","job_listing","type-job_listing","status-publish","hentry","job_listing_type-full-time-fr"],"aioseo_notices":[],"metas":{"_job_country_picker":"ChIJa76xwh5ymkcRW-WRjmtd6HU","_job_required_languages":"","_job_driving_license":"","_job_we_offer":"","_job_type":{"475":"Travail \u00e0 temps plein"},"_job_salary_type":"","_job_salary":"","_job_experience":"","_job_video_url":"","_job_photos":"","_job_application_deadline_date":"","_job_employer_name":"Primus Personaldienstleistungen GmbH","_job_employer_url":"https:\/\/driver-work.com\/pl\/employer\/ext-primus-personaldienstleistungen-gmbh\/"},"_links":{"self":[{"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/job_listing\/561132","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/job_listing"}],"about":[{"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/users\/14354"}],"replies":[{"embeddable":true,"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/comments?post=561132"}],"version-history":[{"count":1,"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/job_listing\/561132\/revisions"}],"predecessor-version":[{"id":561133,"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/job_listing\/561132\/revisions\/561133"}],"wp:attachment":[{"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/media?parent=561132"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/job_listing_type?post=561132"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/job_listing_category?post=561132"},{"taxonomy":"job_listing_location","embeddable":true,"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/job_listing_location?post=561132"},{"taxonomy":"job_listing_tag","embeddable":true,"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/job_listing_tag?post=561132"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}