{"id":561116,"date":"2026-07-12T00:12:27","date_gmt":"2026-07-12T00:12:27","guid":{"rendered":"https:\/\/driver-work.com\/job\/berufskraftfahrer-lkw-fahrer-m-w-d\/"},"modified":"2026-07-12T00:12:27","modified_gmt":"2026-07-12T00:12:27","slug":"job-561116","status":"publish","type":"job_listing","link":"https:\/\/driver-work.com\/pl\/job\/job-561116\/","title":{"rendered":"Berufskraftfahrer\/LKW-Fahrer (m\/w\/d)"},"content":{"rendered":"<p>Reiling Logistik GmbH &amp; Co. KG<\/p>\n<p>## Berufskraftfahrer im Bereich Sch\u00fcttgut- und Landmaschinentransporte (m\/w\/d)<\/p>\n<p>ab sofort<\/p>\n<p>### Wer sind wir?<\/p>\n<p>Durch den heutigen Gesellschafter Christian Reiling wurde 1999 die Firma Christian Reiling Entsorgungslogistik und Transporte gegr\u00fcndet.  Im Jahre 2012 entstand aus diesem Unternehmen die heutige Gesellschaft Reiling Logistik GmbH &amp; Co. KG, die mehr als 90 Mitarbeiter besch\u00e4ftigt. Nationale und internationale Transporte von Sch\u00fcttgut und Landmaschinen geh\u00f6ren ebenso zu unserem Tagesgesch\u00e4ft wie die Leerung von Altglascontainern.<\/p>\n<p>### Welche T\u00e4tigkeiten erwarten dich?<\/p>\n<p>&#8211; Sicherer Transport von Schuttg\u00fctern und Landmaschinen, sowie der kommunalen Glassammlung, zu verschiedenen Zielorten innerhalb des festgelegten Zeitrahmens<br \/>\n&#8211; Durchf\u00fchrung von Fahrzeugkontrollen vor und nach Fahrten, um die Verkehrssicherheit zu gew\u00e4hrleisten<br \/>\n&#8211; Einhaltung aller gesetzlichen Vorschriften, insbesondere der Lenk- und Ruhezeiten sowie der Verkehrsregeln<br \/>\n&#8211; Dokumentation der Fahrten und Lieferscheine<br \/>\n&#8211; Kommunikation mit Disponenten, Kunden und anderen Teammitgliedern, um einen reibungslosen Ablauf zu gew\u00e4hrleisten<br \/>\n&#8211; Verantwortungsbewusster Umgang mit den Fahrzeugen sowie Pflege und Wartung der Fahrzeuge nach festgelegten Standards<\/p>\n<p>### Wir w\u00fcnschen uns von dir?<\/p>\n<p>&#8211; Einen sicheren Arbeitsplatz bei \u00fcberdurchschnittlicher Verg\u00fctung (Pr\u00e4mie, Auslandsspesen etc.)<br \/>\n&#8211; Verdienst im Gehalt und p\u00fcnktliche Bezahlung<br \/>\n&#8211; Zahlung von Urlaubs- und Weihnachtsgeld<br \/>\n&#8211; Umfassende Einarbeitung in ein herausforderndes und abwechslungsreiches Aufgabengebiet<br \/>\n&#8211; Einen modernen Fuhrpark (LKW&#8217;s der Marken Scania, DAF und Volvo sind max. 4 Jahre alt)<br \/>\n&#8211; Ein gutes Betriebsklima sowie moderne Kommunikationsmittel<\/p>\n<p>### Was bieten wir dir?<\/p>\n<p>&#8211; F\u00fchrerschein Klasse CE sowie die Fahrerkarte<br \/>\n&#8211; Nachweis \u00fcber eine g\u00fcltige Berufskraftfahrerqualifikation (Schulung gem\u00e4\u00df BKrFQG)<br \/>\n&#8211; Erfahrung im G\u00fcterverkehr ist von Vorteil, aber keine Voraussetzung<br \/>\n&#8211; Selbstst\u00e4ndiges Arbeiten<br \/>\n&#8211; Zuverl\u00e4ssigkeit, Verantwortungsbewusstsein und P\u00fcnktlichkeit<br \/>\n&#8211; Gute Deutschkenntnisse in Wort und Schrift<br \/>\n&#8211; Freundliches und gepflegtes Auftreten bei unseren Kunden<\/p>\n<p>### Sie sind Umsch\u00fcler und oder Berufsanf\u00e4nger (m\/w\/d), auch dann freuen wir uns auf Ihre Bewerbung.<\/p>\n<p>R\u00fcckfragen und Bewerbungen an:<\/p>\n<p>Reiling Logistik GmbH &amp; Co. KG<br \/>\nAnsprechpartner Herr Andr\u00e9 Claassen<br \/>\nAuf den Middeln 41<br \/>\n33428 Harsewinkel<br \/>\nTel.: 05247-983715<br \/>\nbewerbung@reiling-logistik.de<\/p>\n","protected":false},"author":29358,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","job_listing_type":[481],"job_listing_category":[],"job_listing_location":[],"job_listing_tag":[],"class_list":["post-561116","job_listing","type-job_listing","status-publish","hentry","job_listing_type-full-time-da"],"aioseo_notices":[],"metas":{"_job_country_picker":"ChIJa76xwh5ymkcRW-WRjmtd6HU","_job_required_languages":"","_job_driving_license":"","_job_we_offer":"","_job_type":{"481":"Fuldtidsarbejde"},"_job_salary_type":"","_job_salary":"","_job_experience":"","_job_video_url":"","_job_photos":"","_job_application_deadline_date":"","_job_employer_name":"Reiling Logistik GmbH &#038; Co. KG","_job_employer_url":"https:\/\/driver-work.com\/pl\/employer\/ext-reiling-logistik-gmbh-co-kg\/"},"_links":{"self":[{"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/job_listing\/561116","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/job_listing"}],"about":[{"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/users\/29358"}],"replies":[{"embeddable":true,"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/comments?post=561116"}],"version-history":[{"count":1,"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/job_listing\/561116\/revisions"}],"predecessor-version":[{"id":561117,"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/job_listing\/561116\/revisions\/561117"}],"wp:attachment":[{"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/media?parent=561116"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/job_listing_type?post=561116"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/job_listing_category?post=561116"},{"taxonomy":"job_listing_location","embeddable":true,"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/job_listing_location?post=561116"},{"taxonomy":"job_listing_tag","embeddable":true,"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/job_listing_tag?post=561116"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}