{"id":527482,"date":"2026-06-17T00:09:09","date_gmt":"2026-06-17T00:09:09","guid":{"rendered":"https:\/\/driver-work.com\/job\/chauffeur-de-camion-benne-h-f\/"},"modified":"2026-06-17T00:09:09","modified_gmt":"2026-06-17T00:09:09","slug":"job-527482","status":"publish","type":"job_listing","link":"https:\/\/driver-work.com\/pl\/job\/job-527482\/","title":{"rendered":"Chauffeur de camion-benne H\/F"},"content":{"rendered":"<p><\/p>\n<p><strong> Rejoignez un acteur incontournable de l&#8217;int\u00e9rim et du recrutement !<\/strong><\/p>\n<p>Aquila RH, membre du <strong>Mistertemp&#8217; Group<\/strong> (1 groupe, 4 marques, +230 agences en France), accompagne chaque ann\u00e9e <strong>plus de 62 000 talents<\/strong> dans leur parcours professionnel. Fort de <strong>+400 000 contrats sign\u00e9s<\/strong> et d&#8217;une <strong>expertise reconnue<\/strong>, notre r\u00e9seau mise sur la <strong>proximit\u00e9, l&#8217;\u00e9coute et la performance<\/strong>.<\/p>\n<p>Vous recherchez une exp\u00e9rience professionnelle enrichissante et durable ? C&#8217;est ici que \u00e7a commence !<\/p>\n<p>Nous recherchons pour le compte de notre client sp\u00e9cialis\u00e9 dans le secteur du transport un Chauffeur PL BOM H\/F<\/p>\n<p><\/p>\n<p>Vos missions<\/p>\n<p><strong>Chauffeur PL BOM (H\/F) &#8211; Rejoins une \u00e9quipe qui fait la diff\u00e9rence !<\/strong><\/p>\n<p>Nous recrutons un <strong>Chauffeur Benne \u00e0 Ordures M\u00e9nag\u00e8res (PL)<\/strong> pour int\u00e9grer une \u00e9quipe dynamique et engag\u00e9e au quotidien.<\/p>\n<p><strong>Ta mission (cl\u00e9 sur le terrain) :<\/strong><\/p>\n<ul>\n<li>Conduire le camion de collecte \u00e0 travers les rues de la ville<\/li>\n<li>Travailler en coordination avec les ripeurs<\/li>\n<li>Garantir une collecte efficace, propre et sans accroc<\/li>\n<li>Assurer le bon d\u00e9roulement de ta tourn\u00e9e du d\u00e9but \u00e0 la fin<\/li>\n<li>Adopter une conduite vigilante et s\u00e9curis\u00e9e pour prot\u00e9ger ton \u00e9quipe, les usagers et le mat\u00e9riel<\/li>\n<li>Un poste essentiel o\u00f9 ta rigueur et ton attention font toute la diff\u00e9rence !<\/li>\n<\/ul>\n<p><\/p>\n","protected":false},"author":25731,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","job_listing_type":[67],"job_listing_category":[],"job_listing_location":[],"job_listing_tag":[],"class_list":["post-527482","job_listing","type-job_listing","status-publish","hentry","job_listing_type-full-time"],"aioseo_notices":[],"metas":{"_job_country_picker":"ChIJMVd4MymgVA0R99lHx5Y__Ws","_job_required_languages":"","_job_driving_license":["C"],"_job_we_offer":"","_job_type":{"67":"Full time work"},"_job_salary_type":"","_job_salary":"","_job_experience":"","_job_video_url":"","_job_photos":"","_job_application_deadline_date":"","_job_employer_name":"Aquila RH","_job_employer_url":"https:\/\/driver-work.com\/pl\/employer\/ext-aquila-rh\/"},"_links":{"self":[{"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/job_listing\/527482","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/job_listing"}],"about":[{"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/users\/25731"}],"replies":[{"embeddable":true,"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/comments?post=527482"}],"version-history":[{"count":1,"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/job_listing\/527482\/revisions"}],"predecessor-version":[{"id":527483,"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/job_listing\/527482\/revisions\/527483"}],"wp:attachment":[{"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/media?parent=527482"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/job_listing_type?post=527482"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/job_listing_category?post=527482"},{"taxonomy":"job_listing_location","embeddable":true,"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/job_listing_location?post=527482"},{"taxonomy":"job_listing_tag","embeddable":true,"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/job_listing_tag?post=527482"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}