{"id":491150,"date":"2026-05-31T00:06:48","date_gmt":"2026-05-31T00:06:48","guid":{"rendered":"https:\/\/driver-work.com\/job\/lkw-fahrer-berufskraftfahrer-m-w-d\/"},"modified":"2026-05-31T00:06:48","modified_gmt":"2026-05-31T00:06:48","slug":"job-491150","status":"publish","type":"job_listing","link":"https:\/\/driver-work.com\/pl\/job\/job-491150\/","title":{"rendered":"LKW-Fahrer\/Berufskraftfahrer (m\/w\/d)"},"content":{"rendered":"<p>*Die\u00a0**AIM N\u00fcrnberg Vertriebs GmbH**\u00a0ist Teil der Triathlon Group, einem Unternehmen der Sunlight Group und weltweit f\u00fchrenden Anbieter von Batteriesystemen, Ladeger\u00e4ten und Energiemanagementl\u00f6sungen f\u00fcr industrielle Anwendungen. Vom Standort Dachau aus agieren wir im Gro\u00dfraum M\u00fcnchen als regional t\u00e4tige Vertriebs- und Serviceeinheit und versorgen unsere Gesch\u00e4ftspartner aus der Industrie mit innovativen Produkten auf Basis der Blei-S\u00e4ure- und Lithium-Ionen-Technologie sowie einem starken Serviceanspruch. Wir stehen unseren Kunden in allen Projektphasen von der Erstberatung \u00fcber die Detailplanung und Auslegung bis zur Herstellung und Montage des Batteriesystems zur Seite und gew\u00e4hrleisten somit zuverl\u00e4ssige, effiziente Prozesse.*<\/p>\n<p>Zur Verst\u00e4rkung unseres Teams in\u00a0**F\u00fcrth** suchen wir ab sofort eine\/n **LKW-Fahrer\/ Berufskraftfahrer (m\/w\/d)**<\/p>\n<p>### Ihr Aufgabengebiet:<\/p>\n<p>&#8211; Sichere Be- und Entladung am Firmensitz und bei unseren Kunden<br \/>\n&#8211; Einbau und Inbetriebnahme von Antriebsbatterien und Ladesystemen<\/p>\n<p>### Ihr Profil:<\/p>\n<p>&#8211; Berufserfahrung als Lkw-Fahrer \/ Auslieferfahrer \/ Berufskraftfahrer (m\/w\/d)<br \/>\n&#8211; F\u00fchrerschein der Klasse C\/CE und Eintrag 95er Modul (Modul BKrFQG)<br \/>\n&#8211; Handwerkliches und technisches Grundverst\u00e4ndnis vorausgesetzt<br \/>\n&#8211; Staplerschein<br \/>\n&#8211; Idealerweise Wohnort in Niederlassungsn\u00e4he<br \/>\n&#8211; Ausgepr\u00e4gte Dienstleistungsorientierung<br \/>\n&#8211; Interesse, Motivation und Eigeninitiative setzen wir voraus<br \/>\n&#8211; Gute Deutschkenntnisse<\/p>\n","protected":false},"author":28562,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","job_listing_type":[67],"job_listing_category":[],"job_listing_location":[],"job_listing_tag":[],"class_list":["post-491150","job_listing","type-job_listing","status-publish","hentry","job_listing_type-full-time"],"aioseo_notices":[],"metas":{"_job_country_picker":"ChIJa76xwh5ymkcRW-WRjmtd6HU","_job_required_languages":"","_job_driving_license":"","_job_we_offer":"","_job_type":{"67":"Full time work"},"_job_salary_type":"","_job_salary":"","_job_experience":"","_job_video_url":"","_job_photos":"","_job_application_deadline_date":"","_job_employer_name":"AIM Batterie Vertriebs GmbH","_job_employer_url":"https:\/\/driver-work.com\/pl\/employer\/ext-aim-batterie-vertriebs-gmbh\/"},"_links":{"self":[{"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/job_listing\/491150","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/job_listing"}],"about":[{"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/users\/28562"}],"replies":[{"embeddable":true,"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/comments?post=491150"}],"version-history":[{"count":1,"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/job_listing\/491150\/revisions"}],"predecessor-version":[{"id":491151,"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/job_listing\/491150\/revisions\/491151"}],"wp:attachment":[{"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/media?parent=491150"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/job_listing_type?post=491150"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/job_listing_category?post=491150"},{"taxonomy":"job_listing_location","embeddable":true,"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/job_listing_location?post=491150"},{"taxonomy":"job_listing_tag","embeddable":true,"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/job_listing_tag?post=491150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}