{"id":489931,"date":"2026-05-29T00:08:51","date_gmt":"2026-05-29T00:08:51","guid":{"rendered":"https:\/\/driver-work.com\/job\/chauffeur-spl-frigo-h-f\/"},"modified":"2026-05-29T00:08:51","modified_gmt":"2026-05-29T00:08:51","slug":"job-489931","status":"publish","type":"job_listing","link":"https:\/\/driver-work.com\/pl\/job\/job-489931\/","title":{"rendered":"Chauffeur SPL frigo H\/F"},"content":{"rendered":"<div id=\"shema_offre3\">\n<div>\n<p>\n                            <span><\/p>\n<p>Int\u00e9gr\u00e9 \u00e0 une \u00e9quipe de chauffeurs \/ conducteurs, vous serez rattach\u00e9 \u00e0 un Gestionnaire de transport.<\/p>\n<ul>\n<li>Vous conduirez un ensemble Frigo en<span> r\u00e9gional<\/span><\/li>\n<li>Vous r\u00e9aliserez les ordres de missions qui vous seront transmis par l\u2019exploitation dans le respect des r\u00e8gles de <strong>s\u00e9curit\u00e9<\/strong><\/li>\n<li>Vous serez l\u2019<strong>Ambassadeur<\/strong> du groupe MAUFFREY aupr\u00e8s des clients et des usagers de la route<\/li>\n<\/ul>\n<p>Contrat : CDI<\/p>\n<p>Si vous disposez :<\/p>\n<ul>\n<li>De votre Permis SPL (EC)<\/li>\n<li>De votre FIMO<\/li>\n<li>D\u2019une carte conducteur \u00e0 jour<\/li>\n<li>D\u2019une premi\u00e8re exp\u00e9rience dans le transport routier de marchandises<\/li>\n<li>Du sens du service client<\/li>\n<\/ul>\n<p>Alors ce poste est fait pour vous\u00a0!<\/p>\n<p> Devenir <strong>chauffeur<\/strong> \/ conducteur au sein du Groupe Mauffrey c&#8217;est :<br \/>&#8211; Conduire du mat\u00e9riel r\u00e9cent et renouvel\u00e9 tous les 4 ans<br \/>&#8211; \u00catre accompagn\u00e9 par un conducteur r\u00e9f\u00e9rent lors de votre int\u00e9gration et tout au long de votre vie professionnelle.<br \/>&#8211; Disposer de la technologie embarqu\u00e9e et des outils digitaux (smartphone, CMR \u00e9lectronique)<br \/>&#8211; Avoir des possibilit\u00e9s d&#8217;\u00e9volution interne et de mobilit\u00e9 g\u00e9ographique<\/span>\n                        <\/p>\n<\/p><\/div>\n<\/p><\/div>\n","protected":false},"author":25751,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","job_listing_type":[],"job_listing_category":[],"job_listing_location":[],"job_listing_tag":[],"class_list":["post-489931","job_listing","type-job_listing","status-publish","hentry"],"aioseo_notices":[],"metas":{"_job_country_picker":"ChIJMVd4MymgVA0R99lHx5Y__Ws","_job_required_languages":"","_job_driving_license":"","_job_we_offer":"","_job_type":[],"_job_salary_type":"","_job_salary":"","_job_experience":"","_job_video_url":"","_job_photos":"","_job_application_deadline_date":"","_job_employer_name":"GROUPE MAUFFREY","_job_employer_url":"https:\/\/driver-work.com\/pl\/employer\/ext-groupe-mauffrey\/"},"_links":{"self":[{"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/job_listing\/489931","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/job_listing"}],"about":[{"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/users\/25751"}],"replies":[{"embeddable":true,"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/comments?post=489931"}],"version-history":[{"count":1,"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/job_listing\/489931\/revisions"}],"predecessor-version":[{"id":489932,"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/job_listing\/489931\/revisions\/489932"}],"wp:attachment":[{"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/media?parent=489931"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/job_listing_type?post=489931"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/job_listing_category?post=489931"},{"taxonomy":"job_listing_location","embeddable":true,"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/job_listing_location?post=489931"},{"taxonomy":"job_listing_tag","embeddable":true,"href":"https:\/\/driver-work.com\/pl\/wp-json\/wp\/v2\/job_listing_tag?post=489931"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}