{"id":530050,"date":"2026-06-20T00:15:33","date_gmt":"2026-06-20T00:15:33","guid":{"rendered":"https:\/\/driver-work.com\/job\/lkw-fahrer-m-w-d\/"},"modified":"2026-06-20T00:15:33","modified_gmt":"2026-06-20T00:15:33","slug":"job-530050","status":"publish","type":"job_listing","link":"https:\/\/driver-work.com\/nl\/job\/job-530050\/","title":{"rendered":"LKW-Fahrer (m\/w\/d)"},"content":{"rendered":"<p>LKW-Fahrer (m\/w\/d)<\/p>\n<p>Standort: Kempen, Niederrhein<br \/>\nAnstellungsart(en): Vollzeit<br \/>\nArbeitszeit: 35 &#8211; 40 Stunden pro Woche<\/p>\n<p>Seit \u00fcber 30 Jahren schreiben wir Heldenstories!<\/p>\n<p>M\u00f6chtest du ein Teil davon werden?<br \/>\nTrau dich und bewirb dich als Mafi- oder Terborg Fahrer (m\/w\/d)<\/p>\n<p>Deine Mission<br \/>\n&#8211; Be- und Entladen der LKWs<br \/>\n&#8211; Auslieferung der Ware<br \/>\n&#8211; Sicherheitskontrolle der Fahrzeuge<\/p>\n<p>Deine Superkr\u00e4fte<br \/>\n&#8211; F\u00fchrerschein CE , B mit Modul 95<br \/>\n&#8211; Mehrj\u00e4hrige Fahrpraxis<br \/>\n&#8211; P\u00fcnktlichkeit und Zuverl\u00e4ssigkeit<br \/>\n&#8211; Flexibilit\u00e4t<br \/>\n&#8211; Deutschkenntnisse in Wort und Schrift<br \/>\n&#8211; Bereitschaft zu Nachtfahrten<\/p>\n<p>Unser Versprechen an dich<br \/>\n&#8211; Verg\u00fctung zwischen 16,69\u20ac -20,00\u20ac pro Stunde zzgl. Zulagen &amp; Zuschl\u00e4gen<br \/>\n&#8211; M\u00f6gliche \u00dcbernahme durch unseren Kunden<br \/>\n&#8211; Verg\u00fcnstigungen bei diversen Anbietern (FitX, Mobilfunkanbietern &amp; Reisen)<br \/>\n&#8211; Bis zu 30 Urlaubstage<br \/>\n&#8211; Urlaubs- &amp; Weihnachtsgeld<br \/>\n&#8211; Abschlagszahlungen nach Wunsch<br \/>\n&#8211; Digitale Abwicklung per App<\/p>\n<p>Hier ist die Anleitung zu deiner eigenen #Heldenstory<\/p>\n<p>#1: Zaubere mit deinen Superkr\u00e4ften deine bisherigen Erfahrungen auf ein Dokument und nenne dieses Meisterwerk \u201cBewerbung\u201d.<br \/>\n#2: Nutze deine telepathischen Kr\u00e4fte und sende deine Bewerbung an uns.<br \/>\n#3:\u202fStarte gemeinsam mit uns deine TERO-Heldenstory, wir freuen uns!<\/p>\n<p>Kontaktdaten f\u00fcr Stellenanzeige<br \/>\nTERO GmbH<br \/>\nz.Hd. Frau Nadine Labuch<br \/>\nKr\u00e4merstra\u00dfe 3<br \/>\n41460 Neuss<\/p>\n<p>Tel.: +49 (0)2131\/38799-0<br \/>\nWhatsApp: +49 (0)157\/52731427<br \/>\nE-Mail: neuss@tero-personal.de<br \/>\nArt(en) des Personalbedarfs: Neubesetzung<\/p>\n","protected":false},"author":14148,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","job_listing_type":[481],"job_listing_category":[],"job_listing_location":[],"job_listing_tag":[],"class_list":["post-530050","job_listing","type-job_listing","status-publish","hentry","job_listing_type-full-time-da"],"aioseo_notices":[],"metas":{"_job_country_picker":"ChIJa76xwh5ymkcRW-WRjmtd6HU","_job_required_languages":"","_job_driving_license":"","_job_we_offer":"","_job_type":{"481":"Fuldtidsarbejde"},"_job_salary_type":"","_job_salary":"","_job_experience":"","_job_video_url":"","_job_photos":"","_job_application_deadline_date":"","_job_employer_name":"TERO GmbH","_job_employer_url":"https:\/\/driver-work.com\/nl\/employer\/ext-tero-gmbh\/"},"_links":{"self":[{"href":"https:\/\/driver-work.com\/nl\/wp-json\/wp\/v2\/job_listing\/530050","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/driver-work.com\/nl\/wp-json\/wp\/v2\/job_listing"}],"about":[{"href":"https:\/\/driver-work.com\/nl\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/driver-work.com\/nl\/wp-json\/wp\/v2\/users\/14148"}],"replies":[{"embeddable":true,"href":"https:\/\/driver-work.com\/nl\/wp-json\/wp\/v2\/comments?post=530050"}],"version-history":[{"count":1,"href":"https:\/\/driver-work.com\/nl\/wp-json\/wp\/v2\/job_listing\/530050\/revisions"}],"predecessor-version":[{"id":530051,"href":"https:\/\/driver-work.com\/nl\/wp-json\/wp\/v2\/job_listing\/530050\/revisions\/530051"}],"wp:attachment":[{"href":"https:\/\/driver-work.com\/nl\/wp-json\/wp\/v2\/media?parent=530050"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/driver-work.com\/nl\/wp-json\/wp\/v2\/job_listing_type?post=530050"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/driver-work.com\/nl\/wp-json\/wp\/v2\/job_listing_category?post=530050"},{"taxonomy":"job_listing_location","embeddable":true,"href":"https:\/\/driver-work.com\/nl\/wp-json\/wp\/v2\/job_listing_location?post=530050"},{"taxonomy":"job_listing_tag","embeddable":true,"href":"https:\/\/driver-work.com\/nl\/wp-json\/wp\/v2\/job_listing_tag?post=530050"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}