{"id":529135,"date":"2026-06-19T00:08:42","date_gmt":"2026-06-19T00:08:42","guid":{"rendered":"https:\/\/driver-work.com\/job\/lkw-fahrer-m-w-d\/"},"modified":"2026-06-19T00:08:42","modified_gmt":"2026-06-19T00:08:42","slug":"job-529135","status":"publish","type":"job_listing","link":"https:\/\/driver-work.com\/nl\/job\/job-529135\/","title":{"rendered":"LKW-Fahrer (m\/w\/d)"},"content":{"rendered":"<p>Das Gebhardt Holz-Zentrum ist eines der f\u00fchrenden und innovativsten Unternehmen im Bereich des Holzgro\u00dfhandels. Unser nachhaltiges Sortiment beinhaltet vor allem Bauelemente, Platten, Terrassenbel\u00e4ge, Konstruktionsh\u00f6lzer und Schnitth\u00f6lzer. Ziel ist es, den Nachhaltigkeitsgedanken weiter auszubauen, sowie die Digitalisierungsprozesse in unserem Unternehmen zu optimieren und dadurch weiterhin der beste Partner f\u00fcr unsere Kunden zu bleiben. Als erfolgreiches Traditionsunternehmen verfolgen wir eine langfristige Unternehmens- und Personalpolitik. Um weiter zu wachsen, suchen wir\u00a0**DICH**\u00a0zur Verst\u00e4rkung unseres Teams!<\/p>\n<p>**Dein Profil:**<\/p>\n<p>&#8211; G\u00fcltiger F\u00fchrerschein der Klasse C\/CE<br \/>\n&#8211; Einsatzfreudig<br \/>\n&#8211; Erfolgsorientiert<br \/>\n&#8211; Selbst\u00e4ndiges und sicheres Auftreten<br \/>\n&#8211; Gute Umgangsformen<br \/>\n&#8211; Belastbar, flexibel und teamf\u00e4hig<\/p>\n<p>**Deine Aufgaben:**<\/p>\n<p>&#8211; Be- und Entladen unserer LKWs mit Staplern<br \/>\n&#8211; Ladungssicherung<br \/>\n&#8211; Warenauslieferung<\/p>\n<p>**Wir bieten:**<\/p>\n<p>&#8211; Attraktiven Stundenlohn<br \/>\n&#8211; Urlaubs-\/ und Weihnachtsgeld<br \/>\n&#8211; Angenehmes Arbeitsklima<br \/>\n&#8211; Arbeitskleidung<br \/>\n&#8211; Fahrradleasing<br \/>\n&#8211; Div. Betriebsveranstaltungen<br \/>\n&#8211; Fortbildungsm\u00f6glichkeiten<br \/>\n&#8211; Geregelte Arbeitszeiten<\/p>\n<p>Deine aussagekr\u00e4ftige Bewerbung richtest du bitte<\/p>\n<p>**per Mail an:\u00a0[bewerbung@ghz-cham.de](https:\/\/mailto:bewerbung@ghz-cham.de)<br \/>\n**oder per Post an:****<\/p>\n<p>Gebhardt Holz-Zentrum GmbH\u00a0\u00b7 Andreas Stadler<br \/>\nThierlsteiner Stra\u00dfe 9\u00a0\u00b7 93413 Cham<\/p>\n","protected":false},"author":24090,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","job_listing_type":[487],"job_listing_category":[],"job_listing_location":[],"job_listing_tag":[],"class_list":["post-529135","job_listing","type-job_listing","status-publish","hentry","job_listing_type-full-time-nl"],"aioseo_notices":[],"metas":{"_job_country_picker":"ChIJa76xwh5ymkcRW-WRjmtd6HU","_job_required_languages":"","_job_driving_license":"","_job_we_offer":"","_job_type":{"487":"Voltijdwerk"},"_job_salary_type":"","_job_salary":"","_job_experience":"","_job_video_url":"","_job_photos":"","_job_application_deadline_date":"","_job_employer_name":"Gebhardt Holz-Zentrum GmbH","_job_employer_url":"https:\/\/driver-work.com\/nl\/employer\/ext-gebhardt-holz-zentrum-gmbh\/"},"_links":{"self":[{"href":"https:\/\/driver-work.com\/nl\/wp-json\/wp\/v2\/job_listing\/529135","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/driver-work.com\/nl\/wp-json\/wp\/v2\/job_listing"}],"about":[{"href":"https:\/\/driver-work.com\/nl\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/driver-work.com\/nl\/wp-json\/wp\/v2\/users\/24090"}],"replies":[{"embeddable":true,"href":"https:\/\/driver-work.com\/nl\/wp-json\/wp\/v2\/comments?post=529135"}],"version-history":[{"count":1,"href":"https:\/\/driver-work.com\/nl\/wp-json\/wp\/v2\/job_listing\/529135\/revisions"}],"predecessor-version":[{"id":529136,"href":"https:\/\/driver-work.com\/nl\/wp-json\/wp\/v2\/job_listing\/529135\/revisions\/529136"}],"wp:attachment":[{"href":"https:\/\/driver-work.com\/nl\/wp-json\/wp\/v2\/media?parent=529135"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/driver-work.com\/nl\/wp-json\/wp\/v2\/job_listing_type?post=529135"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/driver-work.com\/nl\/wp-json\/wp\/v2\/job_listing_category?post=529135"},{"taxonomy":"job_listing_location","embeddable":true,"href":"https:\/\/driver-work.com\/nl\/wp-json\/wp\/v2\/job_listing_location?post=529135"},{"taxonomy":"job_listing_tag","embeddable":true,"href":"https:\/\/driver-work.com\/nl\/wp-json\/wp\/v2\/job_listing_tag?post=529135"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}