{"id":489181,"date":"2026-05-29T00:09:33","date_gmt":"2026-05-29T00:09:33","guid":{"rendered":"https:\/\/driver-work.com\/job\/lkw-fahrer-m-w-d\/"},"modified":"2026-05-29T00:09:33","modified_gmt":"2026-05-29T00:09:33","slug":"job-489181","status":"publish","type":"job_listing","link":"https:\/\/driver-work.com\/nl\/job\/job-489181\/","title":{"rendered":"LKW-Fahrer (m\/w\/d)"},"content":{"rendered":"<p>LKW-Fahrer (m\/w\/d)<\/p>\n<p>Standort: Strullendorf \/ Deutschlandweit<\/p>\n<p>Deine Aufgaben:<br \/>\n&#8211; Sicherer Transport von G\u00fctern im Fernverkehr<br \/>\n&#8211; Einsatz im WAB-Systemverkehr mit H\u00e4ngerzug<br \/>\n&#8211; Verantwortung f\u00fcr die Pflege und Wartung des Fahrzeugs<br \/>\n&#8211; Freundlicher Umgang mit Kundinnen, Kunden und Partnerunternehmen<br \/>\n&#8211; Einhaltung aller Verkehrs- und Sicherheitsvorschriften<br \/>\n&#8211; Kontrolle der Ladungssicherung und Transportdokumente<br \/>\n&#8211; Kommunikation mit Disposition und Fahrpersonal<br \/>\n&#8211; Einhaltung der Lenk- und Ruhezeiten<\/p>\n<p>Das bringst mit:<br \/>\n&#8211; F\u00fchrerschein Klasse C\/CE mit g\u00fcltiger Fahrerkarte<br \/>\n&#8211; Erfahrung als Berufskraftfahrer (m\/w\/d), LKW-Fahrer (m\/w\/d) oder Kraftfahrer (m\/w\/d)<br \/>\n&#8211; Erfahrung mit WAB-H\u00e4ngerzug von Vorteil<br \/>\n&#8211; Motivierte Quereinsteiger mit Fahrpraxis sind ebenfalls willkommen<br \/>\n&#8211; Zuverl\u00e4ssigkeit, P\u00fcnktlichkeit und Verantwortungsbewusstsein<br \/>\n&#8211; Flexibilit\u00e4t und Freude am Beruf<br \/>\n&#8211; Bereitschaft zum Nah- und Fernverkehr<\/p>\n<p>Wir bieten dir:<br \/>\n&#8211; Attraktive Verg\u00fctung inklusive Spesen, Pr\u00e4mien, Urlaubsgeld, Weihnachtsgeld und weiteren Zusatzleistungen<br \/>\n&#8211; Sicherer und unbefristeter Arbeitsplatz mit langfristiger Perspektive<br \/>\n&#8211; Planbare Arbeitszeiten durch geregelte und flexible Schichtsysteme (3\/1, 2\/1, 6\/2 oder 2\/2)<br \/>\n&#8211; Moderne und hochwertig ausgestattete LKW-Flotte<br \/>\n&#8211; Internationales und mehrsprachiges Team mit angenehmem Arbeitsklima<br \/>\n&#8211; Kosten\u00fcbernahme der Modulschulungen sowie Weiterbildungs- und Entwicklungsm\u00f6glichkeiten<br \/>\n&#8211; Strukturierte Einarbeitung und pers\u00f6nliche Betreuung<br \/>\n&#8211; Firmenfahrzeug oder organisierte Dienstfahrten<\/p>\n<p>Kontaktdaten f\u00fcr Stellenanzeige<br \/>\nAna-Maria Capatina<\/p>\n<p>0911 4247400<\/p>\n<p>RAHMER Zeitarbeit GmbH<br \/>\nIndustriestra\u00dfe 16<br \/>\n90441 N\u00fcrnberg<\/p>\n<p>job@rahmer.de<\/p>\n","protected":false},"author":22358,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","job_listing_type":[67],"job_listing_category":[],"job_listing_location":[],"job_listing_tag":[],"class_list":["post-489181","job_listing","type-job_listing","status-publish","hentry","job_listing_type-full-time"],"aioseo_notices":[],"metas":{"_job_country_picker":"ChIJa76xwh5ymkcRW-WRjmtd6HU","_job_required_languages":"","_job_driving_license":"","_job_we_offer":"","_job_type":{"67":"Full time work"},"_job_salary_type":"","_job_salary":"","_job_experience":"","_job_video_url":"","_job_photos":"","_job_application_deadline_date":"","_job_employer_name":"Rahmer Zeitarbeit GmbH","_job_employer_url":"https:\/\/driver-work.com\/nl\/employer\/ext-rahmer-zeitarbeit-gmbh\/"},"_links":{"self":[{"href":"https:\/\/driver-work.com\/nl\/wp-json\/wp\/v2\/job_listing\/489181","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/driver-work.com\/nl\/wp-json\/wp\/v2\/job_listing"}],"about":[{"href":"https:\/\/driver-work.com\/nl\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/driver-work.com\/nl\/wp-json\/wp\/v2\/users\/22358"}],"replies":[{"embeddable":true,"href":"https:\/\/driver-work.com\/nl\/wp-json\/wp\/v2\/comments?post=489181"}],"version-history":[{"count":1,"href":"https:\/\/driver-work.com\/nl\/wp-json\/wp\/v2\/job_listing\/489181\/revisions"}],"predecessor-version":[{"id":489182,"href":"https:\/\/driver-work.com\/nl\/wp-json\/wp\/v2\/job_listing\/489181\/revisions\/489182"}],"wp:attachment":[{"href":"https:\/\/driver-work.com\/nl\/wp-json\/wp\/v2\/media?parent=489181"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/driver-work.com\/nl\/wp-json\/wp\/v2\/job_listing_type?post=489181"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/driver-work.com\/nl\/wp-json\/wp\/v2\/job_listing_category?post=489181"},{"taxonomy":"job_listing_location","embeddable":true,"href":"https:\/\/driver-work.com\/nl\/wp-json\/wp\/v2\/job_listing_location?post=489181"},{"taxonomy":"job_listing_tag","embeddable":true,"href":"https:\/\/driver-work.com\/nl\/wp-json\/wp\/v2\/job_listing_tag?post=489181"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}