{"id":488037,"date":"2026-05-28T00:19:15","date_gmt":"2026-05-28T00:19:15","guid":{"rendered":"https:\/\/driver-work.com\/job\/lkw-fahrer-berufskraftfahrer-m-w-d\/"},"modified":"2026-05-28T00:19:15","modified_gmt":"2026-05-28T00:19:15","slug":"job-488037","status":"publish","type":"job_listing","link":"https:\/\/driver-work.com\/nl\/job\/job-488037\/","title":{"rendered":"LKW-Fahrer \/ Berufskraftfahrer (m\/w\/d)"},"content":{"rendered":"<p>###  Gute Gr\u00fcnde f\u00fcr GRIESHABER    <\/p>\n<p>&#8211; **Sicherheit &amp; Vorsorge:**\u00a0Neben einer attraktiven Verg\u00fctung nach GRIESHABER-Haustarif inkl. Weihnachtsgeld unterst\u00fctzen wir Ihre Absicherung durch eine bezuschusste betriebliche Altersvorsorge.<br \/>\n&#8211; **Fuhrparkmanagement &amp; Betreuung:**\u00a0Ein professionelles Fuhrparkmanagement, ein moderner Fuhrpark mit eigenen Werkst\u00e4tten und Waschstra\u00dfen sowie feste Ansprechpartner in der Speditions- und Personalabteilung.<br \/>\n&#8211; **Ausstattung:**\u00a0Wir stellen Ihnen moderne Arbeitskleidung inklusive Grundausstattung zur Verf\u00fcgung.<br \/>\n&#8211; **Ihre Entwicklung im Fokus:**\u00a0\u00dcber unsere hauseigene GRIESHABER Akademie stehen Ihnen vielf\u00e4ltige, kostenlose Weiterbildungsm\u00f6glichkeiten offen.<br \/>\n&#8211; **Gesundheit &amp; Mobilit\u00e4t:**\u00a0Nutzen Sie unser JobRad-Leasing oder halten Sie sich mit dem EGYM Wellpass fit. Unser Gesundheitsmanagement rundet das Angebot ab.<br \/>\n&#8211; **Zusatzleistungen:**\u00a0Profitieren Sie von attraktiven Pr\u00e4mien (z. B. \u201eMitarbeiter werben Mitarbeiter\u201c) und exklusiven Rabatten bei unseren Partnern.<\/p>\n<p>### Ihr Wirkungsbereich  <\/p>\n<p>Zur Verst\u00e4rkung unseres Teams in Weingarten suchen wir ab sofort LKW-Fahrer (m\/w\/d) f\u00fcr den Fern- und Nahverkehr. Zu Ihren Hauptaufgaben geh\u00f6ren vor allem:<\/p>\n<p>* Auslieferung von Waren aller Art im G\u00fcterfernverkehr<br \/>\n* Sicherstellung der Ladungssicherung gem\u00e4\u00df den gesetzlichen Vorschriften<br \/>\n* Pflege und Wartung am Fahrzeug<\/p>\n<p>### Das bringen Sie ins Team     <\/p>\n<p>* G\u00fcltiger F\u00fchrerschein der Klasse CE mit Eintrag der Schl\u00fcsselzahl 95 gem\u00e4\u00df BKrFQG zwingend erforderlich<br \/>\n* Staplerschein w\u00fcnschenswert<br \/>\n* ADR-Schein erforderlich<br \/>\n* Sicherer Umgang mit verschiedenen Fahrzeugtypen, insbesondere Sattel- und Wechselbr\u00fccken<br \/>\n* Langj\u00e4hrige Fahrpraxis als Berufskraftfahrer (m\/w\/d) erw\u00fcnscht<br \/>\n* Grundkenntnisse in der deutschen Sprache w\u00fcnschenswert<\/p>\n<p> **Ihr Ansprechpartner** <\/p>\n<p>Evelina Juretzki<\/p>\n<p>GRIESHABER Logistik GmbH<br \/>\nStettiner Stra\u00dfe 1<br \/>\nD-88250 Weingarten<br \/>\nTel.: +49 751 5001-165<br \/>\nE-Mail: EJuretzki@grieshaberlog.com<\/p>\n","protected":false},"author":14479,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","job_listing_type":[67],"job_listing_category":[],"job_listing_location":[],"job_listing_tag":[],"class_list":["post-488037","job_listing","type-job_listing","status-publish","hentry","job_listing_type-full-time"],"aioseo_notices":[],"metas":{"_job_country_picker":"ChIJa76xwh5ymkcRW-WRjmtd6HU","_job_required_languages":"","_job_driving_license":"","_job_we_offer":"","_job_type":{"67":"Full time work"},"_job_salary_type":"","_job_salary":"","_job_experience":"","_job_video_url":"","_job_photos":"","_job_application_deadline_date":"","_job_employer_name":"GRIESHABER Logistik GmbH","_job_employer_url":"https:\/\/driver-work.com\/nl\/employer\/ext-grieshaber-logistik-gmbh\/"},"_links":{"self":[{"href":"https:\/\/driver-work.com\/nl\/wp-json\/wp\/v2\/job_listing\/488037","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/driver-work.com\/nl\/wp-json\/wp\/v2\/job_listing"}],"about":[{"href":"https:\/\/driver-work.com\/nl\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/driver-work.com\/nl\/wp-json\/wp\/v2\/users\/14479"}],"replies":[{"embeddable":true,"href":"https:\/\/driver-work.com\/nl\/wp-json\/wp\/v2\/comments?post=488037"}],"version-history":[{"count":1,"href":"https:\/\/driver-work.com\/nl\/wp-json\/wp\/v2\/job_listing\/488037\/revisions"}],"predecessor-version":[{"id":488038,"href":"https:\/\/driver-work.com\/nl\/wp-json\/wp\/v2\/job_listing\/488037\/revisions\/488038"}],"wp:attachment":[{"href":"https:\/\/driver-work.com\/nl\/wp-json\/wp\/v2\/media?parent=488037"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/driver-work.com\/nl\/wp-json\/wp\/v2\/job_listing_type?post=488037"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/driver-work.com\/nl\/wp-json\/wp\/v2\/job_listing_category?post=488037"},{"taxonomy":"job_listing_location","embeddable":true,"href":"https:\/\/driver-work.com\/nl\/wp-json\/wp\/v2\/job_listing_location?post=488037"},{"taxonomy":"job_listing_tag","embeddable":true,"href":"https:\/\/driver-work.com\/nl\/wp-json\/wp\/v2\/job_listing_tag?post=488037"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}