{"id":563319,"date":"2026-07-14T00:05:06","date_gmt":"2026-07-14T00:05:06","guid":{"rendered":"https:\/\/driver-work.com\/job\/chauffeur-conducteur-routier-spl-zc-f-h\/"},"modified":"2026-07-14T00:05:06","modified_gmt":"2026-07-14T00:05:06","slug":"job-563319","status":"publish","type":"job_listing","link":"https:\/\/driver-work.com\/fr\/job\/job-563319\/","title":{"rendered":"Chauffeur \/ Conducteur routier SPL ZC (F\/H)"},"content":{"rendered":"<p>AVILOG, notre filiale sp\u00e9cialis\u00e9e dans le transport de canards vivants, vous propose un poste de conducteur routier sur un secteur r\u00e9gional (ZC).<\/p>\n<p> * Vous intervenez sur plusieurs activit\u00e9s : canard GRAS \/ canard PAE \/ canard MAIGRE<br \/> * Vous travaillez de nuit sans d\u00e9couch\u00e9s du dimanche soir au vendredi matin &#8211; certains samedis sur roulement<br \/> * Vous effectuez les transferts des rolls de canards (manutention au hayon \u00e9l\u00e9vateur) dans diff\u00e9rents \u00e9levages <br \/> * Le ramassage des canards est exclusivement effectu\u00e9 par l&rsquo;\u00e9leveur et\/ou son prestataire<br \/>&nbsp;&nbsp; <\/p>\n<p>Les raisons d&rsquo;int\u00e9grer l&rsquo;\u00e9quipe Avilog de Lauzach (56190) !<\/p>\n<p> * Vous int\u00e9grez une \u00e9quipe dynamique et solidaire et serez accompagn\u00e9 dans votre formation par un formateur interne<br \/> * Le poste \u00e0 pourvoir est en CDI sur une base de 169 heures mensuelles<br \/> * Le taux horaire brut est de 12.53\u20ac &#8211; minimum 2171.86\u20ac brut mensuel + frais &amp; prime + majoration des heures de nuit \u00e0 25%<br \/> * Int\u00e9ressement &amp; participation + mutuelle entreprise individuelle int\u00e9ressante + de nombreuses offres Groupe &amp; CSE \u00e0 d\u00e9couvrir ! + programme de cooptation<br \/> * Le Groupe, par ses multiples activit\u00e9s et agences partout en France, vous offre une possibilit\u00e9 de mobilit\u00e9 interne et d&rsquo;\u00e9volution de carri\u00e8re<\/p>\n","protected":false},"author":25854,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","job_listing_type":[67],"job_listing_category":[],"job_listing_location":[],"job_listing_tag":[],"class_list":["post-563319","job_listing","type-job_listing","status-publish","hentry","job_listing_type-full-time"],"aioseo_notices":[],"metas":{"_job_country_picker":"ChIJMVd4MymgVA0R99lHx5Y__Ws","_job_required_languages":"","_job_driving_license":"","_job_we_offer":"","_job_type":{"67":"Full time work"},"_job_salary_type":"","_job_salary":"","_job_experience":"","_job_video_url":"","_job_photos":"","_job_application_deadline_date":"","_job_employer_name":"AVILOG","_job_employer_url":"https:\/\/driver-work.com\/fr\/employer\/ext-avilog\/"},"_links":{"self":[{"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/job_listing\/563319","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/job_listing"}],"about":[{"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/users\/25854"}],"replies":[{"embeddable":true,"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/comments?post=563319"}],"version-history":[{"count":1,"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/job_listing\/563319\/revisions"}],"predecessor-version":[{"id":563320,"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/job_listing\/563319\/revisions\/563320"}],"wp:attachment":[{"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/media?parent=563319"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/job_listing_type?post=563319"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/job_listing_category?post=563319"},{"taxonomy":"job_listing_location","embeddable":true,"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/job_listing_location?post=563319"},{"taxonomy":"job_listing_tag","embeddable":true,"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/job_listing_tag?post=563319"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}