{"id":559682,"date":"2026-07-10T00:17:27","date_gmt":"2026-07-10T00:17:27","guid":{"rendered":"https:\/\/driver-work.com\/job\/chauffeur-spl-jour-h-f\/"},"modified":"2026-07-10T00:17:27","modified_gmt":"2026-07-10T00:17:27","slug":"job-559682","status":"publish","type":"job_listing","link":"https:\/\/driver-work.com\/fr\/job\/job-559682\/","title":{"rendered":"Chauffeur SPL jour (H\/F)"},"content":{"rendered":"<div id=\"shema_offre3\">\n<div>\n<p>\n                            <span>Manpower LESQUIN TRANSPORT recherche pour son client, un acteur du secteur des transports, un <strong>Chauffeur SPL<\/strong> jour (H\/F) Votre itin\u00e9raire quotidien :<br \/>&#8211; Conduite d&rsquo;un ensemble SPL<br \/>&#8211; Livraisons r\u00e9gionales ou nationales en journ\u00e9e, traction ou navette<br \/>&#8211; Chargement\/d\u00e9chargement selon les clients <br \/>&#8211; Respect des consignes de s\u00e9curit\u00e9, des d\u00e9lais et du code de la route <\/p>\n<p>Profil recherch\u00e9 :<br \/>&#8211; Permis CE + FIMO\/FCO + carte conducteur \u00e0 jour<br \/>&#8211; Routier exp\u00e9riment\u00e9<br \/>&#8211; Autonomie, rigueur et bonne humeur au volant<\/p>\n<p>Ce que Manpower met dans votre remorque :<br \/>&#8211; Compte \u00e9pargne temps \u00e0 8&amp;#37; (plus rentable qu&rsquo;un plein de gasoil)<br \/>&#8211; Avantages CE : ch\u00e8ques vacances, r\u00e9ductions loisirs, cin\u00e9, sport, etc.<br \/>&#8211; Jusqu&rsquo;\u00e0 60&amp;#37; de remise sur vos courses du quotidien<br \/>&#8211; Mutuelle solide et accompagnement personnalis\u00e9<br \/>&#8211; Acc\u00e8s \u00e0 la formation pour booster votre carri\u00e8re (et votre salaire !)<\/p>\n<p>Dans le cadre de sa politique diversit\u00e9, Manpower \u00e9tudie, \u00e0 comp\u00e9tences \u00e9gales, toutes candidatures dont celles de personnes en situation de handicap<\/p>\n<p>Contrat : Mission en int\u00e9rim<\/p>\n<p>Exp\u00e9rience : 1 an<\/p>\n<p>Salaire : 12,43 \u20ac par heure<\/p>\n<p>Date de d\u00e9but : D\u00e8s que possible<\/p>\n<p>Dur\u00e9e : 1 semaine(s) renouvelable<\/p>\n<p>Information compl\u00e9mentaire : jour<\/span>\n                        <\/p>\n<\/p><\/div>\n<\/p><\/div>\n","protected":false},"author":25760,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","job_listing_type":[],"job_listing_category":[],"job_listing_location":[],"job_listing_tag":[],"class_list":["post-559682","job_listing","type-job_listing","status-publish","hentry"],"aioseo_notices":[],"metas":{"_job_country_picker":"ChIJMVd4MymgVA0R99lHx5Y__Ws","_job_required_languages":"","_job_driving_license":"","_job_we_offer":"","_job_type":[],"_job_salary_type":"","_job_salary":"","_job_experience":"","_job_video_url":"","_job_photos":"","_job_application_deadline_date":"","_job_employer_name":"Manpower","_job_employer_url":"https:\/\/driver-work.com\/fr\/employer\/ext-manpower-3\/"},"_links":{"self":[{"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/job_listing\/559682","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/job_listing"}],"about":[{"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/users\/25760"}],"replies":[{"embeddable":true,"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/comments?post=559682"}],"version-history":[{"count":1,"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/job_listing\/559682\/revisions"}],"predecessor-version":[{"id":559683,"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/job_listing\/559682\/revisions\/559683"}],"wp:attachment":[{"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/media?parent=559682"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/job_listing_type?post=559682"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/job_listing_category?post=559682"},{"taxonomy":"job_listing_location","embeddable":true,"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/job_listing_location?post=559682"},{"taxonomy":"job_listing_tag","embeddable":true,"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/job_listing_tag?post=559682"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}