{"id":559557,"date":"2026-07-10T00:08:45","date_gmt":"2026-07-10T00:08:45","guid":{"rendered":"https:\/\/driver-work.com\/job\/chauffeur-pl-spl-h-f\/"},"modified":"2026-07-10T00:08:45","modified_gmt":"2026-07-10T00:08:45","slug":"job-559557","status":"publish","type":"job_listing","link":"https:\/\/driver-work.com\/fr\/job\/job-559557\/","title":{"rendered":"Chauffeur PL \/ SPL H\/F"},"content":{"rendered":"<p>Dans le cadre de cette mission, vous assurez le transport de marchandises dans le respect des d\u00e9lais et des consignes de s\u00e9curit\u00e9.<br \/>\n<br \/>\n\u00c0 ce titre, vous serez amen\u00e9(e) \u00e0 :<br \/>\n<br \/>\nConduire un camion Poids Lourd (PL) ou Super Poids Lourd (SPL),<br \/>\n<br \/>\nAssurer les livraisons et enl\u00e8vements aupr\u00e8s des clients,<br \/>\n<br \/>\nCharger et d\u00e9charger les marchandises si n\u00e9cessaire,<br \/>\n<br \/>\nV\u00e9rifier l&rsquo;\u00e9tat du v\u00e9hicule et effectuer les contr\u00f4les de s\u00e9curit\u00e9,<br \/>\n<br \/>\nCompl\u00e9ter les documents de transport,<br \/>\n<br \/>\nRespecter la r\u00e9glementation routi\u00e8re et les consignes de s\u00e9curit\u00e9.<\/p>\n","protected":false},"author":26566,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","job_listing_type":[475],"job_listing_category":[],"job_listing_location":[],"job_listing_tag":[],"class_list":["post-559557","job_listing","type-job_listing","status-publish","hentry","job_listing_type-full-time-fr"],"aioseo_notices":[],"metas":{"_job_country_picker":"ChIJMVd4MymgVA0R99lHx5Y__Ws","_job_required_languages":"","_job_driving_license":["C","CE"],"_job_we_offer":"","_job_type":{"475":"Travail \u00e0 temps plein"},"_job_salary_type":"","_job_salary":"","_job_experience":"","_job_video_url":"","_job_photos":"","_job_application_deadline_date":"","_job_employer_name":"ALTEREGO","_job_employer_url":"https:\/\/driver-work.com\/fr\/employer\/ext-alterego\/"},"_links":{"self":[{"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/job_listing\/559557","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/job_listing"}],"about":[{"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/users\/26566"}],"replies":[{"embeddable":true,"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/comments?post=559557"}],"version-history":[{"count":1,"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/job_listing\/559557\/revisions"}],"predecessor-version":[{"id":559558,"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/job_listing\/559557\/revisions\/559558"}],"wp:attachment":[{"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/media?parent=559557"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/job_listing_type?post=559557"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/job_listing_category?post=559557"},{"taxonomy":"job_listing_location","embeddable":true,"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/job_listing_location?post=559557"},{"taxonomy":"job_listing_tag","embeddable":true,"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/job_listing_tag?post=559557"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}