{"id":543902,"date":"2026-07-03T00:05:12","date_gmt":"2026-07-03T00:05:12","guid":{"rendered":"https:\/\/driver-work.com\/job\/lkw-fahrer-m-w-d\/"},"modified":"2026-07-03T00:05:12","modified_gmt":"2026-07-03T00:05:12","slug":"job-543902","status":"publish","type":"job_listing","link":"https:\/\/driver-work.com\/fr\/job\/job-543902\/","title":{"rendered":"LKW-Fahrer (m\/w\/d)"},"content":{"rendered":"<p>LKW-Fahrer Minijob (m\/w\/d)<\/p>\n<p>Als Familienunternehmen mit \u00fcber 400 Mitarbeitern sind wir seit \u00fcber 45 Jahren an den zw\u00f6lf Standorten in Achern (3x), Kehl Europabr\u00fccke, Kehl-Sundheim, Offenburg, Freiburg, D\u00fcsseldorf,\u00a0 M\u00fcnchen, Berlin, Hamburg und Paris t\u00e4tig.<br \/>\n \u00a0<br \/>\nWir befinden uns in einer starken Wachstumsphase und haben unseren Umsatz in k\u00fcrzester Zeit vervielfacht.\u00a0Wir m\u00f6chten den Wachstumspfad, aufgrund unseres Erfolges, konsequent weitergehen und suchen deshalb talentierte und motivierte Pers\u00f6nlichkeiten. Gemeinsam m\u00f6chten wir unsere Erfolgsstory weiterschreiben.\u00a0<br \/>\n \u00a0<br \/>\n#greatplacetowork\u00a0 \u00a0 #familienunternehmen\u00a0 \u00a0 #vielf\u00e4ltig\u00a0 \u00a0\u00a0#abwechslungsreich\u00a0 #CarEnthusiasts\u00a0 \u00a0 \u00a0 # achern\u00a0 \u00a0#minijob<br \/>\n \u00a0<br \/>\nJoin our team of car enthusiasts an unserem Standort in Achern als Minijobber<\/p>\n<p>#YOU<br \/>\n &#8211; Sie sind zuverl\u00e4ssig und fahren gerne LKW<\/p>\n<p> &#8211; Sie haben einen CE F\u00fchrerschein\u00a0<br \/>\n &#8211; \u200bOptional: Schl\u00fcsselzahl 95<br \/>\n &#8211; KFZ-Kenntnisse von Vorteil (z. B. Auto \u00fcberbr\u00fccken, \u00d6lstand messen, Birne wechseln etc.) Aber nicht zwingend erforderlich.\u00a0\u00a0<\/p>\n<p>#YOUR JOB<br \/>\n &#8211; Fahrzeugtransfer zwischen unseren Stellpl\u00e4tzen und Standorten<\/p>\n<p> &#8211; Sichtkontrolle der Fahrzeuge<br \/>\n &#8211; \u200bAnlage der Fahrzeuge in unserem EDV-System\u00a0<br \/>\n \u00a0<br \/>\n \u00a0<\/p>\n<p>#WHY US<br \/>\n &#8211; Wir sind erfolgreicher als viele unserer Mitbewerber. Das liegt neben den Werten eines modernen Familienunternehmens vor allem an unseren motivierten und freundlichen Mitarbeitern, die mit Freude dabei sind und sich als ein Team verstehen. Werden Sie Teil dieses Tabor Teams.\u00a0<\/p>\n<p> &#8211; Unser Fokus als Familienunternehmen liegt auf einer besonders langfristig ausgelegten Zusammenarbeit und praxisorientierten Produktfortbildungen. Bei uns k\u00f6nnen Sie richtig ankommen &#8211; und gerne langfristig bleiben!<\/p>\n<p> &#8211; Zum Start bei uns erhalten Sie eine entsprechende Einarbeitung und einen \u00ab\u00a0Buddy\u00a0\u00bb, der Ihnen ab Tag 1 f\u00fcr alle Ihre Fragen zur Seite steht.<\/p>\n<p> &#8211; Die Weiterentwicklung unserer Mitarbeiter liegt uns sehr am Herzen, daher legen wir viel Wert auf deren F\u00f6rderung und bezuschussen diese aktiv.<\/p>\n<p> &#8211; Wir haben ein attraktives Bonuspunktesystem, das tolle Leistungen mit tollen Pr\u00e4mien im breit gef\u00e4chertem Pr\u00e4mienshop belohnt.<\/p>\n<p> &#8211; Unsere Mitarbeiter profitieren von einem Werkstatt- und Waschstra\u00dfenrabatt und speziellen Konditionen beim Fahrzeug-Leasing.<\/p>\n<p> &#8211; Betriebliche Gesundheitsf\u00f6rderung ist uns wichtig. Daher bieten wir kostenlose Online- und Pr\u00e4senzkurse (z. B. Yoga) zur F\u00f6rderung der Gesundheit unserer Mitarbeiter an.<\/p>\n<p> &#8211; Obst, Kaffee und Tee stehen gratis zur Verf\u00fcgung.<\/p>\n<p> &#8211; J\u00e4hrlich kostenlose Massagen.<\/p>\n<p> &#8211; Unsere Mitarbeiter erhalten bis zu 32 Urlaubstage<\/p>\n<p> &#8211; Wir sind offizieller Sponsor des Bundesligisten SC Freiburg! Wie wir steht der SC Freiburg seit Jahrzehnten f\u00fcr echten Teamgeist, Bodenst\u00e4ndigkeit und N\u00e4he zu den Menschen in S\u00fcdbaden und ist daher der perfekte Partner f\u00fcr uns als Familienunternehmen.<br \/>\n \u00a0<br \/>\nBitte schicken Sie uns Ihren Lebenslauf und Ihre Zeugnisse. Wir freuen uns auf Ihre Kontaktaufnahme. Bei Fragen k\u00f6nnen Sie uns gerne anrufen. Sollte Ihre Bewerbung unserem Profil entsprechen, werden wir im ersten Schritt ein kurzes Telefonat mit Ihnen f\u00fchren.\u00a0<br \/>\nBei einem eventuellen Bewerbungsgespr\u00e4ch freuen wir uns Sie vor Ort oder im ersten Schritt per Video kennenzulernen!<\/p>\n","protected":false},"author":29531,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","job_listing_type":[475],"job_listing_category":[],"job_listing_location":[],"job_listing_tag":[],"class_list":["post-543902","job_listing","type-job_listing","status-publish","hentry","job_listing_type-full-time-fr"],"aioseo_notices":[],"metas":{"_job_country_picker":"ChIJa76xwh5ymkcRW-WRjmtd6HU","_job_required_languages":"","_job_driving_license":"","_job_we_offer":"","_job_type":{"475":"Travail \u00e0 temps plein"},"_job_salary_type":"","_job_salary":"","_job_experience":"","_job_video_url":"","_job_photos":"","_job_application_deadline_date":"","_job_employer_name":"Autohaus Tabor GmbH","_job_employer_url":"https:\/\/driver-work.com\/fr\/employer\/ext-autohaus-tabor-gmbh\/"},"_links":{"self":[{"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/job_listing\/543902","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/job_listing"}],"about":[{"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/users\/29531"}],"replies":[{"embeddable":true,"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/comments?post=543902"}],"version-history":[{"count":1,"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/job_listing\/543902\/revisions"}],"predecessor-version":[{"id":543903,"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/job_listing\/543902\/revisions\/543903"}],"wp:attachment":[{"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/media?parent=543902"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/job_listing_type?post=543902"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/job_listing_category?post=543902"},{"taxonomy":"job_listing_location","embeddable":true,"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/job_listing_location?post=543902"},{"taxonomy":"job_listing_tag","embeddable":true,"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/job_listing_tag?post=543902"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}