{"id":520459,"date":"2026-06-12T00:05:00","date_gmt":"2026-06-12T00:05:00","guid":{"rendered":"https:\/\/driver-work.com\/job\/conducteur-spl-fma-national-h-f\/"},"modified":"2026-06-12T00:05:00","modified_gmt":"2026-06-12T00:05:00","slug":"job-518749","status":"publish","type":"job_listing","link":"https:\/\/driver-work.com\/fr\/job\/job-518749\/","title":{"rendered":"CONDUCTEUR SPL FMA NATIONAL H\/F"},"content":{"rendered":"<div id=\"shema_offre3\">\n<div>\n<p>\n                            <span><\/p>\n<p>Vous souhaitez un poste sur le long terme et rejoindre une \u00e9quipe dynamique,<br \/>Vous \u00eates motiv\u00e9(e) et consciencieux(se).<\/p>\n<p><span><b><i>Alors<br \/>\nrejoignez-nous !<\/i><\/b><\/span><\/p>\n<p>Nous recrutons pour notre service<br \/>\nTransport Public un <strong>conducteur<\/strong> permis CE. Avec un tracteur attitr\u00e9 et <b>une<br \/>\nsemi-remorque \u00e0 fond mouvant<\/b>, vous r\u00e9alisez des transports \u00e0 la demande<br \/>\navec des <b>d\u00e9couch\u00e9s \u00e0 la semaine<\/b>. Vous vous d\u00e9placez sur l&rsquo;ensemble du<br \/>\nterritoire national avec des passages de fronti\u00e8res possibles. L&rsquo;activit\u00e9<br \/>\ns&rsquo;\u00e9tend principalement du lundi au vendredi, des retours sont possibles les<br \/>\nsamedis.<\/p>\n<p>Prise de service sur notre parc \u00e0<b>\u00a0Bourg en Bresse<\/b><\/p>\n<p><b>Profil souhait\u00e9<\/b><\/p>\n<p><b><span>\u00a0<\/span><\/b>Vous poss\u00e9dez\u00a0: <\/p>\n<p>&#8211; les documents n\u00e9cessaires \u00e0 la<br \/>\nconduite (<b>Permis CE<\/b>\/ FIMO\/FCO\/ Carte conducteur)<\/p>\n<p>&#8211; <b>une exp\u00e9rience significative en<br \/>\nfond mouvant<\/b><\/p>\n<p>&#8211; un bon relationnel,<\/p>\n<p>Vous travaillez en autonomie et<br \/>\ndans les r\u00e8gles de s\u00e9curit\u00e9,<\/p>\n<p><b>Conditions :<\/b><\/p>\n<p>&#8211; Temps de service mensuel garanti<br \/>\n: <b>200h pour les conducteurs exp\u00e9riment\u00e9s <\/b>et <b>186h<\/b> pendant <b>1 an pour les<br \/>\nprofils d\u00e9butants en d\u00e9part \u00e0 la semaine<\/b><\/p>\n<p>&#8211; taux horaire en fonction du<br \/>\nprofil et de l&rsquo;exp\u00e9rience<a><br \/><\/a><\/p>\n<p><span><b><i>\u00a0Travailler pour le Groupe Cayon c\u2019est <\/i><\/b>:<br \/>* Avoir acc\u00e8s au CSE et ses avantages<br \/>* Des bons d\u2019achat pour No\u00ebl, ch\u00e8ques vacances, tarifs r\u00e9duits \u2026<br \/>* Participation aux b\u00e9n\u00e9fices<br \/>* Mutuelle entreprise<\/span><\/p>\n<p><span><b><i>Alors<br \/>\nn\u2019attendez plus et rejoignez nos \u00e9quipes. Pour plus d&rsquo;informations,<br \/>\nappelez-nous au 0385417880.\u00a0<\/i><\/b><\/span><\/p>\n<p><\/span>\n                        <\/p>\n<\/p><\/div>\n<\/p><\/div>\n","protected":false},"author":26079,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","job_listing_type":[],"job_listing_category":[],"job_listing_location":[],"job_listing_tag":[],"class_list":["post-520459","job_listing","type-job_listing","status-publish","hentry"],"aioseo_notices":[],"metas":{"_job_country_picker":"ChIJMVd4MymgVA0R99lHx5Y__Ws","_job_required_languages":"","_job_driving_license":"","_job_we_offer":"","_job_type":[],"_job_salary_type":"","_job_salary":"","_job_experience":"","_job_video_url":"","_job_photos":"","_job_application_deadline_date":"","_job_employer_name":"GROUPE CAYON","_job_employer_url":"https:\/\/driver-work.com\/fr\/employer\/ext-groupe-cayon-2\/"},"_links":{"self":[{"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/job_listing\/520459","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/job_listing"}],"about":[{"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/users\/26079"}],"replies":[{"embeddable":true,"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/comments?post=520459"}],"version-history":[{"count":1,"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/job_listing\/520459\/revisions"}],"predecessor-version":[{"id":520460,"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/job_listing\/520459\/revisions\/520460"}],"wp:attachment":[{"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/media?parent=520459"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/job_listing_type?post=520459"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/job_listing_category?post=520459"},{"taxonomy":"job_listing_location","embeddable":true,"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/job_listing_location?post=520459"},{"taxonomy":"job_listing_tag","embeddable":true,"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/job_listing_tag?post=520459"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}