{"id":491285,"date":"2026-05-31T00:06:27","date_gmt":"2026-05-31T00:06:27","guid":{"rendered":"https:\/\/driver-work.com\/job\/ce-vrachtwagenchauffeur-nacht-pendelritten-walkingfloor\/"},"modified":"2026-05-31T00:06:27","modified_gmt":"2026-05-31T00:06:27","slug":"job-491285","status":"publish","type":"job_listing","link":"https:\/\/driver-work.com\/fr\/job\/job-491285\/","title":{"rendered":"CE vrachtwagenchauffeur | Nacht | Pendelritten | Walkingfloor"},"content":{"rendered":"<p>Wij zijn 24\/7 drive. Het is onze drive om werkgevers en werknemers in de transport en logistieke wereld bij elkaar te brengen. Dit doen we 24 uur per dag, 7 dagen per week. Met vestigingen door heel Europa zijn we gespecialiseerd in de werving, selectie en uitzending van vakkundige vrachtwagenchauffeurs, bezorgers, logistiek medewerkers en productiekrachten.<b>Functiebeschrijving<\/b><\/p>\n<p>Als <b>vrachtwagenchauffeur CE<\/b> rijd je pendelritten tussen distributiecentra van vaste klanten. Je werkt in de nacht en zorgt dat alles veilig en op tijd wordt afgeleverd.<\/p>\n<ul>\n<li>Starttijd tussen <b>17:00 en 18:00 uur<\/b>, diensten van <b>10 tot 12 uur<\/b><\/li>\n<li>Werken volgens een <b>vast rooster<\/b>, inclusief nacht- en weekenddiensten<\/li>\n<li>Rijden met <b>wisselend materieel<\/b>, zoals trekker-oplegger of walking floor<\/li>\n<li>Vervoeren van <b>voornamelijk pallets<\/b> tussen distributiecentra<\/li>\n<li><b>Zelf laden en lossen<\/b> met een EPT<\/li>\n<li>Nauwelijks <b>fysieke belasting<\/b><\/li>\n<li>Zorgen voor correcte levering en <b>kort klantcontact<\/b> op locatie<\/li>\n<li>Standplaats: <b>Oosteind<\/b><\/li>\n<\/ul>\n<p><b>Functie-eisen<\/b><\/p>\n<ul>\n<li><b>Rijbewijs CE<\/b>, geldige <b>Code 95<\/b> en bestuurderskaart<\/li>\n<li>Goede beheersing van de <b>Nederlandse taal<\/b><\/li>\n<li>Bereidheid om <b>nacht- en weekenddiensten<\/b> te werken<\/li>\n<li>Zelfstandige en verantwoordelijke werkhouding<\/li>\n<li>Veilig werken en naleven van <b>verkeers- en veiligheidsregels<\/b><\/li>\n<\/ul>\n<p>Klaar voor een zelfstandige baan in de nacht met veel rijdende uren en modern materieel? Solliciteer direct en ga aan de slag via 24\/7 drive.<\/p>\n<p><b>Arbeidsvoorwaarden<\/b><\/p>\n<ul>\n<li>Salaris volgens TLN CAO schaal D: <b>\u20ac 2.893 tot \u20ac 3.520,40 bruto per maand<\/b> (o.b.v. 40 uur)<\/li>\n<li>Toeslagen: <b>overwerk 130%<\/b>, <b>zaterdag 150%<\/b>, <b>zondag 200%<\/b><\/li>\n<li><b>Reiskostenvergoeding \u20ac0,23 per km vanaf 10 km<\/b><\/li>\n<li><b>Goede pensioenregeling gelijk aan TLN CAO<\/b><\/li>\n<li><b>24 vakantiedagen + leeftijdsdagen + 8% vakantiegeld<\/b><\/li>\n<li><b>\u20ac0,83 netto vergoeding per uur<\/b><\/li>\n<li>Mogelijkheid om je <b>LZV-certificaat<\/b> te behalen bij goed functioneren<\/li>\n<li>Werken met <b>modern en goed onderhouden materieel<\/b><\/li>\n<li><b>Sparen voor 24\/7 drive kleding en merchandise<\/b><\/li>\n<li>Veel <b>vrijheid en zelfstandigheid<\/b> in je werk<\/li>\n<li><b>Werkzekerheid<\/b> bij een stabiele opdrachtgever<\/li>\n<\/ul>\n","protected":false},"author":27892,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","job_listing_type":[67],"job_listing_category":[],"job_listing_location":[],"job_listing_tag":[],"class_list":["post-491285","job_listing","type-job_listing","status-publish","hentry","job_listing_type-full-time"],"aioseo_notices":[],"metas":{"_job_country_picker":"ChIJu-SH28MJxkcRnwq9_851obM","_job_required_languages":"","_job_driving_license":"","_job_we_offer":"","_job_type":{"67":"Full time work"},"_job_salary_type":"","_job_salary":"$2893 - $3520","_job_experience":"","_job_video_url":"","_job_photos":"","_job_application_deadline_date":"","_job_employer_name":"24\/7 drive","_job_employer_url":"https:\/\/driver-work.com\/fr\/employer\/ext-24-7-drive\/"},"_links":{"self":[{"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/job_listing\/491285","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/job_listing"}],"about":[{"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/users\/27892"}],"replies":[{"embeddable":true,"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/comments?post=491285"}],"version-history":[{"count":1,"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/job_listing\/491285\/revisions"}],"predecessor-version":[{"id":491286,"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/job_listing\/491285\/revisions\/491286"}],"wp:attachment":[{"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/media?parent=491285"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/job_listing_type?post=491285"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/job_listing_category?post=491285"},{"taxonomy":"job_listing_location","embeddable":true,"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/job_listing_location?post=491285"},{"taxonomy":"job_listing_tag","embeddable":true,"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/job_listing_tag?post=491285"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}