{"id":487155,"date":"2026-05-27T00:11:42","date_gmt":"2026-05-27T00:11:42","guid":{"rendered":"https:\/\/driver-work.com\/job\/lkw-fahrer-m-w-d\/"},"modified":"2026-05-27T00:11:42","modified_gmt":"2026-05-27T00:11:42","slug":"job-487155","status":"publish","type":"job_listing","link":"https:\/\/driver-work.com\/fr\/job\/job-487155\/","title":{"rendered":"LKW-Fahrer (m\/w\/d)"},"content":{"rendered":"<p>Wir sind die Unsichtbaren&#8230;<\/p>\n<p>Stell dir vor: DU als Teammitglied bei der UDO GmbH &#8211; dem Full-Service-Dienstleister des Universit\u00e4tsklinikums T\u00fcbingen!<\/p>\n<p>Komm ins Team Logistik!<\/p>\n<p>LKW-Fahrer (m\/w\/d)<\/p>\n<p>Stellennummer 110452 in DE-T\u00fcbingen [72072] () &#8211; Vollzeit<\/p>\n<p>Bei uns hast Du systemrelevante Aufgaben:<\/p>\n<p>&#8211; Du f\u00e4hrst nicht nur, Du tr\u00e4gst Verantwortung &#8211; unsere Speisen und Materialien kommen sicher ans Ziel<br \/>\n&#8211; Du tr\u00e4gst dazu bei, dass das Universit\u00e4tsklinikum immer bestens versorgt ist<br \/>\n&#8211; Du beh\u00e4ltst den \u00dcberblick und sorgst daf\u00fcr, dass die Ladung immer ordentlich verstaut ist<br \/>\n&#8211; Du h\u00e4ltst unsere LKWs in Top-Form. Regelm\u00e4\u00dfige Pflege und Wartung geh\u00f6ren zu deinem Job<br \/>\n&#8211; Vor jeder Abfahrt pr\u00fcfst Du alles bis ins kleinste Detail- Sicherheit geht bei dir vor<\/p>\n<p>So \u00fcberzeugst Du uns:<\/p>\n<p>&#8211; Du hast idealerweise schon Berufserfahrung in einer vergleichbaren Position<br \/>\n&#8211; Du hast einen F\u00fchrerschein der Klasse CE inkl. g\u00fcltiger Module mit Eintrag der Schl\u00fcsselzahl 95<br \/>\n&#8211; Du f\u00e4hrst nicht einfach nur &#8211; Du f\u00e4hrst sicher und verantwortungsvoll<br \/>\n&#8211; Du \u00fcberzeugst uns durch deine Einsatzbereitschaft und deine zuverl\u00e4ssige Arbeitsweise<br \/>\n&#8211; Du zeigst die Bereitschaft Wochenendarbeit zu leisten, f\u00fcr die Du eine attraktive Verg\u00fctung erh\u00e4ltst<\/p>\n<p>&#8230;Siehst Du uns jetzt?!<\/p>\n<p>Aufgabe:<\/p>\n<p>&#8211; Vielf\u00e4ltige T\u00e4tigkeit: Bei uns ist immer was los \u2013 Langeweile? Gibt\u2019s nicht!<br \/>\n&#8211; Arbeit mit Sinn: Du arbeitest jeden Tag in einem systemrelevanten Umfeld<\/p>\n<p>Team &amp; Gesundheit:<\/p>\n<p>&#8211; Gemeinschaft: Wir sind mehr als ein Team \u2013 wir sind eine starke Community, die zusammenh\u00e4lt und voneinander lernt<br \/>\n&#8211; Unternehmenskultur: Offenheit, Inklusion und Diversit\u00e4t sind uns wichtig. DeineIdeen z\u00e4hlen und wir feiern gerne gemeinsam die Erfolge<br \/>\n&#8211; Umweltfreundlich unterwegs: Bei uns erh\u00e4ltst Du Rabattm\u00f6glichkeiten zum Erwerb von E-Bikes<br \/>\n&#8211; Fit bleiben: Wir unterst\u00fctzen Firmenfitness mit dem Partner MC Shape<\/p>\n<p>Bezahlung und Arbeitszeit:<\/p>\n<p>&#8211; Familie und Beruf: Wir bieten dir geregelte Arbeitszeiten und flexible Arbeitszeitmodelle<br \/>\n&#8211; Sicherer Job: Deine Arbeit bei uns ist langfristig und sicher<br \/>\n&#8211; Anerkennung: Dein Beitrag ist wertvoll und wird angemessen honoriert<\/p>\n<p>Mobilit\u00e4t und weitere Benefits:<\/p>\n<p>&#8211; Perfekt vorbereitet: Wir stellen dir kostenfreie Arbeitskleidung zur Verf\u00fcgung<br \/>\n&#8211; Verpflegung: Bei uns erh\u00e4ltst Du ein nicht endendes Kontingent an Kaffee, Tee und Kaltgetr\u00e4nken. Du kannst t\u00e4glich frisches Essen in der Betriebskantine genie\u00dfen<br \/>\n&#8211; Mitarbeiterverg\u00fcnstigungen: Du erh\u00e4ltst Rabattm\u00f6glichkeiten beim Ticket f\u00fcr die \u00f6ffentlichen Verkehrsmittel und exklusive Verg\u00fcnstigungen bei ausgew\u00e4hlten Partnern<\/p>\n<p>Inklusion wird bei uns gro\u00dfgeschrieben: Wir freuen uns besonders \u00fcber Bewerbungen von Schwerbehinderten und Menschen mit Gleichstellung.<\/p>\n<p>U.D.O. GmbH<br \/>\nPersonalabteilung<br \/>\nAlte Landstra\u00dfe 54<br \/>\nD-72072 T\u00fcbingen<br \/>\njobs@udo-tuebingen.de<br \/>\nwww.udo-tuebingen.de<\/p>\n","protected":false},"author":14127,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","job_listing_type":[481],"job_listing_category":[],"job_listing_location":[],"job_listing_tag":[],"class_list":["post-487155","job_listing","type-job_listing","status-publish","hentry","job_listing_type-full-time-da"],"aioseo_notices":[],"metas":{"_job_country_picker":"ChIJa76xwh5ymkcRW-WRjmtd6HU","_job_required_languages":"","_job_driving_license":"","_job_we_offer":"","_job_type":{"481":"Fuldtidsarbejde"},"_job_salary_type":"","_job_salary":"","_job_experience":"","_job_video_url":"","_job_photos":"","_job_application_deadline_date":"","_job_employer_name":"U.D.O. Universit\u00e4tsklinikum Dienstleistungs- Organisations GmbH","_job_employer_url":"https:\/\/driver-work.com\/fr\/employer\/ext-u-d-o-universitatsklinikum-dienstleistungs-organisations-gmbh\/"},"_links":{"self":[{"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/job_listing\/487155","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/job_listing"}],"about":[{"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/users\/14127"}],"replies":[{"embeddable":true,"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/comments?post=487155"}],"version-history":[{"count":1,"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/job_listing\/487155\/revisions"}],"predecessor-version":[{"id":487156,"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/job_listing\/487155\/revisions\/487156"}],"wp:attachment":[{"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/media?parent=487155"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/job_listing_type?post=487155"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/job_listing_category?post=487155"},{"taxonomy":"job_listing_location","embeddable":true,"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/job_listing_location?post=487155"},{"taxonomy":"job_listing_tag","embeddable":true,"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/job_listing_tag?post=487155"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}