{"id":481986,"date":"2026-05-22T00:16:42","date_gmt":"2026-05-22T00:16:42","guid":{"rendered":"https:\/\/driver-work.com\/job\/chauffeur-spl-f-h\/"},"modified":"2026-05-22T00:16:42","modified_gmt":"2026-05-22T00:16:42","slug":"job-481986","status":"publish","type":"job_listing","link":"https:\/\/driver-work.com\/fr\/job\/job-481986\/","title":{"rendered":"Chauffeur SPL F\/H"},"content":{"rendered":"<div id=\"shema_offre3\">\n<div>\n<p>\n                            <span><\/p>\n<h2>Description de l&rsquo;entreprise<\/h2>\n<\/p>\n<p>Fond\u00e9e en 1958 par Louis Le Saint et actuellement bas\u00e9e \u00e0 Guipavas, l\u2019entreprise Le Saint est sp\u00e9cialiste dans la distribution de fruits et l\u00e9gumes dans tout le Finist\u00e8re, en Bretagne.<\/p>\n<p>Le Saint est \u00e9galement certifi\u00e9 \u00ab Jouons Local \u00bb, ce qui d\u00e9montre l\u2019engagement de l\u2019entreprise de favoriser les producteurs locaux. En effet, les produits sont r\u00e9colt\u00e9s quelques heures avant d\u2019\u00eatre achemin\u00e9s vers l\u2019entrep\u00f4t puis livr\u00e9s aux diff\u00e9rents clients !<\/p>\n<p>De plus, l\u2019\u00e9tablissement dispose d\u2019une m\u00fbrisserie dans la commune de Bourg-Blanc, afin de proposer des fruits \u00e0 diff\u00e9rents stades de maturit\u00e9.<\/p>\n<\/p>\n<h2>Description du poste<\/h2>\n<p><\/p>\n<p>Vous souhaitez \u00eatre acteur d&rsquo;une <strong>aventure <\/strong>humaine, conviviale et engag\u00e9e ?<\/p>\n<p>Dans le cadre de notre d\u00e9veloppement, nous recherchons un(e) <strong>Chauffeur SPL<\/strong> pour renforcer notre \u00e9quipe logistique.<\/p>\n<\/p>\n<p><strong>Vos missions principales :<\/strong><\/p>\n<ul>\n<li>\n<p><strong>Charger le v\u00e9hicule<\/strong> en respectant le plan de tourn\u00e9e et les consignes de transport<\/p>\n<\/li>\n<li>\n<p><strong>Assurer les livraisons<\/strong> aupr\u00e8s des clients selon la feuille de route, dans le <strong>respect des d\u00e9lais et horaires de livraison<\/strong><\/p>\n<\/li>\n<li>\n<p>Veiller au maintien de la qualit\u00e9 des produits transport\u00e9s (respect de la cha\u00eene qualit\u00e9, manipulation, conditions de transport)<\/p>\n<\/li>\n<li>\n<p><strong>Contr\u00f4ler la conformit\u00e9 des marchandises<\/strong> lors de la livraison (quantit\u00e9, \u00e9tat, r\u00e9f\u00e9rences)<\/p>\n<\/li>\n<li>\n<p><strong>Appliquer les r\u00e8gles de s\u00e9curit\u00e9<\/strong>, ainsi que les proc\u00e9dures et exigences du syst\u00e8me qualit\u00e9<\/p>\n<\/li>\n<li>\n<p><strong>Veiller \u00e0 la propret\u00e9<\/strong> et au bon <strong>entretien <\/strong>du v\u00e9hicule mis \u00e0 disposition<\/p>\n<\/li>\n<li>\n<p><strong>Repr\u00e9senter l\u2019entreprise<\/strong> aupr\u00e8s de la client\u00e8le avec professionnalisme et sens du service<\/p>\n<\/li>\n<\/ul>\n<p> <strong>Localisation : Guipavas (29)<\/strong><br \/> <strong>Type de<\/strong> <strong>Contrat :<\/strong> CDD 6 mois<br \/>\u23f3 <strong>Temps plein<\/strong><\/p>\n<p> <strong>Horaires <\/strong>: 04H00-&gt;12H00 du mercredi au samedi 15H00-&gt;00H00 le dimanche, repos le lundi et mardi<\/p>\n<h4><strong>Ce que nous vous offrons<\/strong><\/h4>\n<p> <strong>R\u00e9mun\u00e9ration<\/strong> selon votre niveau de <strong>comp\u00e9tences <\/strong>et votre <strong>exp\u00e9rience<\/strong><br \/> <strong>Des avantages attractifs <\/strong><\/p>\n<ul>\n<li>Mutuelle d\u2019entreprise<\/li>\n<li>Acc\u00e8s \u00e0 des achats de produits du r\u00e9seau \u00e0 des prix pr\u00e9f\u00e9rentiels<\/li>\n<li>Avantages CSE<\/li>\n<li>Accompagnement par un <strong>conducteur<\/strong> r\u00e9f\u00e9rent lors de votre int\u00e9gration<\/li>\n<li>Possibilit\u00e9s d\u2019\u00e9volution interne et de mobilit\u00e9 g\u00e9ographique<\/li>\n<\/ul>\n<p><\/p>\n<p> <strong>Permis EC <\/strong>+ <strong>FIMO\/FCO<\/strong> + <strong>carte conducteur<\/strong> <strong>en cours de validit\u00e9<\/strong><\/p>\n<p> Exp\u00e9rience en transport de marchandises, id\u00e9alement en alimentaire est un plus<\/p>\n<ul>\n<li>\n<p>Sens du service, ponctualit\u00e9 et autonomie<\/p>\n<\/li>\n<li>\n<p>Bon relationnel et esprit d\u2019\u00e9quipe<\/p>\n<\/li>\n<\/ul>\n<p>Contrat : CDD, Temps plein<\/span>\n                        <\/p>\n<\/p><\/div>\n<\/p><\/div>\n","protected":false},"author":25757,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","job_listing_type":[],"job_listing_category":[],"job_listing_location":[],"job_listing_tag":[],"class_list":["post-481986","job_listing","type-job_listing","status-publish","hentry"],"aioseo_notices":[],"metas":{"_job_country_picker":"ChIJMVd4MymgVA0R99lHx5Y__Ws","_job_required_languages":"","_job_driving_license":"","_job_we_offer":"","_job_type":[],"_job_salary_type":"","_job_salary":"","_job_experience":"","_job_video_url":"","_job_photos":"","_job_application_deadline_date":"","_job_employer_name":"R\u00e9seau Le Saint","_job_employer_url":"https:\/\/driver-work.com\/fr\/employer\/ext-reseau-le-saint\/"},"_links":{"self":[{"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/job_listing\/481986","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/job_listing"}],"about":[{"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/users\/25757"}],"replies":[{"embeddable":true,"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/comments?post=481986"}],"version-history":[{"count":1,"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/job_listing\/481986\/revisions"}],"predecessor-version":[{"id":481987,"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/job_listing\/481986\/revisions\/481987"}],"wp:attachment":[{"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/media?parent=481986"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/job_listing_type?post=481986"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/job_listing_category?post=481986"},{"taxonomy":"job_listing_location","embeddable":true,"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/job_listing_location?post=481986"},{"taxonomy":"job_listing_tag","embeddable":true,"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/job_listing_tag?post=481986"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}