{"id":438051,"date":"2026-04-29T15:49:01","date_gmt":"2026-04-29T15:49:01","guid":{"rendered":"https:\/\/driver-work.com\/job\/chauffeur-pl-h-f\/"},"modified":"2026-04-29T15:49:01","modified_gmt":"2026-04-29T15:49:01","slug":"job-438051","status":"publish","type":"job_listing","link":"https:\/\/driver-work.com\/fr\/job\/job-438051\/","title":{"rendered":"Chauffeur pl H\/F"},"content":{"rendered":"<p><strong>Pourquoi pas vous ! <\/strong><\/p>\n<p><strong>PROMAN BERGERAC recherche pour l&rsquo;un de ses clients des CHAUFFEURS PL\/SPL (H\/F)<\/strong><\/p>\n<p>Vous conduisez le camion de l&rsquo;entreprise et \u00eatre responsable de l&rsquo;acheminement des engins, du mat\u00e9riel et des mati\u00e8res premi\u00e8res sur chantier.<\/p>\n<p>Vous assurez le chargement \/ d\u00e9chargement de votre camion,<\/p>\n<p>En parall\u00e8le de la conduite, vous aidez les \u00e9quipes au sol sur le chantier, si besoin et vous devez veiller \u00e0 l&rsquo;entretien du camion.<\/p>\n<p><\/p>\n<p>Pour plus d&rsquo;offres d&#8217;emploi, t\u00e9l\u00e9chargez notre application myPROMAN int\u00e9rimaires sur App Store ou Google Play.<\/p>\n<p><\/p>\n<p>Disponible imm\u00e9diatement, vous justifiez \u00e0 ce jour d&rsquo;une premi\u00e8re exp\u00e9rience significative sur le m\u00eame type de poste.<\/p>\n<p>PERMIS, FIMO et Carte Conducteur \u00e0 jour.<\/p>\n<p><strong>Salaire :<\/strong> Selon profil + zone + panier + 10% de fin de mission + 10% de cong\u00e9s pay\u00e9s<\/p>\n<p><strong>Horaires :<\/strong> Journ\u00e9e<\/p>\n<p><strong>Vous vous reconnaissez dans cette offre ? Postulez d\u00e8s maintenant !!<\/strong><\/p>\n<p><\/p>\n<p>Tous nos postes sont ouverts aux personnes en situation de handicap.<\/p>\n","protected":false},"author":25873,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","job_listing_type":[475],"job_listing_category":[],"job_listing_location":[],"job_listing_tag":[],"class_list":["post-438051","job_listing","type-job_listing","status-publish","hentry","job_listing_type-full-time-fr"],"aioseo_notices":[],"metas":{"_job_country_picker":"ChIJMVd4MymgVA0R99lHx5Y__Ws","_job_required_languages":"","_job_driving_license":"","_job_we_offer":"","_job_type":{"475":"Travail \u00e0 temps plein"},"_job_salary_type":"","_job_salary":"","_job_experience":"","_job_video_url":"","_job_photos":"","_job_application_deadline_date":"","_job_employer_name":"Proman","_job_employer_url":"https:\/\/driver-work.com\/fr\/employer\/ext-proman-2\/"},"_links":{"self":[{"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/job_listing\/438051","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/job_listing"}],"about":[{"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/users\/25873"}],"replies":[{"embeddable":true,"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/comments?post=438051"}],"version-history":[{"count":0,"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/job_listing\/438051\/revisions"}],"wp:attachment":[{"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/media?parent=438051"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/job_listing_type?post=438051"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/job_listing_category?post=438051"},{"taxonomy":"job_listing_location","embeddable":true,"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/job_listing_location?post=438051"},{"taxonomy":"job_listing_tag","embeddable":true,"href":"https:\/\/driver-work.com\/fr\/wp-json\/wp\/v2\/job_listing_tag?post=438051"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}