{"id":564184,"date":"2026-07-15T00:12:05","date_gmt":"2026-07-15T00:12:05","guid":{"rendered":"https:\/\/driver-work.com\/job\/lkw-fahrer-m-w-d\/"},"modified":"2026-07-15T00:12:05","modified_gmt":"2026-07-15T00:12:05","slug":"job-564184","status":"publish","type":"job_listing","link":"https:\/\/driver-work.com\/de\/job\/job-564184\/","title":{"rendered":"LKW-Fahrer (m\/w\/d)"},"content":{"rendered":"<p>Starte jetzt deine Tour in einen sicheren Job.<br \/>\nDu bist Profi am Steuer und suchst einen neuen Job? F\u00fcr unseren Kunden aus der Glasbranche bieten wir dir als Lagerist und LKW-Fahrer (m\/w\/d) am Standort Warendorf im Rahmen der Arbeitnehmer\u00fcberlassung einen unbefristeten Arbeitsvertrag. Piening Personal steht f\u00fcr Verl\u00e4sslichkeit, pers\u00f6nliche Betreuung und erstklassigen Service werde Teil eines starken Teams.<\/p>\n<p>Deine Benefits:<br \/>\n \u2022 Unbefristeter Arbeitsvertrag bei Piening Personal<br \/>\n \u2022 Faire Bezahlung nach GVP-Tarifvertrag<br \/>\n \u2022 Urlaubs- und Weihnachtsgeld on top<br \/>\n \u2022 Pers\u00f6nliche Betreuung und schnelle R\u00fcckmeldung<br \/>\n \u2022 Kostenlose Arbeitskleidung<br \/>\n \u2022 Mitarbeiter werben Mitarbeiter Pr\u00e4mien<br \/>\n \u2022 Corporate Benefits bei adidas, Sky, apple, Weg. de u. v. m.<\/p>\n<p>Deine Aufgaben:<br \/>\n \u2022 Mitarbeit im Versand, Kommissionierung und Verpackung<br \/>\n \u2022 Wareneingangspr\u00fcfungen durchf\u00fchren<br \/>\n \u2022 Be- und Entladen von LKWs<br \/>\n \u2022 Bedienen von Hallenkran, Ladekran und Staplern<br \/>\n \u2022 Auslieferung von Isolier- und Sicherheitsglas auf Transportgestellen oder Kisten in Tagestouren<\/p>\n<p>Dein Profil:<br \/>\n \u2022 Wir suchen LKW-Fahrer (m\/w\/d), Berufskraftfahrer (m\/w\/d) oder Kraftfahrer (m\/w\/d)<br \/>\n \u2022 F\u00fchrerschein Klasse CE und Kennzeichnung 95 mit Modul sowie g\u00fcltige Fahrerkarte<br \/>\n \u2022 Berufserfahrung als Fahrer w\u00fcnschenswert<br \/>\n \u2022 Zuverl\u00e4ssigkeit, Sorgfalt und Verantwortungsbewusstsein zeichnen dich aus<br \/>\n \u2022 Motivation und Engagement bringst du mit ins Team und auf die Stra\u00dfe<\/p>\n<p>Sichere dir deinen Job als LKW-Fahrer (m\/w\/d) in Warendorf.<br \/>\nJetzt bewerben, durchstarten und gemeinsam mit uns die Zukunft bewegen! Jeder Arbeitsplatz in unserem Unternehmen kann f\u00fcr einen Menschen mit Behinderungen je nach Art der Beeintr\u00e4chtigung geeignet sein. Werde Teil unseres Teams wir freuen uns auf dich.<\/p>\n","protected":false},"author":17776,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","job_listing_type":[169],"job_listing_category":[],"job_listing_location":[],"job_listing_tag":[],"class_list":["post-564184","job_listing","type-job_listing","status-publish","hentry","job_listing_type-full-time-de"],"aioseo_notices":[],"metas":{"_job_country_picker":"ChIJa76xwh5ymkcRW-WRjmtd6HU","_job_required_languages":"","_job_driving_license":"","_job_we_offer":"","_job_type":{"169":"Vollzeitjob"},"_job_salary_type":"","_job_salary":"","_job_experience":"","_job_video_url":"","_job_photos":"","_job_application_deadline_date":"","_job_employer_name":"Piening GmbH (M\u00fcnster)","_job_employer_url":"https:\/\/driver-work.com\/de\/employer\/ext-piening-gmbh-munster\/"},"_links":{"self":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing\/564184","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing"}],"about":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/users\/17776"}],"replies":[{"embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/comments?post=564184"}],"version-history":[{"count":1,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing\/564184\/revisions"}],"predecessor-version":[{"id":564185,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing\/564184\/revisions\/564185"}],"wp:attachment":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/media?parent=564184"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_type?post=564184"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_category?post=564184"},{"taxonomy":"job_listing_location","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_location?post=564184"},{"taxonomy":"job_listing_tag","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_tag?post=564184"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}