{"id":563919,"date":"2026-07-14T00:15:24","date_gmt":"2026-07-14T00:15:24","guid":{"rendered":"https:\/\/driver-work.com\/job\/chauffeur-spl-h-f\/"},"modified":"2026-07-14T00:15:24","modified_gmt":"2026-07-14T00:15:24","slug":"job-563919","status":"publish","type":"job_listing","link":"https:\/\/driver-work.com\/de\/job\/job-563919\/","title":{"rendered":"Chauffeur SPL* H\/F"},"content":{"rendered":"<div id=\"shema_offre3\">\n<div>\n<p>\n                            <span><\/p>\n<p>Tu souhaites combiner conduite longue distance et transport frigorifique avec rigueur et professionnalisme ?<\/p>\n<p> Nous recherchons un(e) <strong>Chauffeur SPL Frigo<\/strong> motiv\u00e9(e) pour rejoindre une entreprise reconnue sur <strong>Chalon-sur-Sa\u00f4ne<\/strong>.<\/p>\n<p>Vos missions<\/p>\n<\/p>\n<p>Tes missions :<\/p>\n<p><\/p>\n<p>Conduire un <strong>SPL Frigo<\/strong> pour transporter des marchandises sensibles \u00e0 la temp\u00e9rature,<\/p>\n<p>V\u00e9rifier et maintenir la cha\u00eene du froid tout au long du trajet,<\/p>\n<p>Charger et d\u00e9charger les produits en toute s\u00e9curit\u00e9,<\/p>\n<p>Effectuer les contr\u00f4les du v\u00e9hicule et signaler toute anomalie,<\/p>\n<p>Tenir \u00e0 jour les documents de transport et respecter les proc\u00e9dures internes,<\/p>\n<p>Respecter les r\u00e8gles de s\u00e9curit\u00e9 routi\u00e8re et d&#8217;hygi\u00e8ne..<\/p>\n<p><\/span><\/p>\n<p>Pr\u00e9-requis<\/p>\n<\/p>\n<p>Permis <strong>C\/CE<\/strong>, <strong>FIMO\/FCO<\/strong> et carte <strong>conducteur<\/strong> \u00e0 jour,<\/p>\n<p>Exp\u00e9rience souhait\u00e9e en transport frigorifique SPL,<\/p>\n<p>Rigueur, autonomie et sens du service client,<\/p>\n<p>Organisation et ponctualit\u00e9,<\/p>\n<p>Profil recherch\u00e9<\/p>\n<\/p>\n<p>\ud83d\udd54 Prise de poste t\u00f4t le matin (selon planning)<\/p>\n<p>\ud83d\ude9b Mission en <strong>r\u00e9gional<\/strong> (retour chaque soir \u00e0 domicile)<\/p>\n<p>\u2744\ufe0f Connaissance des proc\u00e9dures de transport frigorifique et respect de la cha\u00eene du froid<\/p>\n<p>Informations compl\u00e9mentaires<\/p>\n<p>Type de contrat : Int\u00e9rim<\/p>\n<p>Temps de travail : Temps plein<\/p>\n<p>Salaire : 13 \u20ac &#8211; 17.5 \u20ac par heure<\/p>\n<p><\/p><\/div>\n<\/p><\/div>\n","protected":false},"author":25878,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","job_listing_type":[],"job_listing_category":[],"job_listing_location":[],"job_listing_tag":[],"class_list":["post-563919","job_listing","type-job_listing","status-publish","hentry"],"aioseo_notices":[],"metas":{"_job_country_picker":"ChIJMVd4MymgVA0R99lHx5Y__Ws","_job_required_languages":"","_job_driving_license":"","_job_we_offer":"","_job_type":[],"_job_salary_type":"","_job_salary":"","_job_experience":"","_job_video_url":"","_job_photos":"","_job_application_deadline_date":"","_job_employer_name":"Aquila Rh","_job_employer_url":"https:\/\/driver-work.com\/de\/employer\/ext-aquila-rh-2\/"},"_links":{"self":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing\/563919","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing"}],"about":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/users\/25878"}],"replies":[{"embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/comments?post=563919"}],"version-history":[{"count":1,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing\/563919\/revisions"}],"predecessor-version":[{"id":563920,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing\/563919\/revisions\/563920"}],"wp:attachment":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/media?parent=563919"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_type?post=563919"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_category?post=563919"},{"taxonomy":"job_listing_location","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_location?post=563919"},{"taxonomy":"job_listing_tag","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_tag?post=563919"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}