{"id":562141,"date":"2026-07-13T00:05:06","date_gmt":"2026-07-13T00:05:06","guid":{"rendered":"https:\/\/driver-work.com\/job\/conducteur-pl-h-f\/"},"modified":"2026-07-13T00:05:06","modified_gmt":"2026-07-13T00:05:06","slug":"job-562141","status":"publish","type":"job_listing","link":"https:\/\/driver-work.com\/de\/job\/job-562141\/","title":{"rendered":"Conducteur PL (H\/F)"},"content":{"rendered":"<p>Vous avez envie de diversifier vos exp\u00e9riences professionnelles, de gagner en libert\u00e9 et en s\u00e9r\u00e9nit\u00e9 ? Vous \u00eates au bon endroit ! Avec nos 190 agences r\u00e9parties sur tous le territoire, nous sommes toujours plus proches de vous. Il y a plein de raisons de donner raison \u00e0 notre int\u00e9rim, d\u00e9couvrez l&#8217;int\u00e9rim fait pour vous !<\/p>\n<p>VOS MISSIONS :<\/p>\n<p>Vous recherchez un emploi ? Faites confiances \u00e0 nos diff\u00e9rences ! R.A.S Int\u00e9rim, r\u00e9seau d&#8217;agences d&#8217;emploi de 185 agences, propose des centaines d&#8217;opportunit\u00e9s d&#8217;emploi dans tous les secteurs d&#8217;activit\u00e9, en int\u00e9rim, CDD et CDI.<br \/>L&#8217;agence R.A.S Int\u00e9rim de PONT L&#8217;EVEQUE recherche un(e) Conducteur Permis C H\/F pour un de ses clients. Poste en Int\u00e9rim bas\u00e9 \u00e0 LISIEUX.<\/p>\n<p>Votre mission sera :<\/p>\n<p>Vous devez effectuer la livraison des marchandises en r\u00e9gional.<br \/>Vous aurez en charge 15 \u00e0 20 points de livraisons en fonction du planning quotidien. Vous assurerez le chargement et\/ou d\u00e9chargement de votre v\u00e9hicule \u00e0 l&#8217;aide d&#8217;un transpalette \u00e9lectrique et\/ou manuel.<\/p>\n<p>VOTRE PROFIL :<\/p>\n<p>Vous \u00eates ponctuel, rigoureux, autonome et respectueux de la l\u00e9gislation du transport, vous avez un bon relationnel et le sens des responsabilit\u00e9s.<br \/>Vous \u00eates titulaire d&#8217;un titre professionnel sur porteur, du permis C, de la FIMO, de la carte de qualification conducteur de marchandises en cours de validit\u00e9 et de la carte chronotachygraphe.<br \/>Taux Horaire : 12.527\u20ac<br \/>Repas : 14\u20ac<br \/>Prime : 20\u20ac \/ jour<\/p>\n<p>R\u00e9mun\u00e9ration et avantages :<\/p>\n<p>Taux horaire fixe + 10% de fin de mission + 10% de cong\u00e9s pay\u00e9s<br \/>Primes collective et\/ou individuelle + participation aux b\u00e9n\u00e9fices + CET 5%<br \/>Acompte de paye \u00e0 la semaine si besoin,<br \/>Possibilit\u00e9 d&#8217;int\u00e9gration rapide, de formation et d&#8217;\u00e9volution,<br \/>B\u00e9n\u00e9ficier d&#8217;aides et de services d\u00e9di\u00e9s (mutuelle, logement, garde d&#8217;enfant, d\u00e9placement.)<\/p>\n<p>Les + R.A.S (acc\u00e8s apr\u00e8s avoir effectu\u00e9 910 heures sur les 12 derniers mois au sein d&#8217;une ou plusieurs agences du r\u00e9seau R.A.S Int\u00e9rim)<\/p>\n","protected":false},"author":27072,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","job_listing_type":[169],"job_listing_category":[],"job_listing_location":[],"job_listing_tag":[],"class_list":["post-562141","job_listing","type-job_listing","status-publish","hentry","job_listing_type-full-time-de"],"aioseo_notices":[],"metas":{"_job_country_picker":"ChIJMVd4MymgVA0R99lHx5Y__Ws","_job_required_languages":"","_job_driving_license":"","_job_we_offer":"","_job_type":{"169":"Vollzeitjob"},"_job_salary_type":"","_job_salary":"","_job_experience":"","_job_video_url":"","_job_photos":"","_job_application_deadline_date":"","_job_employer_name":"RAS 1170","_job_employer_url":"https:\/\/driver-work.com\/de\/employer\/ext-ras-1170\/"},"_links":{"self":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing\/562141","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing"}],"about":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/users\/27072"}],"replies":[{"embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/comments?post=562141"}],"version-history":[{"count":1,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing\/562141\/revisions"}],"predecessor-version":[{"id":562142,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing\/562141\/revisions\/562142"}],"wp:attachment":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/media?parent=562141"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_type?post=562141"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_category?post=562141"},{"taxonomy":"job_listing_location","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_location?post=562141"},{"taxonomy":"job_listing_tag","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_tag?post=562141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}