{"id":562049,"date":"2026-07-13T00:08:54","date_gmt":"2026-07-13T00:08:54","guid":{"rendered":"https:\/\/driver-work.com\/job\/lkw-fahrer-m-w-d\/"},"modified":"2026-07-13T00:08:54","modified_gmt":"2026-07-13T00:08:54","slug":"job-562049","status":"publish","type":"job_listing","link":"https:\/\/driver-work.com\/de\/job\/job-562049\/","title":{"rendered":"LKW-Fahrer (m\/w\/d)"},"content":{"rendered":"<p>Wir, die Firma Schmidt Schubert, suchen Dich als LKW-Fahrer (m\/w\/d).<\/p>\n<p>Wir bieten unseren Mitarbeitern bei unserem Kundenbetrieb in Ahaus einen **UNBEFRISTETEN ARBEITSVERTRAG.**<\/p>\n<p>Eine sp\u00e4tere **\u00dcBERNAHME** ist vom Kundenbetrieb gew\u00fcnscht.<\/p>\n<p>Als LKW-Fahrer (m\/w\/d) arbeitest Du in Tagschicht und f\u00e4hrst im Nahverkehr.<\/p>\n<p>## Was wir Dir bieten:<\/p>\n<p>Unsere Philosophie: **PERSONAL IST MEHR WERT**. Bei uns stehen die Menschen im Mittelpunkt, denn unsere Mitarbeiter sind unser wertvollstes Gut.<\/p>\n<p>&#8211; Pers\u00f6nliches Vorabgespr\u00e4ch mit **Ausloten deiner M\u00f6glichkeiten** beim potenziellen Kundenbetrieb<br \/>\n&#8211; \u00dcbernahmem\u00f6glichkeiten beim Kunden<br \/>\n&#8211; Stellung von Arbeitskleidung<br \/>\n&#8211; **Abschlagszahlungen** auf deinen Lohn<br \/>\n&#8211; Equal-Pay ( Gleiches Geld f\u00fcr gleiche Arbeit )<br \/>\n&#8211; **Loakalerie App**, Lokale und \u00fcberregionale Angebote in Form von Rabatten<br \/>\n&#8211; Zahlung der aktuellen Branchenzuschl\u00e4ge und Schichtzulagen **25% Nachtschichtzulage, 50% Sonntagszuschlag, 100% Feiertagszuschlag und 25% \u00dcberstundenzuschlag**<br \/>\n&#8211; Bis zu 30 Tage Urlaub<br \/>\n&#8211; **Unbefristeten Arbeitsvertrag** in Vollzeit<br \/>\n&#8211; Sozialleistungen wie Weihnachts-Urlaubsgeld und betriebliche Altersvorsorge<br \/>\n&#8211; Mitarbeiter **Vermittlungsprovision von 500 \u20ac,** f\u00fcr jeden neuen Schmidt Schubert Mitarbeiter (m\/w\/d)<\/p>\n<p>## Deine Aufgaben:<\/p>\n<p>&#8211; Auslieferung von Waren im Nahverkehr (t\u00e4gliche R\u00fcckkehr)<br \/>\n&#8211; Be- und Entladen inkl. Ladungssicherung<br \/>\n&#8211; Kontrolle von Lieferscheinen und Transportpapieren<br \/>\n&#8211; Abstimmung mit Disposition und Lager<\/p>\n<p>## Das bringst Du mit:<\/p>\n<p>&#8211; F\u00fchrerschein Klasse CE inkl. Schl\u00fcsselzahl 95 und Fahrerkarte<br \/>\n&#8211; Erfahrung im Nahverkehr von Vorteil<br \/>\n&#8211; Zuverl\u00e4ssige und selbstst\u00e4ndige Arbeitsweise<br \/>\n&#8211; Freundliches Auftreten<\/p>\n<p>Du bist mit deinem jetzigen Job unzufrieden oder kommst beruflich nicht weiter?<\/p>\n<p>Dann sende uns deine Bewerbung \u00fcber den **JETZT BEWERBEN** Button oder sende uns eine E-Mail an **[bewerbung@schmidtschubert.com](mailto:bewerbung@schmidtschubert.com).**<\/p>\n<p>Alternativ kannst du uns ein Foto von deinem Lebenslauf an folgende WhatsApp Nummer [**01709053197**](https:\/\/wa.me\/491709053197) senden.<\/p>\n<p> Bei Fragen kannst du uns auch gerne im B\u00fcro anrufen **[02565 \/ 9138030](tel:+4925659138030).**<\/p>\n<p>Wir freuen uns auf jeden Bewerber (m\/w\/d), ob zum Vorstellungsgespr\u00e4ch- oder Beratungsgespr\u00e4ch.<\/p>\n<p>**Besuch uns im Zentrum von Epe und starte mit uns deine neue Berufskarriere.**<\/p>\n<p> [JETZT BEWERBEN!](https:\/\/bewerben.schmidtschubert.com\/Bewerben\/1001Xb636e975-045d-4fad-8a4f-cba753757f0b)<\/p>\n<p>## Stellendetails:<\/p>\n<p>**Arbeitsbeginn:** ab sofort<\/p>\n<p>**Arbeitsort:** Ahaus<\/p>\n<p>**Beruf:** LKW-Fahrer (m\/w\/d)<\/p>\n<p>**Arbeitszeiten:** Tagschicht<\/p>\n<p>**Vertragsart:** unbefristeter Vertrag<\/p>\n<p>## BENEFITS<\/p>\n<p>&#8211; Betriebliche Altersvorsorge<br \/>\n&#8211; Urlaubsgeld<br \/>\n&#8211; Weihnachtsgeld<br \/>\n&#8211; Work-Life-Balance<br \/>\n&#8211; \u00dcbernahmeoption<\/p>\n","protected":false},"author":28015,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","job_listing_type":[67],"job_listing_category":[],"job_listing_location":[],"job_listing_tag":[],"class_list":["post-562049","job_listing","type-job_listing","status-publish","hentry","job_listing_type-full-time"],"aioseo_notices":[],"metas":{"_job_country_picker":"ChIJa76xwh5ymkcRW-WRjmtd6HU","_job_required_languages":"","_job_driving_license":"","_job_we_offer":"","_job_type":{"67":"Full time work"},"_job_salary_type":"","_job_salary":"","_job_experience":"","_job_video_url":"","_job_photos":"","_job_application_deadline_date":"","_job_employer_name":"E.Schmidt GmbH &#038; Co. KG","_job_employer_url":"https:\/\/driver-work.com\/de\/employer\/ext-e-schmidt-gmbh-co-kg-2\/"},"_links":{"self":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing\/562049","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing"}],"about":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/users\/28015"}],"replies":[{"embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/comments?post=562049"}],"version-history":[{"count":1,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing\/562049\/revisions"}],"predecessor-version":[{"id":562050,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing\/562049\/revisions\/562050"}],"wp:attachment":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/media?parent=562049"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_type?post=562049"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_category?post=562049"},{"taxonomy":"job_listing_location","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_location?post=562049"},{"taxonomy":"job_listing_tag","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_tag?post=562049"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}