{"id":561730,"date":"2026-07-12T00:08:42","date_gmt":"2026-07-12T00:08:42","guid":{"rendered":"https:\/\/driver-work.com\/job\/chauffeur-pl-caces-grue-auxiliaire-h-f\/"},"modified":"2026-07-12T00:08:42","modified_gmt":"2026-07-12T00:08:42","slug":"job-561730","status":"publish","type":"job_listing","link":"https:\/\/driver-work.com\/de\/job\/job-561730\/","title":{"rendered":"CHAUFFEUR PL CACES GRUE AUXILIAIRE H\/F"},"content":{"rendered":"<p>Notre agence Camo Emploi de Rennes recrute pour son client, sp\u00e9cialis\u00e9 dans la gestion des d\u00e9chets, un <strong>CHAUFFEUR PL CACES GRUE AUXILIAIRE H\/F<\/strong> afin de renforcer ses \u00e9quipes.<\/p>\n<p>Dans le cadre de votre mission, vous assurez la conduite d&#8217;un poids lourd \u00e9quip\u00e9 d&#8217;une grue auxiliaire sur le secteur du sud-ouest de l&#8217;Ille-et-Vilaine, selon la r\u00e9glementation du transport routier ainsi que des imp\u00e9ratifs de satisfaction de la client\u00e8le en termes de d\u00e9lais et de conformit\u00e9.<\/p>\n<p>Vous \u00eates \u00e9galement amen\u00e9 \u00e0 :<\/p>\n<ul>\n<li>Utiliser la grue auxiliaire pour charger\/d\u00e9charger les mat\u00e9riaux<\/li>\n<li>Assurer le bon entretien du camion et des \u00e9quipements<\/li>\n<li>Effectuer les livraisons ponctuelles sur les diff\u00e9rents sites<\/li>\n<li>Veiller \u00e0 la s\u00e9curit\u00e9 lors des op\u00e9rations de levage<\/li>\n<\/ul>\n<p><\/p>\n","protected":false},"author":25732,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","job_listing_type":[475],"job_listing_category":[],"job_listing_location":[],"job_listing_tag":[],"class_list":["post-561730","job_listing","type-job_listing","status-publish","hentry","job_listing_type-full-time-fr"],"aioseo_notices":[],"metas":{"_job_country_picker":"ChIJMVd4MymgVA0R99lHx5Y__Ws","_job_required_languages":"","_job_driving_license":["C"],"_job_we_offer":"","_job_type":{"475":"Travail \u00e0 temps plein"},"_job_salary_type":"","_job_salary":"","_job_experience":"","_job_video_url":"","_job_photos":"","_job_application_deadline_date":"","_job_employer_name":"CAMO EMPLOI","_job_employer_url":"https:\/\/driver-work.com\/de\/employer\/ext-camo-emploi\/"},"_links":{"self":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing\/561730","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing"}],"about":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/users\/25732"}],"replies":[{"embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/comments?post=561730"}],"version-history":[{"count":1,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing\/561730\/revisions"}],"predecessor-version":[{"id":561731,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing\/561730\/revisions\/561731"}],"wp:attachment":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/media?parent=561730"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_type?post=561730"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_category?post=561730"},{"taxonomy":"job_listing_location","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_location?post=561730"},{"taxonomy":"job_listing_tag","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_tag?post=561730"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}