{"id":560348,"date":"2026-07-11T00:05:03","date_gmt":"2026-07-11T00:05:03","guid":{"rendered":"https:\/\/driver-work.com\/job\/chauffeur-pl-h-f\/"},"modified":"2026-07-11T00:05:03","modified_gmt":"2026-07-11T00:05:03","slug":"job-560348","status":"publish","type":"job_listing","link":"https:\/\/driver-work.com\/de\/job\/job-560348\/","title":{"rendered":"Chauffeur PL H\/F"},"content":{"rendered":"<p>Nous sommes \u00e0 la recherche d&#8217;un Chauffeur PL H\/F pour notre client sp\u00e9cialis\u00e9 dans la location de tout type de mat\u00e9riel pour les professionnels du BTP,(compresseurs, groupes \u00e9lectrog\u00e8nes, nacelles \u00e9l\u00e9vatrices de personnel, chariots automoteurs etc.) situ\u00e9 \u00e0 Saint-Priest. <br \/>Vos missions: <br \/>-Organiser le chargement des marchandises dans le v\u00e9hicule<br \/>-V\u00e9rifier l&#8217;exactitude et la conformit\u00e9 de documents de transport de marchandises<br \/>-Contr\u00f4ler l&#8217;\u00e9tat de fonctionnement d&#8217;un v\u00e9hicule<br \/>-R\u00e9aliser les op\u00e9rations d&#8217;attelage<br \/>-D\u00e9finir un itin\u00e9raire en fonction des consignes de livraison<br \/>-Expliquer au client le fonctionnement du mat\u00e9riel Vous \u00eates titulaire du permis C&nbsp;&nbsp;et de la FIMO.<br \/>Poss\u00e9der les habilitations suivantes est un plus :<br \/>-CACES R 489 cat 3 ou 7 <br \/>-CACES R 486 cat C<br \/>-CACES R 482 cat F\/G<\/p>\n<p>Vous \u00eates rigoureux et aimez l&#8217;autonomie.<br \/>Vous souhaitez travailler dans le monde du BT\u00a8P.<br \/>Alors n&#8217;h\u00e9sitez plus et postulez ! Nous traitons chaque candidature avec soin.<\/p>\n","protected":false},"author":27898,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","job_listing_type":[171],"job_listing_category":[],"job_listing_location":[],"job_listing_tag":[],"class_list":["post-560348","job_listing","type-job_listing","status-publish","hentry","job_listing_type-full-time-uk"],"aioseo_notices":[],"metas":{"_job_country_picker":"ChIJMVd4MymgVA0R99lHx5Y__Ws","_job_required_languages":"","_job_driving_license":"","_job_we_offer":"","_job_type":{"171":"\u041f\u043e\u0432\u043d\u0430 \u0437\u0430\u0439\u043d\u044f\u0442\u0456\u0441\u0442\u044c"},"_job_salary_type":"","_job_salary":"","_job_experience":"","_job_video_url":"","_job_photos":"","_job_application_deadline_date":"","_job_employer_name":"ENTHALPIA RHONE ALPES","_job_employer_url":"https:\/\/driver-work.com\/de\/employer\/ext-enthalpia-rhone-alpes\/"},"_links":{"self":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing\/560348","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing"}],"about":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/users\/27898"}],"replies":[{"embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/comments?post=560348"}],"version-history":[{"count":1,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing\/560348\/revisions"}],"predecessor-version":[{"id":560349,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing\/560348\/revisions\/560349"}],"wp:attachment":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/media?parent=560348"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_type?post=560348"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_category?post=560348"},{"taxonomy":"job_listing_location","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_location?post=560348"},{"taxonomy":"job_listing_tag","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_tag?post=560348"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}