{"id":560090,"date":"2026-07-11T00:10:06","date_gmt":"2026-07-11T00:10:06","guid":{"rendered":"https:\/\/driver-work.com\/job\/lkw-fahrer-m-w-d\/"},"modified":"2026-07-11T00:10:06","modified_gmt":"2026-07-11T00:10:06","slug":"job-560090","status":"publish","type":"job_listing","link":"https:\/\/driver-work.com\/de\/job\/job-560090\/","title":{"rendered":"LKW-Fahrer (m\/w\/d)"},"content":{"rendered":"<p>Im Auftrag der Zukunft \u2013 Wir bewegen Ideen: Aus Wertstoff wird Rohstoff, aus Biomasse Strom, aus Abfall W\u00e4rme, aus Wasser Leben. Mehr als 40.000 Menschen arbeiten bei REMONDIS an ganzheitlichen L\u00f6sungen, die Fortschritt und Ressourcenschonung in Einklang bringen. Gemeinsam, wieder und wieder, weltweit.<\/p>\n<p>LKW-Fahrer (m\/w\/d)<\/p>\n<p>&#8211; Betriebsst\u00e4tte Hetzerath<br \/>\n&#8211; Stellen-Nr.: 180900<\/p>\n<p>Ihre Qualifikationen auf einen Blick<\/p>\n<p>&#8211; Sie besitzen einen F\u00fchrerschein der Klasse CE sowie g\u00fcltige Module nach dem Berufskraftfahrerqualifikationsgesetz<br \/>\n&#8211; Eine g\u00fcltige Fahrerkarte bringen Sie ebenfalls mit<br \/>\n&#8211; Idealerweise kennen Sie Hetzerath und die Umgebung oder finden sich schnell in neue Tourengebiete ein<br \/>\n&#8211; Sie arbeiten zuverl\u00e4ssig, verantwortungsbewusst und gerne im Team<\/p>\n<p>So sieht Ihr Tag bei uns aus<\/p>\n<p>&#8211; Der Tag beginnt mit einem starken Kaffee und einer Tour, die Sie abends wieder nach Hause bringt<br \/>\n&#8211; Verantwortung zu \u00fcbernehmen ist f\u00fcr Sie selbstverst\u00e4ndlich \u2013 ob f\u00fcr Fahrzeug, Ladung oder Sicherheit auf der Stra\u00dfe<br \/>\n&#8211; Moderne Fahrzeuge wie Absetzer, Abroller oder Hecklader geh\u00f6ren zu Ihrem Alltag<br \/>\n&#8211; Wenn\u2019s mal stressig wird, behalten Sie die Nerven und finden pragmatische L\u00f6sungen<br \/>\n&#8211; Zusammenhalt wird bei uns gro\u00dfgeschrieben \u2013 hier z\u00e4hlt jeder, vom Fahrer bis zur Disposition<\/p>\n<p>Unser Angebot f\u00fcr Ihren Einsatz<\/p>\n<p>Steigen Sie bei uns ein und profitieren Sie von den St\u00e4rken, die REMONDIS als Unternehmensgruppe mit sich bringt. Unser Blick ist auf die Zukunft gerichtet. Deshalb f\u00f6rdern wir Ihre Kompetenzen und bieten Ihnen unter anderem sichere Perspektiven sowie ansprechende Benefits:<\/p>\n<p>&#8211; geregelte, planbare Arbeitszeiten: Als Fahrer wissen Sie, wann Feierabend ist \u2013 mit festen Touren und planbaren Eins\u00e4tzen im Nahverkehr.<br \/>\n&#8211; VL und Arbeitgeberzuschuss: Wir unterst\u00fctzen Sie beim Verm\u00f6gensaufbau \u2013 mit attraktiven Zusch\u00fcssen zu verm\u00f6genswirksamen Leistungen.<br \/>\n&#8211; Mitarbeiterrabatte bei \u00fcber 400 Partnern: Sparen Sie bei diversen Produkten \u2013 mit exklusiven Mitarbeiterrabatten.<br \/>\n&#8211; Arbeitskleidung und -reinigung: Top ausgestattet und immer gepflegt \u2013 mit kostenloser Arbeitskleidung und W\u00e4scheservice.<br \/>\n&#8211; Pers\u00f6nliche Schutzausr\u00fcstung: Sicher arbeiten \u2013 wir stellen Ihnen die passende Schutzausr\u00fcstung kostenlos zur Verf\u00fcgung.<br \/>\n&#8211; Sicherer Arbeitsplatz in einem gro\u00dfen Familienunternehmen: Arbeiten mit Perspektive &#8211; das bietet die Sicherheit eines stabilen Familienunternehmens mit jahrzehntelanger Erfahrung am Markt.<\/p>\n<p>Die Zukunft geh\u00f6rt Ihnen: Bewerben Sie sich jetzt auf remondis-karriere.de.<\/p>\n<p>REMONDIS GmbH \/\/ Region S\u00fcdwest \/\/ Martin Lexen \/\/ Hier erreichen Sie unser Recruiting Tean: 0621 8048736<\/p>\n","protected":false},"author":14347,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","job_listing_type":[67],"job_listing_category":[],"job_listing_location":[],"job_listing_tag":[],"class_list":["post-560090","job_listing","type-job_listing","status-publish","hentry","job_listing_type-full-time"],"aioseo_notices":[],"metas":{"_job_country_picker":"ChIJa76xwh5ymkcRW-WRjmtd6HU","_job_required_languages":"","_job_driving_license":"","_job_we_offer":"","_job_type":{"67":"Full time work"},"_job_salary_type":"","_job_salary":"","_job_experience":"","_job_video_url":"","_job_photos":"","_job_application_deadline_date":"","_job_employer_name":"REMONDIS GmbH &#038; Co. KG Region Nord","_job_employer_url":"https:\/\/driver-work.com\/de\/employer\/ext-remondis-gmbh-co-kg-region-nord\/"},"_links":{"self":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing\/560090","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing"}],"about":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/users\/14347"}],"replies":[{"embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/comments?post=560090"}],"version-history":[{"count":1,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing\/560090\/revisions"}],"predecessor-version":[{"id":560091,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing\/560090\/revisions\/560091"}],"wp:attachment":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/media?parent=560090"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_type?post=560090"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_category?post=560090"},{"taxonomy":"job_listing_location","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_location?post=560090"},{"taxonomy":"job_listing_tag","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_tag?post=560090"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}