{"id":559733,"date":"2026-07-10T00:11:05","date_gmt":"2026-07-10T00:11:05","guid":{"rendered":"https:\/\/driver-work.com\/job\/lkw-fahrer-m-w-d\/"},"modified":"2026-07-10T00:11:05","modified_gmt":"2026-07-10T00:11:05","slug":"job-558628","status":"publish","type":"job_listing","link":"https:\/\/driver-work.com\/de\/job\/job-558628\/","title":{"rendered":"LKW-Fahrer (m\/w\/d)"},"content":{"rendered":"<p>Zur Verst\u00e4rkung unseres Teams suchen wir:<\/p>\n<p>## **LKW-Fahrer (m\/w\/d)**<\/p>\n<p>**Dein Aufgabengebiet:**<\/p>\n<p>&#8211; LKW-Touren im Raum Bremen (Regionalverkehr\/Tagestouren) zweimal pro Woche und bei Bedarf<br \/>\n&#8211; An- bzw. Auslieferung von Kundenmaterial unter Einhaltung von Lieferpl\u00e4nen<br \/>\n&#8211; Ggf. Selbstst\u00e4ndige Beladung des LKW\u00b4s mit Kundenmaterial mittels eines Gabelstaplers<br \/>\n&#8211; Eigenst\u00e4ndige Ladungssicherung &amp; Fahrzeugpflege<br \/>\n&#8211; Innerbetrieblicher Transport von Kundenware<br \/>\n&#8211; Beachtung der Qualit\u00e4ts- und Sicherheitsvorschriften<\/p>\n<p>**Dein Anforderungsprofil:**<\/p>\n<p>&#8211; F\u00fchrerscheinklasse C\/CE mit Eintragung 95 bzw. Fahrerqualifizierungsnachweis<br \/>\n&#8211; Besitz einer g\u00fcltigen Fahrerkarte<br \/>\n&#8211; Besitz eines g\u00fcltigen Gabelstaplerf\u00fchrerscheins (w\u00fcnschenswert)<br \/>\n&#8211; Sichere und routinierte Fahrweise<br \/>\n&#8211; Sorgf\u00e4ltige, zuverl\u00e4ssige und selbstst\u00e4ndige Arbeitsweise<br \/>\n&#8211; Hohe Einsatzbereitschaft, Flexibilit\u00e4t und Teamf\u00e4higkeit<br \/>\n&#8211; Hohes Qualit\u00e4ts- und Verantwortungsbewusstsein<br \/>\n&#8211; Kundenfreundliches Auftreten<br \/>\n&#8211; Gute Deutschkenntnisse (Lesen und Schreiben)<\/p>\n<p>**Wir bieten:**<\/p>\n<p>&#8211; 35 Stunden\/Woche als Regelarbeitszeit (Vollzeit)<br \/>\n&#8211; Kollegiales Arbeitsumfeld<br \/>\n&#8211; Bis zu 30 Tage Urlaub im Jahr<br \/>\n&#8211; Urlaubs- und Weihnachtsgeld<br \/>\n&#8211; Interessantes und vielf\u00e4ltiges Aufgabengebiet<br \/>\n&#8211; \u201eJob mit Zukunft\u201c in einem Familienunternehmen mit 70-j\u00e4hriger Tradition<br \/>\n&#8211; Aufbau eines Arbeitszeitkontos zur Unterst\u00fctzung bei der Work-Life-Balance<\/p>\n<p>**Haben wir Dein Interesse geweckt?**<\/p>\n<p>Dann freuen wir uns auf Deine aussagekr\u00e4ftige Bewerbung inklusive fr\u00fchestm\u00f6glichen Einstiegstermins und Angaben zur Gehaltsvorstellung.<\/p>\n","protected":false},"author":20985,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","job_listing_type":[169],"job_listing_category":[],"job_listing_location":[],"job_listing_tag":[],"class_list":["post-559733","job_listing","type-job_listing","status-publish","hentry","job_listing_type-full-time-de"],"aioseo_notices":[],"metas":{"_job_country_picker":"ChIJa76xwh5ymkcRW-WRjmtd6HU","_job_required_languages":"","_job_driving_license":"","_job_we_offer":"","_job_type":{"169":"Vollzeitjob"},"_job_salary_type":"","_job_salary":"","_job_experience":"","_job_video_url":"","_job_photos":"","_job_application_deadline_date":"","_job_employer_name":"Diedrich Sandersfeld GmbH &#038; Co. KG","_job_employer_url":"https:\/\/driver-work.com\/de\/employer\/ext-diedrich-sandersfeld-gmbh-co-kg\/"},"_links":{"self":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing\/559733","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing"}],"about":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/users\/20985"}],"replies":[{"embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/comments?post=559733"}],"version-history":[{"count":1,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing\/559733\/revisions"}],"predecessor-version":[{"id":559734,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing\/559733\/revisions\/559734"}],"wp:attachment":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/media?parent=559733"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_type?post=559733"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_category?post=559733"},{"taxonomy":"job_listing_location","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_location?post=559733"},{"taxonomy":"job_listing_tag","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_tag?post=559733"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}