{"id":559624,"date":"2026-07-10T00:13:06","date_gmt":"2026-07-10T00:13:06","guid":{"rendered":"https:\/\/driver-work.com\/job\/chauffeur-pl-grue-auxiliaire-h-f\/"},"modified":"2026-07-10T00:13:06","modified_gmt":"2026-07-10T00:13:06","slug":"job-559624","status":"publish","type":"job_listing","link":"https:\/\/driver-work.com\/de\/job\/job-559624\/","title":{"rendered":"Chauffeur PL grue auxiliaire (H\/F)"},"content":{"rendered":"<div id=\"shema_offre3\">\n<div>\n<p>\n                            <span>Jubil int\u00e9rim recherche pour l&#8217;un de ses clients un <strong>Chauffeur<\/strong> PL avec grue auxiliaire (H\/F) sur le secteur de Mont de Marsan.<\/p>\n<p>Vos missions :<\/p>\n<p>&#8211; charger et d\u00e9charger son camion,<br \/>&#8211; respecter les consignes de s\u00e9curit\u00e9 et le code de la route<br \/>&#8211; port de charge et aide \u00e0 la manutention sur le parc<br \/>&#8211; Assurer la distribution chez les clients,<br \/>&#8211; \u00catre \u00e0 l&#8217;\u00e9coute des besoins clients.<br \/>&#8211; Assurer le retour de livraison et remonter les informations clients recueillies au Responsable ou \u00e0 l&#8217;Assistant(e).<\/p>\n<p>Prise de poste au plus vite<\/p>\n<p>Contrat : Interim<\/p>\n<p>Salaire : 12.31 \u00e0 14<\/p>\n<p>Nous recherchons pour cette mission le profil suivant :<\/p>\n<p>-vous devez imp\u00e9rativement \u00eatre d\u00e9tenteur du Permis C +FIMO + carte chrono \u00e0 jour + CACES R490.<br \/>&#8211; manutention et port de charge \u00e0 pr\u00e9voir <br \/>&#8211; respect des r\u00e8gles et consignes de s\u00e9curit\u00e9 <br \/>&#8211; rigoureux, autonome et ponctuel .<\/p>\n<p>Ce descriptif vous correspond, n&#8217;h\u00e9sitez plus \u00e0 postuler ou venir en agence rencontrer nos \u00e9quipes. <br \/><\/span>\n                        <\/p>\n<\/p><\/div>\n<\/p><\/div>\n","protected":false},"author":26769,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","job_listing_type":[],"job_listing_category":[],"job_listing_location":[],"job_listing_tag":[],"class_list":["post-559624","job_listing","type-job_listing","status-publish","hentry"],"aioseo_notices":[],"metas":{"_job_country_picker":"ChIJMVd4MymgVA0R99lHx5Y__Ws","_job_required_languages":"","_job_driving_license":"","_job_we_offer":"","_job_type":[],"_job_salary_type":"","_job_salary":"","_job_experience":"","_job_video_url":"","_job_photos":"","_job_application_deadline_date":"","_job_employer_name":"JUBIL INTERIM","_job_employer_url":"https:\/\/driver-work.com\/de\/employer\/ext-jubil-interim-2\/"},"_links":{"self":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing\/559624","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing"}],"about":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/users\/26769"}],"replies":[{"embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/comments?post=559624"}],"version-history":[{"count":1,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing\/559624\/revisions"}],"predecessor-version":[{"id":559625,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing\/559624\/revisions\/559625"}],"wp:attachment":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/media?parent=559624"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_type?post=559624"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_category?post=559624"},{"taxonomy":"job_listing_location","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_location?post=559624"},{"taxonomy":"job_listing_tag","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_tag?post=559624"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}