{"id":534937,"date":"2026-06-25T00:14:24","date_gmt":"2026-06-25T00:14:24","guid":{"rendered":"https:\/\/driver-work.com\/job\/electricien-eclairage-public-chauffeur-pl-h-f\/"},"modified":"2026-06-25T00:14:24","modified_gmt":"2026-06-25T00:14:24","slug":"job-534937","status":"publish","type":"job_listing","link":"https:\/\/driver-work.com\/de\/job\/job-534937\/","title":{"rendered":"\u00c9lectricien \u00c9clairage Public \/ Chauffeur PL (H\/F)"},"content":{"rendered":"<div id=\"shema_offre3\">\n<div>\n<p>\n                            <span>Votre agence Domino RH Toulon recrute pour l&#8217;un de ses clients un \u00c9lectricien \u00c9clairage Public \/ Chauffeur Poids Lourd (H\/F) dans le cadre d&#8217;une mission d&#8217;int\u00e9rim avec perspective de CDI.<\/p>\n<p>Vous intervenez principalement sur des travaux d&#8217;\u00e9lectricit\u00e9 li\u00e9s \u00e0 l&#8217;\u00e9clairage public (80%), avec une part ponctuelle de conduite Poids Lourd en remplacement (20%). <br \/>Vous souhaitez int\u00e9grer une entreprise qui mise sur la transmission des savoir-faire et la mont\u00e9e en comp\u00e9tences ? Cette mission est faite pour vous.<\/p>\n<p>Vos principales missions :<\/p>\n<p>&#8211; R\u00e9aliser des travaux d&#8217;installation, de maintenance et de d\u00e9pannage sur les \u00e9quipements d&#8217;\u00e9clairage public.<br \/>&#8211; Effectuer les raccordements \u00e9lectriques et assurer la mise en s\u00e9curit\u00e9 des installations.<br \/>&#8211; Participer aux interventions sur chantier en lien avec les \u00e9quipes terrain.<br \/>&#8211; Participer \u00e0 la pose, au remplacement et \u00e0 la s\u00e9curisation des m\u00e2ts\/poteaux d&#8217;\u00e9clairage public.<br \/>&#8211; Assurer ponctuellement la conduite d&#8217;un Poids Lourd avec grue auxiliaire pour le transport et la manutention des m\u00e2ts.<\/p>\n<p>Contrat : Interim<\/p>\n<p>Salaire : 13 \u00e0 14<\/p>\n<p>Une premi\u00e8re exp\u00e9rience en \u00e9lectricit\u00e9 est appr\u00e9ci\u00e9e.<br \/>Une exp\u00e9rience en travaux publics (TP) est accept\u00e9e.<br \/>Le CACES Grue Auxiliaire est un plus.<br \/>Vous appr\u00e9ciez le travail de terrain et savez intervenir en respectant les consignes de s\u00e9curit\u00e9.<\/p>\n<p>Nous recherchons avant tout une personne fiable, impliqu\u00e9e et pr\u00eate \u00e0 monter en comp\u00e9tences au sein d&#8217;une \u00e9quipe terrain..<br \/><\/span>\n                        <\/p>\n<\/p><\/div>\n<\/p><\/div>\n","protected":false},"author":25753,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","job_listing_type":[],"job_listing_category":[],"job_listing_location":[],"job_listing_tag":[],"class_list":["post-534937","job_listing","type-job_listing","status-publish","hentry"],"aioseo_notices":[],"metas":{"_job_country_picker":"ChIJMVd4MymgVA0R99lHx5Y__Ws","_job_required_languages":"","_job_driving_license":"","_job_we_offer":"","_job_type":[],"_job_salary_type":"","_job_salary":"","_job_experience":"","_job_video_url":"","_job_photos":"","_job_application_deadline_date":"","_job_employer_name":"DOMINO RH","_job_employer_url":"https:\/\/driver-work.com\/de\/employer\/ext-domino-rh\/"},"_links":{"self":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing\/534937","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing"}],"about":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/users\/25753"}],"replies":[{"embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/comments?post=534937"}],"version-history":[{"count":1,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing\/534937\/revisions"}],"predecessor-version":[{"id":534938,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing\/534937\/revisions\/534938"}],"wp:attachment":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/media?parent=534937"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_type?post=534937"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_category?post=534937"},{"taxonomy":"job_listing_location","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_location?post=534937"},{"taxonomy":"job_listing_tag","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_tag?post=534937"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}