{"id":526254,"date":"2026-06-16T00:05:12","date_gmt":"2026-06-16T00:05:12","guid":{"rendered":"https:\/\/driver-work.com\/job\/chauffeur-spl-h-f\/"},"modified":"2026-06-16T00:05:12","modified_gmt":"2026-06-16T00:05:12","slug":"job-526254","status":"publish","type":"job_listing","link":"https:\/\/driver-work.com\/de\/job\/job-526254\/","title":{"rendered":"Chauffeur SPL* H\/F"},"content":{"rendered":"<p><\/p>\n<p><strong>Aquila RH Cherbourg<\/strong> est un r\u00e9seau d&#8217;agence d&#8217;int\u00e9rim, et recrute en CDD et CDI des profils CAP \u00e0 BAC sp\u00e9cialis\u00e9s en transport, logistique, industrie et BTP. Nous recherchons pour l&#8217;un de nos clients, un <strong>CHAUFFEUR SPL (H\/F)<\/strong>.<\/p>\n<p>Nos avantages :<\/p>\n<ul>\n<li>Acomptes 2 fois par semaine les mardis et jeudis<\/li>\n<li>10% d&#8217;indemnit\u00e9 de fin de mission<\/li>\n<li>10% d&#8217;indemnit\u00e9 cong\u00e9s pay\u00e9s<\/li>\n<li>Avances de tr\u00e9sorerie jusqu&#8217;\u00e0 100% de vos Indemnit\u00e9s de Fin de Mission et Ind\u00e9mnit\u00e9s Cong\u00e9s Pay\u00e9s<\/li>\n<li>Votre \u00e9pargne r\u00e9mun\u00e9r\u00e9e \u00e0 5% par an en 2026<\/li>\n<li>Une prime de fid\u00e9lit\u00e9 pouvant aller jusqu&#8217;\u00e0 200\u20ac en janvier 2027<\/li>\n<li>Acc\u00e8s \u00e0 notre partenaire Couleur CE d\u00e8s la 1\u00e8re heure de mission (billetterie, parcs et loisirs, art et culture\u2026)<\/li>\n<li>Mutuelle d&#8217;entreprise et acc\u00e8s au FASTT pour des avantages et services suppl\u00e9mentaires.<\/li>\n<\/ul>\n<p><\/p>\n<p>Vos missions<\/p>\n<p>Sur ce poste vous \u00eates charg\u00e9 de plusieurs missions telles que :<\/p>\n<ul>\n<li>S&#8217;assurer du bon fonctionnement du v\u00e9hicule ;<\/li>\n<li>Acheminer les marchandises chez les diff\u00e9rents clients ;<\/li>\n<li>Conduire un camion SPL ;<\/li>\n<li>Respecter les r\u00e8gles de s\u00e9curit\u00e9 du code de la route.<\/li>\n<\/ul>\n<p><\/p>\n","protected":false},"author":25731,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","job_listing_type":[171],"job_listing_category":[],"job_listing_location":[],"job_listing_tag":[],"class_list":["post-526254","job_listing","type-job_listing","status-publish","hentry","job_listing_type-full-time-uk"],"aioseo_notices":[],"metas":{"_job_country_picker":"ChIJMVd4MymgVA0R99lHx5Y__Ws","_job_required_languages":"","_job_driving_license":["CE"],"_job_we_offer":"","_job_type":{"171":"\u041f\u043e\u0432\u043d\u0430 \u0437\u0430\u0439\u043d\u044f\u0442\u0456\u0441\u0442\u044c"},"_job_salary_type":"","_job_salary":"","_job_experience":"","_job_video_url":"","_job_photos":"","_job_application_deadline_date":"","_job_employer_name":"Aquila RH","_job_employer_url":"https:\/\/driver-work.com\/de\/employer\/ext-aquila-rh\/"},"_links":{"self":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing\/526254","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing"}],"about":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/users\/25731"}],"replies":[{"embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/comments?post=526254"}],"version-history":[{"count":1,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing\/526254\/revisions"}],"predecessor-version":[{"id":526255,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing\/526254\/revisions\/526255"}],"wp:attachment":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/media?parent=526254"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_type?post=526254"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_category?post=526254"},{"taxonomy":"job_listing_location","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_location?post=526254"},{"taxonomy":"job_listing_tag","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_tag?post=526254"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}