{"id":397930,"date":"2026-04-11T01:03:00","date_gmt":"2026-04-11T01:03:00","guid":{"rendered":"https:\/\/driver-work.com\/job\/pl-fahrer-m-w-d\/"},"modified":"2026-04-11T01:03:00","modified_gmt":"2026-04-11T01:03:00","slug":"job-396794","status":"publish","type":"job_listing","link":"https:\/\/driver-work.com\/de\/job\/job-396794\/","title":{"rendered":"PL Fahrer (m\/w\/d)"},"content":{"rendered":"<div id=\"shema_offre3\">\n<div>\n<p>\n                            <span><\/p>\n<h2>Das Unternehmen<\/h2>\n<p>Armor Fruits wurde 1971 in Vannes in der Bretagne gegr\u00fcndet und trat 1999 dem Le Saint Network bei. Das Unternehmen besch\u00e4ftigt derzeit \u00fcber 70 Mitarbeiter und m\u00f6chte sich weiterentwickeln. Armor Fruits vertreibt Obst und Gem\u00fcse im gesamten Departement mit einer absoluten Anforderung: dank kurzer Wege lokal zu agieren!<\/p>\n<p>Armor Fruits ist ISO-zertifiziert und garantiert den Verkauf und die Lieferung von frischen Produkten von ausgezeichneter Qualit\u00e4t an Gastronomiebetriebe sowie an gro\u00dfe und mittelst\u00e4ndische Einzelhandelsgesch\u00e4fte.<\/p>\n<p>Das Unternehmen verf\u00fcgt auch \u00fcber eine Reihe von Produkten aus biologischem Anbau.<\/p>\n<\/p>\n<h2>Stellenbeschreibung<\/h2>\n<p><\/p>\n<p>M\u00f6chten Sie Teil eines menschlichen, freundlichen und engagierten <strong>Abenteuers<\/strong> sein?<\/p>\n<p>Im Rahmen seiner Entwicklung sucht unsere Transportabteilung <strong>PL-Auslieferungsfahrer<\/strong>, um die Lieferung unserer Produkte an unsere professionellen Kunden (RHD und GMS\/PMS) sicherzustellen.<\/p>\n<\/p>\n<p><strong>Ihre Hauptaufgaben:<\/strong><\/p>\n<ul>\n<li>\n<p><strong>Beladen des Fahrzeugs<\/strong> unter Beachtung des Tourenplans und der Transportanweisungen<\/p>\n<\/li>\n<li>\n<p><strong>Sicherstellung der Lieferungen<\/strong> an die Kunden gem\u00e4\u00df dem Fahrplan, unter <strong>Einhaltung der Lieferfristen und -zeiten<\/strong><\/p>\n<\/li>\n<li>\n<p>Sicherstellung der Aufrechterhaltung der Qualit\u00e4t der transportierten Produkte (Einhaltung der Qualit\u00e4tskette, Handhabung, Transportbedingungen)<\/p>\n<\/li>\n<li>\n<p><strong>Pr\u00fcfung der Konformit\u00e4t der Waren<\/strong> bei der Lieferung (Menge, Zustand, Referenzen)<\/p>\n<\/li>\n<li>\n<p>Gegebenenfalls Durchf\u00fchrung bestimmter <strong>Abholungen<\/strong> bei Kunden<\/p>\n<\/li>\n<li>\n<p><strong>Anwendung der Sicherheitsregeln<\/strong> sowie der Verfahren und Anforderungen des Qualit\u00e4tssystems<\/p>\n<\/li>\n<li>\n<p><strong>Sicherstellung der Sauberkeit<\/strong> und ordnungsgem\u00e4\u00dfen <strong>Wartung<\/strong> des zur Verf\u00fcgung gestellten Fahrzeugs<\/p>\n<\/li>\n<li>\n<p><strong>Vertretung des Unternehmens<\/strong> gegen\u00fcber Kunden mit Professionalit\u00e4t und Serviceorientierung<\/p>\n<\/li>\n<\/ul>\n<h4><strong>Was wir Ihnen bieten<\/strong><\/h4>\n<p> <strong>Verg\u00fctung<\/strong> entsprechend Ihrem <strong>K\u00f6nnen<\/strong> und Ihrer <strong>Erfahrung + Boni<\/strong><br \/> <strong>Attraktive Sozialleistungen<\/strong><\/p>\n<ul>\n<li>Betriebliche Krankenzusatzversicherung<\/li>\n<li>Zugang zum Kauf von Netzwerkprodukten zu Vorzugspreisen<\/li>\n<li>Ein dynamisches und freundliches Arbeitsumfeld<\/li>\n<\/ul>\n<p> <strong>Die Stelle ist ab sofort zu besetzen<\/strong><\/p>\n<p><strong> Standort: Vannes (56)<\/strong><\/p>\n<p><strong><strong> Zwei m\u00f6gliche Touren: <\/strong><\/strong>von 4:00 bis 12:00 Uhr oder von 2:00 bis 10:00 Uhr<\/p>\n<p><\/p>\n<p> <strong>CE- oder C-F\u00fchrerschein mit g\u00fcltiger G\u00fcltigkeit<\/strong> + FIMO\/FCO auf dem neuesten Stand<\/p>\n<p> Erfahrung in der Zustellung ist ein Plus<br \/>\u23f3 P\u00fcnktlichkeit, Seriosit\u00e4t und Kundenserviceorientierung sind unerl\u00e4sslich<\/p>\n<p>Vertrag: Befristeter Vertrag, Vollzeit<\/span>\n                        <\/p>\n<\/p><\/div>\n<\/p><\/div>\n","protected":false},"author":25757,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","job_listing_type":[],"job_listing_category":[],"job_listing_location":[],"job_listing_tag":[],"class_list":["post-397930","job_listing","type-job_listing","status-publish","hentry"],"aioseo_notices":[],"metas":{"_job_country_picker":"ChIJMVd4MymgVA0R99lHx5Y__Ws","_job_required_languages":"","_job_driving_license":"","_job_we_offer":"","_job_type":[],"_job_salary_type":"","_job_salary":"","_job_experience":"","_job_video_url":"","_job_photos":"","_job_application_deadline_date":"","_job_employer_name":"R\u00e9seau Le Saint","_job_employer_url":"https:\/\/driver-work.com\/de\/employer\/ext-reseau-le-saint\/"},"_links":{"self":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing\/397930","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing"}],"about":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/users\/25757"}],"replies":[{"embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/comments?post=397930"}],"version-history":[{"count":0,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing\/397930\/revisions"}],"wp:attachment":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/media?parent=397930"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_type?post=397930"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_category?post=397930"},{"taxonomy":"job_listing_location","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_location?post=397930"},{"taxonomy":"job_listing_tag","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_tag?post=397930"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}